{"id":236249,"date":"2023-09-13T09:36:00","date_gmt":"2023-09-13T14:36:00","guid":{"rendered":"https:\/\/insightcrime.org\/?page_id=236249"},"modified":"2023-11-27T17:13:30","modified_gmt":"2023-11-27T22:13:30","slug":"un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia","status":"publish","type":"page","link":"https:\/\/insightcrime.org\/es\/investigaciones\/un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia\/","title":{"rendered":"Un antiguo sicario de Escobar sigue el camino de la &#8216;Paz Total&#8217; en Medell\u00edn, Colombia"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull cover-byline\" style=\"padding-top:var(--wp--preset--spacing--80);padding-right:var(--wp--preset--spacing--80);padding-bottom:var(--wp--preset--spacing--80);padding-left:var(--wp--preset--spacing--80);min-height:350px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-70 has-background-dim\"><\/span><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"768\" class=\"wp-block-cover__image-background wp-image-231169\" alt=\"\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=1600%2C768&#038;quality=100&#038;ssl=1\" style=\"object-position:50% 20%\" data-object-fit=\"cover\" data-object-position=\"50% 20%\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?w=1600&amp;quality=100&amp;ssl=1 1600w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=300%2C144&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=1024%2C492&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=768%2C369&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=1536%2C737&amp;quality=100&amp;ssl=1 1536w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=1200%2C576&amp;quality=100&amp;ssl=1 1200w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=1568%2C753&amp;quality=100&amp;ssl=1 1568w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=400%2C192&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?resize=706%2C339&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing-2.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-0cefa6ed wp-block-cover-is-layout-constrained\">\t<div\n\t\tclass=\"wp-block-newspack-blocks-homepage-articles wpnbha ts-7 \"\n\t\tstyle=\"\"\n\t\t>\n\t\t<div data-posts data-current-post-id=\"236249\">\n\t\t\t\t\t\t\n\t<article data-post-id=\"236249\"\n\t\tclass=\"tag-colombia-pais tag-homicidios tag-paz-colombia tag-politicas-de-seguridad category-investigaciones type-page post-has-image\"\n\t\t\t\t>\n\t\t\t\t\n\t\t<div class=\"entry-wrapper\">\n\t\t\t\t\t\t<h2 class=\"entry-title\"><a href=\"https:\/\/insightcrime.org\/es\/investigaciones\/un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia\/\" rel=\"bookmark\">Un antiguo sicario de Escobar sigue el camino de la &#8216;Paz Total&#8217; en Medell\u00edn, Colombia<\/a><\/h2>\t\t\t\t\t\t\t\t\t\t<div class=\"entry-meta\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"byline\">\n\t\t\t\t\t\t\t<span class=\"author-prefix\">por<\/span> <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/insightcrime.org\/es\/author\/sgarcia\/\">Sara Garcia<\/a><\/span> y <span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/insightcrime.org\/es\/author\/ddenheld\/\">Douwe den Held<\/a><\/span>\t\t\t\t\t\t<\/span><!-- .author-name -->\n\t\t\t\t\t\t<time class=\"entry-date published\" datetime=\"2023-09-13T09:36:00-05:00\">13 de septiembre de 2023<\/time><time class=\"updated\" datetime=\"2023-11-27T17:13:30-05:00\">27 de noviembre de 2023<\/time>\t\t\t\t<\/div><!-- .entry-meta -->\n\t\t\t\t\t\t\t\t<\/div><!-- .entry-wrapper -->\n\t<\/article>\n\n\t\t\t\t<\/div>\n\t\t\n\t<\/div>\n\t<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading accent-header\" id=\"h-\"><\/h2>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-63375db1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Un-antiguo-sicario-de-Escobar-sigue-el-camino-de-la-Paz-Total-en-Medellin-Colombia-InSight-Crime-Sep-2023.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descargue el informe completo (PDF)<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Henry Holgu\u00edn se asom\u00f3 por el balc\u00f3n del segundo piso vac\u00edo de un peque\u00f1o restaurante en La Bayadera, un concurrido barrio industrial de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsto fue una zona roja, brava\u2026 aqu\u00ed no se pod\u00eda vender un marihuano sin mi autorizaci\u00f3n\u201d, record\u00f3 Holgu\u00edn satisfecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A primera vista, este hombre de 54 a\u00f1os parece una persona com\u00fan. Una cicatriz entre las cejas, recuerdo de un enfrentamiento con un polic\u00eda en sus a\u00f1os como actor del conflicto urbano en Medell\u00edn, delata los altibajos que lo han llevado a donde est\u00e1 ahora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mediados de los 80, una \u00e9poca en que el hampa de la ciudad crec\u00eda r\u00e1pidamente en escala y complejidad, Holgu\u00edn lideraba una banda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, cuarenta a\u00f1os despu\u00e9s de comprar su primera arma y fundar un grupo armado para defenderse de los criminales del barrio, Holgu\u00edn coordina el movimiento Sinergia, voceros civiles de una de las bandas criminales del \u00e1rea metropolitana de Medell\u00edn que participan en el proyecto de \u00abPaz Total\u201d, la pol\u00edtica insignia del presidente Gustavo Petro.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"416\" height=\"576\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-6-2.png?resize=416%2C576&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-235011\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-6-2.png?w=416&amp;quality=100&amp;ssl=1 416w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-6-2.png?resize=217%2C300&amp;quality=100&amp;ssl=1 217w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-6-2.png?resize=400%2C554&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-6-2.png?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 416px) 100vw, 416px\" \/><figcaption class=\"wp-element-caption\"><em>Henry Holgu\u00edn. Cr\u00e9dito: InSight Crime.<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La Paz Total es el proceso de paz m\u00e1s ambicioso jam\u00e1s intentado en Colombia. Mediante este, el gobierno busca negociaciones simult\u00e1neas con m\u00e1s de 20 grupos armados que representan las diferentes caras del mundo criminal colombiano: insurgencias guerrilleras, ej\u00e9rcitos narcotraficantes y pandillas urbanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al hacerlo, la administraci\u00f3n de Petro busca no solo desmovilizar grupos espec\u00edficos, sino tambi\u00e9n romper el ciclo de generaciones del conflicto en Colombia, donde cada vez que el Estado ha eliminado a un actor, ya sea por persecuci\u00f3n o negociaci\u00f3n, surge una nueva generaci\u00f3n de grupos criminales para tomar su lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Medell\u00edn y otros municipios que hacen parte de la subregi\u00f3n antioque\u00f1a del Valle de Aburr\u00e1 han sido un crisol de esta violencia interminable. La ciudad ha sido escenario de acontecimientos que definieron toda una \u00e9poca, desde la ca\u00edda del primer capo de la coca\u00edna, Pablo Escobar, hasta la primera desmovilizaci\u00f3n paramilitar. Pero cada vez, lejos de socavar el crimen organizado, estos escenarios han impulsado evoluciones criminales que han reforzado su control sobre la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, el hampa de la ciudad es compleja y tiene m\u00faltiples capas. A pesar de estar fragmentada y sin l\u00edderes, mantiene un profundo arraigo y enorme poder sobre la poblaci\u00f3n y sus instituciones. Este podr\u00eda ser el reto m\u00e1s grande al que se enfrenten los negociadores de la Paz Total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos dudan de sus posibilidades de \u00e9xito. Pero Holgu\u00edn, quien ha sido no solo testigo, sino tambi\u00e9n part\u00edcipe de esta historia delictiva, dice ser la prueba viviente de que el cambio es posible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quien-llena-los-vacios-de-un-estado-ausente\">\u00bfQui\u00e9n llena los vac\u00edos de un Estado ausente?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" height=\"492\" width=\"1024\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Cap-1.jpg?resize=1024%2C492&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224569\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn creci\u00f3 en el barrio Popular 2, en la ladera Nororiental de Medell\u00edn. Este barrio fue en sus inicios un asentamiento informal construido por sus propios habitantes, principalmente migrantes que hu\u00edan de zonas rurales donde se libraba una guerra entre el Estado y las guerrillas marxistas nacidas en la d\u00e9cada de los 60.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los a\u00f1os 80, algunas de estas guerrillas comenzaron su accionar armado y pol\u00edtico en Medell\u00edn y otras \u00e1reas urbanas. Esto marc\u00f3 el momento en que la guerra lleg\u00f3 a las ciudades colombianas y sent\u00f3 las bases de un conflicto urbano que prevalece hoy. Seg\u00fan Holgu\u00edn, fue en ese entonces cuando \u00e9l, con un poco m\u00e1s de 10 a\u00f1os, conoci\u00f3 las armas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ocurri\u00f3 un d\u00eda, a comienzos de los 80, cuando un grupo de hombres y mujeres armados, con la cara cubierta, entraron a su sal\u00f3n de clase. Se identificaron como miembros del Ej\u00e9rcito Popular de Liberaci\u00f3n (<a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/epl\/\" target=\"_blank\" rel=\"noreferrer noopener\">EPL<\/a>), un grupo guerrillero surgido en 1967 como brazo armado del Partido Comunista Colombiano Marxista Leninista (PCC-ML).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el colegio, los guerrilleros invitaron a ni\u00f1os y ni\u00f1as a una reuni\u00f3n informativa en una casa del barrio. Holgu\u00edn asisti\u00f3. En el encuentro sostuvo un arma y escuch\u00f3 con atenci\u00f3n el discurso guerrillero.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"884\" height=\"614\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-1-2.png?resize=884%2C614&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-235014\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-1-2.png?w=884&amp;quality=100&amp;ssl=1 884w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-1-2.png?resize=300%2C208&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-1-2.png?resize=768%2C533&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-1-2.png?resize=400%2C278&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-1-2.png?resize=706%2C490&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-1-2.png?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 884px) 100vw, 884px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHablaban de escuelas, de que quer\u00edan un desarrollo para el barrio\u201d, record\u00f3, \u201csent\u00eda que con ellos podr\u00edamos lograr que hubiera menos hambre y menos sufrimiento en la comunidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A esa corta edad, Holgu\u00edn aspir\u00f3 a ser guerrillero. Pero al mismo tiempo, se sent\u00eda atra\u00eddo por otro actor armado que operaba en su barrio. Una banda de ladrones, que robaban joyer\u00edas en el centro de la ciudad y repart\u00edan el bot\u00edn entre las familias de la comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEmpez\u00f3 ese debate interno, porque por un lado ve\u00eda las armas de la guerrilla, con un ideal y habl\u00e1ndonos en favor de nuestro pueblo. Por otro lado, ve\u00eda las armas en manos de otros que hab\u00edan robado oro y que estaban llevando esa riqueza al barrio\u201d dijo Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siendo un ni\u00f1o, Holgu\u00edn entendi\u00f3 algo que 40 a\u00f1os despu\u00e9s sigue siendo uno de los principales obst\u00e1culos para alcanzar la paz en Medell\u00edn: el sentimiento com\u00fan entre los habitantes de los barrios marginados de que el Estado no est\u00e1 ah\u00ed para ellos y, quienes llenan el vac\u00edo son quienes empu\u00f1an las armas desde la ilegalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn dijo que se sum\u00f3 a las juventudes revolucionarias cercanas al EPL, pero fue expulsado poco despu\u00e9s por planear el robo a una joyer\u00eda, acusado de ser un \u201cvulgar delincuente\u201d, palabras que hasta hoy martillan en su memoria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Los grupos cambian pero las armas quedan<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El EPL no dur\u00f3 mucho en el barrio. El 23 de agosto de 1984 la guerrilla firm\u00f3 un acuerdo de cese al fuego con el gobierno, que se <a href=\"https:\/\/www.comisiondelaverdad.co\/intento-de-paz-con-el-epl\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">rompi\u00f3<\/a> tan solo un mes despu\u00e9s. Por 10 d\u00edas, el barrio fue el escenario de enfrentamientos entre el EPL y las fuerzas estatales, record\u00f3 Holgu\u00edn. Despu\u00e9s de esto, la guerrilla abandon\u00f3 el barrio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe van del barrio los guerrilleros, los que ten\u00edan ideolog\u00eda pol\u00edtica, los que eran capaces de ejercer disciplina y \u00bfqu\u00e9 nos qued\u00f3? las armas; \u00bfen manos de qui\u00e9n? de los reci\u00e9n reclutados por las guerrillas\u201d, reflexion\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed fue como en el barrio emergi\u00f3 un grupo delincuencial llamado \u201cLos Chorrillos\u201d. Algunos de sus miembros hab\u00edan hecho parte de las guerrillas y tras su salida se quedaron con las armas. Seg\u00fan Holgu\u00edn, estos comenzaron a sembrar temor entre la poblaci\u00f3n, pues comet\u00edan robos, amenazas, asesinatos y abusos sexuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un d\u00eda de ese a\u00f1o Holgu\u00edn fue a visitar a su novia. Estaban sentados fuera de la casa, cuando lleg\u00f3 el l\u00edder de los Chorrillos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo est\u00e1s de buena, un d\u00eda de estos te robo\u201d, record\u00f3 Holgu\u00edn que le dijo el hombre a su novia. El muchacho se sinti\u00f3 temeroso de que el l\u00edder de Los Chorrillos agrediera a su pareja y decidi\u00f3 unirse con dos hombres del barrio, un expresidiario y un polic\u00eda, para declararles la guerra a los Chorrillos. Como eran solo tres y no ten\u00edan armas, Holgu\u00edn empe\u00f1\u00f3 su moto y compr\u00f3 dos rev\u00f3lveres.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"510\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-2-2.png?resize=720%2C510&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-235016\" style=\"width:834px;height:591px\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-2-2.png?w=720&amp;quality=100&amp;ssl=1 720w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-2-2.png?resize=300%2C213&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-2-2.png?resize=400%2C283&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-2-2.png?resize=706%2C500&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-2-2.png?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\"><em>Holgu\u00edn en su adolescencia. Cr\u00e9dito: cortes\u00eda de Henry Holgu\u00edn.<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de sus compa\u00f1eros fue el encargado de asesinar al l\u00edder de Los Chorrillos. Tras \u00e9l, siguieron otros miembros de la banda. Con cada muerte, Holgu\u00edn y su peque\u00f1o grupo ganaban poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComienzan las personas a ayudarnos para que pudi\u00e9ramos crecer militarmente. La comunidad nos [amaba] porque [\u00e9ramos] de la comunidad, porque nos convertimos en la autoridad, porque ya la comunidad [estaba] tranquila\u00bb seg\u00fan dijo Holgu\u00edn, \u201cCrey\u00e9ndonos que \u00e9ramos los buenos en la pel\u00edcula, entramos a hacer un proceso de guerra en aquella \u00e9poca.\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Detonando y cobrando<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al acabar con Los Chorrillos, Holgu\u00edn y su peque\u00f1o grupo se consolidaron como el poder armado dominante del barrio. Lo que comenz\u00f3 como un acto de defensa ante Los Chorrillos, los convirti\u00f3 en los principales victimarios del territorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Din\u00e1micas similares suced\u00edan en otros barrios pobres de Medell\u00edn, donde numerosas bandas se afianzaban en los territorios. Estos grupos comenzaron a prestar servicios a un poder criminal mayor: el narcotr\u00e1fico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ese entonces, <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/pablo-escobar\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pablo Escobar<\/a> lideraba el Cartel de Medell\u00edn y el boom de la coca\u00edna, un fen\u00f3meno que cambiar\u00eda para siempre el rostro de la guerra en Colombia. El narcotr\u00e1fico se convirti\u00f3 en el punto de convergencia de los conflictos pol\u00edticos y sociales del pa\u00eds con el crimen organizado.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#b40026\" class=\"has-inline-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/pablo-escobar\/\" target=\"_blank\" rel=\"noreferrer noopener\">Perfil de Pablo Escobar<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En Medell\u00edn, las bandas y pandillas peque\u00f1as de los barrios, conocidas como combos, comenzaron a servir de brazo armado para el cartel y emergi\u00f3 la figura del sicario, j\u00f3venes movilizados en moto que mataban por dinero.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Asdi-Paz-Total-Composicion-de-la-criminalidad-en-Medellin-1977-1993-InSight-Crime_Sep-2023-4-2.jpg?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224679\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn dijo que cometi\u00f3 su primer asesinato a sueldo cuando estaba cerca de cumplir 17 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn esa \u00e9poca me gan\u00e9 400.000 pesos\u201d \u2014equivalentes a US$4.400 hoy \u2014\u201cEso era una fortuna\u201d, destac\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-4.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224536\" style=\"width:840px;height:559px\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Hacia finales de la d\u00e9cada de los 80, Holgu\u00edn fue invitado a hacer parte del ala militar del Cartel de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEra el estatus m\u00e1s grande que se le pod\u00eda dar a los bandidos de aqu\u00ed\u201d, record\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La invitaci\u00f3n lleg\u00f3 por dos hermanos conocidos como \u201cLos Picapiedra\u201d, lugartenientes de Lim\u00f3n, hombre de confianza de Escobar. Ten\u00edan v\u00ednculos con la polic\u00eda y los servicios de inteligencia, seg\u00fan coment\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn acept\u00f3 la invitaci\u00f3n, pues esto les facilitar\u00eda el acceso suyo y de su banda a armas y dinero, con lo cual podr\u00edan ganar m\u00e1s control territorial.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#b40026\" class=\"has-inline-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/oficina-de-envigado-perfil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Perf\u00edl de la Oficina de Envigado<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Al tiempo que Holgu\u00edn trabajaba para el Cartel de Medell\u00edn, al Popular 2 llegaron las milicias, una nueva generaci\u00f3n de grupos armados que surgi\u00f3 a finales de los 80, tiempo despu\u00e9s de la retirada de las guerrillas de algunos barrios de Medell\u00edn. Motivadas por un discurso de izquierda, buscaban contrarrestar el ascenso de las bandas en la ciudad y <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/09\/medellin-memorias-de-una-guerra-urbana-paz-total-insight-crime.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">defend\u00edan<\/a> la supuesta restauraci\u00f3n del orden y la seguridad a partir de la persecuci\u00f3n de actores que consideraban indeseables, como ladrones y consumidores de drogas. Algunas milicias ten\u00edan cercan\u00eda con las guerrillas, mientras que otras se mantuvieron independientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las milicias del barrio invitaron a Holgu\u00edn a unir fuerzas, pero \u00e9l se neg\u00f3, pues no estaba de acuerdo con las motivaciones de los asesinatos cometidos por las milicias.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPor fumarse un cigarrillo de marihuana mataban [a los j\u00f3venes]\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto tens\u00f3 la relaci\u00f3n entre Holgu\u00edn y las milicias de su barrio. As\u00ed, el 31 de diciembre de 1989, descubri\u00f3 que un l\u00edder miliciano hab\u00eda destruido la casa de sus padres para vender los materiales y costear las fiestas de fin de a\u00f1o de su grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La disputa por la casa fue confirmada a InSight Crime por un residente del barrio, aunque de acuerdo con la fuente, el miliciano tuvo permiso de tomar elementos de la casa, pues se hab\u00eda visto afectada por un da\u00f1o geol\u00f3gico, pero hubo conflicto sobre algunos materiales de valor que Holgu\u00edn no le hab\u00eda permitido quedarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Furibundo, Holgu\u00edn se enfrent\u00f3 al l\u00edder miliciano y lo mat\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las relaciones con el Cartel de Medell\u00edn tambi\u00e9n se deterioraron. A comienzos de los a\u00f1os 90, Holgu\u00edn dijo, descubri\u00f3 que Los Picapiedra le robaban dinero de los asesinatos a sueldo que comet\u00edan juntos, y decidi\u00f3 enfrentarlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan relata, les dijo: \u201cPrefiero robar relojes con mis amigos que millonadas aqu\u00ed con manada de torcidos\u00bb. Y a\u00f1adi\u00f3: \u201cEso le cay\u00f3 a todos y no les gust\u00f3. Me declararon objetivo militar\u201d. Entonces, debi\u00f3 abandonar la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su historia, se mud\u00f3 a Pereira, una ciudad al sur de Medell\u00edn, pero no tard\u00f3 en ser capturado por hacer parte del Cartel y el homicidio del l\u00edder miliciano. Para verificar esto, InSight Crime se puso en contacto con los tribunales, pero no obtuvo acceso al expediente judicial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La recomposici\u00f3n de poderes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn, quien para entonces ten\u00eda 22 a\u00f1os, fue condenado a 17 a\u00f1os de c\u00e1rcel, seg\u00fan coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo era un ni\u00f1o y cre\u00ed que se me acababa el mundo\u201d, record\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras estaba preso, el bajo mundo en Medell\u00edn estaba por cambiar para siempre. En diciembre de 1993, Pablo Escobar fue dado de baja por el Bloque de B\u00fasqueda del gobierno colombiano, una unidad \u00e9lite de polic\u00eda, con el <a href=\"https:\/\/es.insightcrime.org\/images\/PDFs\/Elites_Crimen_Organizado_Colombia\" target=\"_blank\" rel=\"noreferrer noopener\">presunto<\/a> apoyo de miembros de los PEPES (Perseguidos por Pablo Escobar), un grupo de antiguos socios del capo que se aliaron para dar con su paradero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero para Holgu\u00edn, el cambio m\u00e1s grande lleg\u00f3 unos meses despu\u00e9s, cuando las Milicias Populares del Pueblo y para el Pueblo (MPPP), las Milicias Independientes del Valle de Aburr\u00e1 y las Milicias Independientes de Medell\u00edn se desmovilizaron en mayo de 1994, luego de varios meses de negociaciones con representantes del gobierno nacional, departamental y local. Este fue el primer proceso de negociaciones entre grupos armados y la institucionalidad para dar soluci\u00f3n al conflicto urbano en Medell\u00edn, pero algunos de sus fracasos contin\u00faan acechando las negociaciones de paz actuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las milicias acordaron con el gobierno que 843 milicianos recibir\u00edan beneficios a cambio de desarmarse y confesar ciertos delitos. En el proceso, se defini\u00f3 que los milicianos desmovilizados podr\u00edan ejercer labores de seguridad privada a trav\u00e9s de una entidad llamada Cooperativa de Seguridad y Servicios Comunitarios (Coosercom), la cual recibi\u00f3 un contrato de dos a\u00f1os con el gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero esto llev\u00f3 a otros problemas. La poblaci\u00f3n civil comenz\u00f3 a <a href=\"https:\/\/www.eltiempo.com\/archivo\/documento\/MAM-480910\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">denunciar<\/a> abusos de poder de los exmilicianos armados en Coosercom. De hecho, esta medida no disminuy\u00f3 la violencia en la ciudad, sino que <a href=\"http:\/\/www.scielo.org.co\/pdf\/rci\/n77\/n77a08.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">perpetu\u00f3<\/a> la idea de la justicia privada en manos de civiles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En diferentes barrios de la ciudad, las bandas se enfrentaron a Coosercom. Holgu\u00edn dijo que fue dejado en libertad en 1994, en medio de este conflicto, despu\u00e9s de que un juez determin\u00f3 que el asesinato del l\u00edder miliciano fue leg\u00edtima defensa, aunque InSight Crime no logr\u00f3 verificar la decisi\u00f3n judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn volvi\u00f3 a las armas para sumarse a la pelea con las antiguas milicias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en abril de 1995 cambiar\u00eda todo para \u00e9l. Fue invitado como observador a un proceso de di\u00e1logo entre los remanentes de las milicias y las bandas, mediado por la sociedad civil y la Alcald\u00eda de Medell\u00edn. \u00c9l accedi\u00f3 a asistir, pero con objetivos diferentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo cre\u00eda en la paz, yo fui con doble moral porque quer\u00eda identificar a unos enemigos de las milicias para luego matarlos\u201d, confes\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, cambi\u00f3 de opini\u00f3n en el momento en que escuch\u00f3 a un l\u00edder miliciano hablar del barrio que so\u00f1aba. Era el mismo sue\u00f1o de Holgu\u00edn y algunos l\u00edderes de bandas. Un barrio donde el abandono estatal no fuera la norma, y donde ni\u00f1os y ni\u00f1as pudieran crecer de manera segura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All\u00ed se dio cuenta de que: \u201cEl enemigo de nosotros no eran los milicianos. [El enemigo era] esa soledad en que viv\u00edamos, ese abandono que exist\u00eda en esas periferias, en donde lo \u00fanico que conoc\u00edamos del Estado era la bota militar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de all\u00ed, se gener\u00f3 un pacto de respeto a la vida y no agresi\u00f3n entre las bandas y Coosercom, que buscaba poner fin a la confrontaci\u00f3n entre ambos bandos, un proceso que marc\u00f3 la vida de Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNos sent\u00e1bamos y pod\u00edamos mirarnos sabiendo que \u00e9ramos enemigos y pod\u00edamos pactar\u201d, reflexion\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estos di\u00e1logos, hubo participaci\u00f3n de la Alcald\u00eda de Medell\u00edn, pero su apoyo fue limitado en cuanto a generar nuevas oportunidades para los j\u00f3venes que hac\u00edan parte de los pactos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c[\u2026] Los pactos de convivencia, [eran] pactar la vida. Eran los primeros auxilios. Pero luego el Estado ten\u00eda que invertir para que ese pacto de convivencia fuera estable. El Estado no lleg\u00f3 a esa segunda parte\u00bb, dijo a InSight Crime un acad\u00e9mico que acompa\u00f1\u00f3 los pactos en aquel entonces y que prefiri\u00f3 no ser identificado por motivos de seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que sucedi\u00f3 despu\u00e9s se convirti\u00f3 en el tal\u00f3n de Aquiles de los procesos de paz de Colombia, tanto en Medell\u00edn como en otras partes del pa\u00eds, y es una advertencia del pasado para la Paz Total hoy. Ante la ausencia de apoyo estatal para continuar con los procesos, los l\u00edderes de las bandas se valieron de lo conocido para mantener a flote los pactos: las fuentes de financiaci\u00f3n ilegales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Holgu\u00edn, para evitar que los j\u00f3venes violaran los pactos, los l\u00edderes crearon negocios legales con las rentas criminales que recib\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00faltiples fuentes con conocimiento de estos pactos en los barrios de Medell\u00edn en los 90 confirmaron a InSight Crime que se usaron dineros il\u00edcitos para financiar microempresas y otros proyectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTen\u00edamos a los chicos ya metidos en un proceso, dici\u00e9ndoles: no roben, no maten, colaboren&#8230;m\u00ednimamente ten\u00edamos que darles la comida a esos muchachos\u201d, explic\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero seg\u00fan \u00e9l, hab\u00eda otro beneficiario de las rentas criminales del grupo que no estaba dispuesto a renunciar a su tajada: un sargento de la polic\u00eda que recib\u00eda un porcentaje. Holgu\u00edn relat\u00f3 que cuando le pidi\u00f3 bajar el valor su porcentaje para tener m\u00e1s recursos para sus negocios legales, este respondi\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo, ustedes no van a hacer paz con la m\u00eda. Si el s\u00e1bado no me mandan nada, yo s\u00e9 qui\u00e9nes son ustedes y escojan: para [la c\u00e1rcel de] Bellavista o para el cementerio\u00bb, recuerda Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn decidi\u00f3 no pagarle y, en consecuencia, seg\u00fan \u00e9l, fue declarado objetivo militar por el polic\u00eda corrupto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un d\u00eda de abril 1996, Holgu\u00edn se movilizaba en una camioneta por un barrio del nororiente de Medell\u00edn, cuando cuatro balazos impactaron su carro. Las balas ven\u00edan del mismo polic\u00eda que lo hab\u00eda amenazado, seg\u00fan coment\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comenzaron a pelear. Holgu\u00edn gan\u00f3 el control de la subametralladora del polic\u00eda. Le dispar\u00f3 apuntando a una pierna, seg\u00fan dijo, y corri\u00f3 hacia el segundo piso de una vivienda cercana que le serv\u00eda de casa de seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pasados unos minutos, Holgu\u00edn fue capturado. Sin que \u00e9l supiera, el polic\u00eda hab\u00eda muerto a causa de su disparo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">InSight Crime accedi\u00f3 al expediente judicial de Holgu\u00edn y pudo confirmar la pelea con el sargento, pero, de acuerdo con la versi\u00f3n de la polic\u00eda, fue otra la causa de la confrontaci\u00f3n ese d\u00eda. En el expediente se describe c\u00f3mo Holgu\u00edn supuestamente hu\u00eda en compa\u00f1\u00eda de un colega criminal de un robo que hab\u00eda cometido a unas oficinas en un barrio del occidente de Medell\u00edn, cuando la patrulla del polic\u00eda los identific\u00f3. Seg\u00fan el expediente, habr\u00eda sido este robo y no una disputa personal, el motivo por el que Holgu\u00edn fue parado por el sargento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">De sicario a pacificador<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn fue trasladado a la c\u00e1rcel Bellavista, en el municipio de Bello, aleda\u00f1o a Medell\u00edn. Cumpli\u00f3 los 27 a\u00f1os tras las rejas. Record\u00f3 que la primera noche llor\u00f3, sabiendo que podr\u00eda pasar entre 40 y 60 a\u00f1os en prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-5.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224541\"\/><figcaption class=\"wp-element-caption\"><em>Fragmento de expediente carcelario de Holgu\u00edn. Cr\u00e9dito: C\u00e1rcel y Penitenciar\u00eda de Media Seguridad de Bello.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer a\u00f1o, pasaba sus d\u00edas vendiendo desayunos y haciendo ejercicio. Afuera de la c\u00e1rcel, los pactos comenzaron a resquebrajarse. Seg\u00fan Holgu\u00edn, la raz\u00f3n principal fue la captura gradual de los l\u00edderes de las bandas, quienes tambi\u00e9n lideraban los pactos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1997, la Alcald\u00eda de Medell\u00edn reuni\u00f3 a Holgu\u00edn y a otros reclusos de Bellavista para que desde las c\u00e1rceles mediaran para mantener los procesos de convivencia en los barrios. As\u00ed, trabajaron en una propuesta que fue aprobada en agosto de ese mismo a\u00f1o, cuyo objetivo era poner fin a los conflictos en los barrios de la ciudad.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-6.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224543\"\/><figcaption class=\"wp-element-caption\"><em>Holgu\u00edn participando de los procesos de convivencia en la c\u00e1rcel Bellavista. Cr\u00e9dito: cortes\u00eda Henry Holgu\u00edn.<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa recibi\u00f3 cr\u00edticas, pues no se resolvieron los temas estructurales que alimentaban los ciclos de violencia. Por el contrario, la institucionalidad permiti\u00f3 que actores armados dentro y fuera de la c\u00e1rcel mantuvieran su poder criminal sobre diferentes barrios de la ciudad, lo que dio lugar a un relacionamiento t\u00e1cito entre la criminalidad de la ciudad y la institucionalidad, que contin\u00faa siendo uno de los principales retos para los negociadores de la Paz Total. Los \u00edndices de violencia se convirtieron en la moneda de cambio de los grupos criminales para calibrar la presi\u00f3n sobre los representantes del gobierno y poder continuar recibiendo sus rentas ilegales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de Holgu\u00edn, dijo que, a pesar de ser reconocido como l\u00edder del proceso carcelario, continuaba recibiendo dineros ilegales por fuera de la c\u00e1rcel. Pero, Holgu\u00edn, quien se hab\u00eda acercado a la religi\u00f3n en la c\u00e1rcel, se sinti\u00f3 conflictuado y tom\u00f3 la decisi\u00f3n de entregar sus rentas. Sus subalternos intentaron disuadirlo, llam\u00e1ndolo ingenuo y diciendo que nada iba a cambiar en la calle. Pero Holgu\u00edn se mantuvo firme.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-7.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224545\"\/><figcaption class=\"wp-element-caption\"><em>Holgu\u00edn presentando el proceso de convivencia en la c\u00e1rcel Bellavista. Cr\u00e9dito: cortes\u00eda Henry Holgu\u00edn<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">\u201cYo necesito dar el primer paso y que las cosas cambien en m\u00ed, y ser un verdadero comisionado de paz, como est\u00e1 diciendo la gente\u201d, les respondi\u00f3<em>.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el proceso de Bellavista, se hicieron m\u00e1s de 50 pactos de respeto a la vida y no agresi\u00f3n en barrios de Medell\u00edn, seg\u00fan mencion\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de Bellavista se sum\u00f3 a una serie de pactos entre bandas que ven\u00edan desde 1995. Para 1999, procesos de mediaci\u00f3n o pactos con 160 grupos armados de la ciudad, entre bandas, combos y milicias, seg\u00fan report\u00f3 el diario El Colombiano en ese entonces. Aproximadamente 3.000 personas de estos grupos hicieron parte del proceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn esa \u00e9poca todos fuimos muy felices, [hab\u00eda] mucha esperanza\u201d, record\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, esa felicidad dur\u00f3 poco. Para ese entonces un nuevo actor armado entraba al escenario criminal de Medell\u00edn, iniciando un nuevo ciclo de violencia en la ciudad, que llevar\u00eda a un entramado criminal m\u00e1s complejo, fragmentado y sin cabezas visibles; ese es el escenario en el que hoy se propende por la Paz Total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nuevos ciclos de violencia: el paramilitarismo se toma la ciudad<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" height=\"492\" width=\"1024\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Cap-2.jpg?resize=1024%2C492&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224572\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras Henry Holgu\u00edn intentaba romper el ciclo de la guerra de las pandillas de Medell\u00edn desde la c\u00e1rcel de Bellavista, el conflicto de Colombia entraba en una nueva fase, a\u00fan m\u00e1s brutal, con la expansi\u00f3n de los grupos paramilitares de derecha por todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos de estos grupos estaban motivados pol\u00edticamente a eliminar a las guerrillas de izquierda, pero otros eran simplemente ej\u00e9rcitos privados de narcotraficantes que se escond\u00edan tras una fachada de contrainsurgencia. As\u00ed, la brecha entre el conflicto pol\u00edtico colombiano y el crimen organizado sigui\u00f3 cerr\u00e1ndose, hasta el escenario que hoy enfrenta la Paz Total, donde ambas caras son casi imposibles de separar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los paramilitares llegaron a Medell\u00edn al final de 1998 cuando una organizaci\u00f3n conocida como las Autodefensas Unidas de Colombia (<a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/auc-perfil\/\" target=\"_blank\" rel=\"noreferrer noopener\">AUC<\/a>) envi\u00f3 a una de sus estructuras, el Bloque Metro, para eliminar a las milicias de izquierda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como lo hab\u00edan hecho anteriormente la guerrilla y los narcotraficantes, los paramilitares buscaron reclutas entre las bandas de los barrios marginados, para lo cual contactaron a sus jefes. Y ah\u00ed chocaron con Holgu\u00edn y sus sue\u00f1os de paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No pas\u00f3 mucho tiempo antes de que Holgu\u00edn recibiera una llamada del Bloque Metro para convencerlo de apoyar esa causa. Seg\u00fan Holgu\u00edn, representantes de esta estructura le exigieron entregar a los m\u00e1s de 3.000 j\u00f3venes que participaban en el proceso de paz que \u00e9l lideraba desde la c\u00e1rcel de Bellavista. Los paramilitares quer\u00edan engrosar sus filas armadas con estos j\u00f3venes, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn dijo que ya hab\u00eda rechazado estas solicitudes en dos ocasiones, pero esta vez fue algo distinto. Un d\u00eda de 2001, los representantes de los paramilitares en la c\u00e1rcel le entregaron un tel\u00e9fono. Cuando Holgu\u00edn lo acerc\u00f3 a su o\u00eddo, escuch\u00f3 la voz ronca de Carlos Casta\u00f1o, el entonces m\u00e1ximo comandante de las AUC y una de las figuras m\u00e1s notorias de la larga y sangrienta historia de Colombia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo me asust\u00e9 demasiado porque era una \u00e9poca de muchas masacres y mucha cosa\u201d, cont\u00f3 Holgu\u00edn, \u00abyo me pongo a llorar y le digo \u2018yo trabajo es por la paz [\u2026] est\u00e9 tranquilo, que yo nunca voy a permitir que se vayan a volver guerrilleros, pero tampoco pa\u2019 que se vuelvan paramilitares. Yo soy neutral\u2019.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las palabras de Casta\u00f1o fueron contundentes. \u201c\u00bfNeutral?, \u00bfqui\u00e9n le dijo a usted que un carro en neutro camina?\u00bb y colg\u00f3 el tel\u00e9fono.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn record\u00f3 la conversaci\u00f3n que tuvo al otro d\u00eda, cuando uno de los hombres de los paramilitares le reclam\u00f3 el celular y le pregunt\u00f3 si hab\u00edan llegado a un acuerdo. Holgu\u00edn ya ten\u00eda una resoluci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfSabe qu\u00e9?\u201d le dijo. \u201cCuando las milicias llegaron a tomarse la ciudad ustedes no exist\u00edan. Y ahora que ya tenemos la ciudad, ustedes ya quieren llegar. Si usted quiere reclutar a esos muchachos, recl\u00fatelos. Pero yo no, el proceso no se lo entrego. Y nunca voy a poner mi liderazgo en favor de que ustedes recluten a los muchachos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imposible probar si se debi\u00f3 a su rechazo a sumarse al proyecto paramilitar, pero poco despu\u00e9s de esa negativa, Holgu\u00edn fue trasladado a una c\u00e1rcel a m\u00e1s de 500 kil\u00f3metros de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde all\u00e1, no pod\u00eda impedir que los paramilitares reclutaran a muchos de los j\u00f3venes que participaban en el proceso liderado desde Bellavista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSent\u00eda ese dolor de sentirme traicionado, de saber que ese sue\u00f1o de paz y convivencia lo hab\u00edan truncado\u00bb, lament\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">De pe\u00f3n al poder: el ascenso criminal de Don Berna<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Poco a poco los paramilitares empezaron a expulsar a las milicias de los barrios. Pero incluso entonces, no eran el verdadero poder detr\u00e1s del hampa de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el ca\u00f3tico panorama posterior a la muerte de Pablo Escobar en 1993, un hombre logr\u00f3 agrupar el hampa de Medell\u00edn: Diego Fernando Murillo, alias \u201c<a href=\"https:\/\/es.insightcrime.org\/noticias\/analisis\/don-berna\/\" target=\"_blank\" rel=\"noreferrer noopener\">Don Berna<\/a>\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#b40026\" class=\"has-inline-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/colombia-elites-crimen-organizado-don-berna\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9lites y crimen organizado en Colombia: &#8216;Don Berna&#8217;<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que Holgu\u00edn, Don Berna ten\u00eda un origen humilde y hab\u00eda vivido distintas etapas del conflicto en Colombia. Tambi\u00e9n comenz\u00f3 su carrera delictiva con el EPL en la d\u00e9cada de los 80, para luego unirse a las filas del Cartel de Medell\u00edn. Berna integr\u00f3 la llamada <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/oficina-de-envigado-perfil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Oficina de Envigado<\/a>, una entidad encargada de cobrar deudas y de que todos los miembros del Cartel de Medell\u00edn le pagaran sus cuotas a Escobar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los 90, Don Berna se convirti\u00f3 en uno de los protagonistas del hampa en Colombia. Cuando Escobar asesin\u00f3 a sus jefes por una disputa de dinero, Berna se volvi\u00f3 contra el capo, y junto con otros enemigos de Pablo Escobar que formaron los PEPES, colabor\u00f3 estrechamente con las fuerzas de seguridad de Colombia para buscar la ca\u00edda del narcotraficante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la muerte de Escobar, Don Berna reagrup\u00f3 la mayor parte del submundo criminal de Medell\u00edn.&nbsp; Asumi\u00f3 el liderazgo de la Oficina de Envigado, que sigui\u00f3 actuando como agencia de cobro de deudas, pero ahora para los diversos narcos que hab\u00edan llenado el vac\u00edo dejado por Escobar. Don Berna cre\u00f3 alianzas con diferentes pandillas del \u00e1rea metropolitana de Medell\u00edn para <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/09\/medellin-memorias-de-una-guerra-urbana-paz-total-insight-crime.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">establecer<\/a> un amplio control territorial. As\u00ed, cre\u00f3 una empresa criminal que operaba en red, con jerarqu\u00edas claras, pero tambi\u00e9n con la autonom\u00eda necesaria para el \u00e9xito en sus actividades il\u00edcitas. En lugar de operar como un dictador, al estilo de Pablo Escobar, Don Berna se posicion\u00f3 como juez, jurado y verdugo de la criminalidad en Medell\u00edn.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Asdi-Paz-Total-Composicion-de-la-criminalidad-en-Medellin-1997-2003-InSight-Crime_Sep-2023-4-2.jpg?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224683\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Don Berna tambi\u00e9n se ali\u00f3 con las AUC y se presentaba como comandante paramilitar. Pero cuando el gobierno colombiano ofreci\u00f3 a los paramilitares un acuerdo ventajoso en la forma de un proceso de desmovilizaci\u00f3n, surgi\u00f3 un conflicto entre Berna \u2014para quien el proceso de paz ser\u00eda una manera de limpiar su pasado criminal\u2014 y el Bloque Metro, que estaba en desacuerdo con la inclusi\u00f3n de narcotraficantes dentro de las AUC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para confrontar al Bloque Metro, Don Berna <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/09\/medellin-memorias-de-una-guerra-urbana-paz-total-insight-crime.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">despleg\u00f3<\/a> su propio bloque paramilitar, denominado Bloque Cacique Nutibara (BCN), para el cual uni\u00f3 a muchas de las bandas de la ciudad como fuerza armada. La violencia volvi\u00f3 a desatarse. En 2002, la ciudad <a href=\"https:\/\/app.powerbi.com\/view?r=eyJrIjoiYTAxNGEzNWEtN2VlNy00Njg5LWI0ZTAtMWY5MzZjMTUyMmZjIiwidCI6IjljNDhlMDg4LTVlNDQtNGIwZC05M2EwLWVlYjJjNjEyN2MzZCIsImMiOjR9\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">tuvo<\/a> un nuevo pico de homicidios, con 3.829 personas asesinadas (179,8 por cada 100.000 habitantes).<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-genially wp-block-embed-genially\"><div class=\"wp-block-embed__wrapper\">\n<iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Evoluci\u00f3n de homicidios en Medell\u00edn 1970-2022 InSightCrime Agosto 2023\" frameborder='0' width='1200' height='618.0300500834725' src='https:\/\/view.genial.ly\/64efb41274b1480018cb29d2#?secret=coHvNsjMQz' data-secret='coHvNsjMQz' scrolling='yes'><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o siguiente, el BCN acab\u00f3 con el Bloque Metro. Tanto las milicias como los paramilitares con motivaciones ideol\u00f3gicas hab\u00edan desaparecido. El crimen hab\u00eda prevalecido sobre lo pol\u00edtico, y Don Berna estaba en la cima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Berna y el BCN se acogieron a los di\u00e1logos y en diciembre de 2003, el BCN fue el primer bloque paramilitar en desmovilizarse, con el sometimiento de 868 combatientes y la entrega de 497 armas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una propuesta inesperada<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La desmovilizaci\u00f3n coincidi\u00f3 con la \u00faltima etapa de Holgu\u00edn en la c\u00e1rcel, pues su condena se hab\u00eda reducido a 10 a\u00f1os, por estudio y trabajo. En septiembre de 2005, cuando a Holgu\u00edn le faltaban dos meses para cumplir su condena, lo trasladaron a la c\u00e1rcel de Itag\u00fc\u00ed, un municipio vecino de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco tiempo despu\u00e9s de su llegada, Holgu\u00edn se encontraba en su celda, cuando unos guardias de la c\u00e1rcel lo esposaron, seg\u00fan record\u00f3. \u201cVa para donde el patr\u00f3n\u201d, le dijeron. Y lo sacaron de su celda a punta de empujones. \u201cYo cre\u00eda que me iban a matar\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese momento lleg\u00f3 hasta donde el supuesto patr\u00f3n; quien lo esperaba era Don Berna. Este se hab\u00eda entregado a las autoridades en mayo de ese a\u00f1o, por presi\u00f3n de otros l\u00edderes de las AUC, despu\u00e9s de que la Fiscal\u00eda colombiana lo acusara del asesinato de un l\u00edder social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn record\u00f3 la conversaci\u00f3n con Berna:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl pol\u00e9mico Henry Holgu\u00edn\u201d, fue el saludo del hombre m\u00e1s poderoso del hampa de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSent\u00ed susto, las \u2018g\u00fcevas\u2019 en la nuca\u201d, record\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima vez que Holgu\u00edn hab\u00eda estado en Medell\u00edn hab\u00eda sido expulsado de la ciudad justamente por negarse a ser parte de las AUC y en ese momento quiso anticiparse y apaciguarlo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abYa estoy esperando la libertad, no me le voy a quedar en la ciudad. Yo le respeto esto a usted. D\u00edgame si usted me da la oportunidad de salir de aqu\u00ed, que yo le garantizo que salgo de esta c\u00e1rcel y me voy para el lugar m\u00e1s lejos que me pueda ir\u201d, le dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero Don Berna ten\u00eda otro prop\u00f3sito para Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNadie en esta ciudad puede desconocer todo lo que has hecho por la paz\u201d, le respondi\u00f3 Berna, seg\u00fan record\u00f3 Holgu\u00edn: \u201cqueremos que trabaj\u00e9s por el proceso de paz y que todo lo social que vos quer\u00e9s hacer lo hag\u00e1s en los territorios de las Autodefensas Unidas de Colombia\u201d.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-9.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224549\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn acept\u00f3, entusiasmado con la idea de continuar su trabajo por la paz y honrado por el reconocimiento y respeto que vio en Don Berna. As\u00ed, fue nombrado miembro de la junta directiva de la Corporaci\u00f3n Democracia, una organizaci\u00f3n que surgi\u00f3 en mayo de 2004, luego de la desmovilizaci\u00f3n del BCN, para hacer seguimiento al proceso de reincorporaci\u00f3n de los exparamilitares a la vida civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn se encarg\u00f3 de coordinar el \u00e1rea social de la corporaci\u00f3n. Buscaba continuar con el proceso que hab\u00eda adelantado desde 1995 y luego desde la c\u00e1rcel de Bellavista, pero esta vez con los desmovilizados de las AUC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHay un momento fenomenal en donde llegamos a hacer una cumbre nacional de todas las autodefensas desmovilizadas. Todos los se\u00f1ores comandantes desmovilizados de las AUC manifestaron su aprobaci\u00f3n al desarrollo del proyecto social que les presentamos, lo cual nos llen\u00f3 de mucha alegr\u00eda, mucha expectativa\u00bb, record\u00f3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un sue\u00f1o destrozado<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El sue\u00f1o de Holgu\u00edn de construir la paz a trav\u00e9s de la desmovilizaci\u00f3n paramilitar pronto se desmoron\u00f3 cuando comenz\u00f3 a notar una descomposici\u00f3n del proceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDe repente se dan como unos se\u00f1alamientos o una criminalizaci\u00f3n de los se\u00f1ores dirigentes de estos grupos, en lo nacional, y en lo local\u201d, dijo Holgu\u00edn. La desmovilizaci\u00f3n hab\u00eda sido una fachada que permiti\u00f3 a Don Berna mantener un control total sobre el hampa de Medell\u00edn y para ese entonces, ya era evidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Funcionarios de la Medell\u00edn <a href=\"https:\/\/www.hrw.org\/es\/report\/2010\/02\/03\/herederos-de-los-paramilitares\/la-nueva-cara-de-la-violencia-en-colombia#_ftn14\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">dijeron<\/a> a Human Rights Watch en 2009 que hasta 75% de los desmovilizados no eran en realidad combatientes paramilitares. A\u00f1os despu\u00e9s, en 2011, un excomandante de las AUC <a href=\"https:\/\/www.eltiempo.com\/archivo\/documento\/CMS-8964100\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">declar\u00f3<\/a> que la desmovilizaci\u00f3n del BCN hab\u00eda sido ficticia, y que los l\u00edderes recib\u00edan beneficios mientras continuaban con sus actividades delictivas. Una vez m\u00e1s, una desmovilizaci\u00f3n y desarme en Medell\u00edn no evit\u00f3 que se reciclaran ciclos de violencia y estructuras criminales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El n\u00famero de homicidios disminuy\u00f3 en los a\u00f1os posteriores a la desmovilizaci\u00f3n del BCN (de 3.829 casos y una tasa de 179,8 homicidios por cada 100.0000 habitantes en 2002, a 782 casos y una tasa de 35,3 por cada 100.000 habitantes en 2005). Pero esto fue una demostraci\u00f3n de la fuerza criminal de Don Berna, en lugar del resultado de pol\u00edticas p\u00fablicas. Ning\u00fan miembro de una banda en la ciudad pod\u00eda cometer asesinatos sin la autorizaci\u00f3n directa del patr\u00f3n. Por primera, pero no por \u00faltima vez, Medell\u00edn experimentaba una paz basada en el control criminal de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Corporaci\u00f3n Democracia result\u00f3 ser otro veh\u00edculo para el control criminal. Aparte de tener su estructura y ciertas actividades legales, muchos de sus dirigentes continuaron sus carreras criminales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Asdi-Paz-Total-Composicion-de-la-criminalidad-en-Medellin-2003-2008-InSight-Crime_Sep-2023-4-2.jpg?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224685\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para Holgu\u00edn, la gota que colm\u00f3 el vaso fue el asesinato de un buen amigo el 16 de noviembre de 2006, el entonces cabecilla de la banda criminal \u201cLos Pachelly\u201d. Holgu\u00edn culp\u00f3 de este hecho a los exparamilitares de las AUC, aunque nadie ha sido condenado por el crimen y oficialmente se desconoce la identidad de los asesinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe disminuy\u00f3 la esperanza y me dio mucha tristeza de que hubiera ocurrido ese caso. Y eso me llev\u00f3 a pensar que quien lideraba el proceso en esa \u00e9poca valoraba m\u00e1s sus intereses militares por encima de lo que se deb\u00eda de hacer socialmente\u201d, coment\u00f3 al respecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Decepcionado, comenz\u00f3 a buscar oportunidades fuera del pa\u00eds. \u00abMe desped\u00ed de todos ac\u00e1, y le dije [a Don Berna] que fue muy triste la muerte de mi amigo, que debido a esa tristeza mi coraz\u00f3n no me daba la capacidad para seguir militando en lo social aqu\u00ed\u201d. Luego de esto, decidi\u00f3 mudarse a Espa\u00f1a en 2008.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-11.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224553\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo a\u00f1o en que Holgu\u00edn dej\u00f3 el pa\u00eds, Don Berna fue extraditado a Estados Unidos junto con otros excomandantes paramilitares, acusado de continuar sus actividades il\u00edcitas despu\u00e9s de su desmovilizaci\u00f3n. El hampa de Medell\u00edn, una vez m\u00e1s, quedaba sin l\u00edder y se enfrentaba a una nueva metamorfosis.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La fragmentaci\u00f3n del hampa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La extradici\u00f3n de Don Berna desat\u00f3 una guerra de sucesi\u00f3n que llev\u00f3 a la fragmentaci\u00f3n criminal de Medell\u00edn, y que cre\u00f3 las condiciones a las que hoy se enfrenta la Paz Total en la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos lugartenientes de Don Berna buscaron llenar el vac\u00edo y en 2008 se inici\u00f3 una guerra que alcanz\u00f3 su pico en 2009. Ese a\u00f1o, se registraron 2.186 homicidios en la ciudad (94 por cada 100,000 habitantes), 1.141 casos m\u00e1s que el a\u00f1o anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, Holgu\u00edn se hab\u00eda mudado de Espa\u00f1a a Per\u00fa, donde empez\u00f3 a trabajar en temas de convivencia y seguridad ciudadana para los gobiernos locales de las ciudades de Callao, adyacente a Lima, la capital y Piura, en el norte del pa\u00eds. Desde all\u00ed, segu\u00eda las noticias sobre las confrontaciones en Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abYo lloraba la guerra, porque en la guerra siempre mueren muchos amigos\u00bb, record\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para 2012, los dos lugartenientes rivales hab\u00edan sido capturados por las autoridades. Pero la guerra continu\u00f3. Las bandas de la ciudad estaban divididas en dos facciones: las que permanec\u00edan unidas bajo el estandarte de la Oficina de Envigado, ahora sin l\u00edder \u00fanico, y las que se hab\u00edan unido a la red de un ej\u00e9rcito criminal invasor: el grupo paramilitar sucesor llamado Autodefensas Gaitanistas de Colombia (AGC).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#b40026\" class=\"has-inline-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/urabenos-perfil\/#:~:text=Los%20Gaitanistas%2C%20tambi%C3%A9n%20conocidos%20como,con%20alcance%20a%20nivel%20nacional.\" target=\"_blank\" rel=\"noreferrer noopener\">Perf\u00edl de los Gaitanistas &#8211; Clan del Golfo<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Esta nueva fase de la guerra termin\u00f3 con un pacto entre los grupos en conflicto en julio de 2013. Fue un <a href=\"https:\/\/es.insightcrime.org\/noticias\/analisis\/una-tregua-en-medellin-acerca-a-los-grupos-a-una-hegeomonia-criminal\/\" target=\"_blank\" rel=\"noreferrer noopener\">pacto<\/a> que no fue negociado por las autoridades ni por mediadores de paz como Henry Holgu\u00edn, sino por oscuros narcotraficantes y \u00e9lites criminales a quienes la guerra afectaba los negocios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este llamado \u201cpacto de fusil\u201d fue un armisticio despojado de una soluci\u00f3n pol\u00edtica, basado \u00fanicamente en el silenciamiento de las armas con el objetivo de maximizar las oportunidades criminales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, lo que no lograron los procesos de paz iniciados por el gobierno nacional y local, los grupos criminales lo lograron por s\u00ed mismos otra vez, como hab\u00eda sucedido en los a\u00f1os 90. Los homicidios disminuyeron de 1.248 en 2012 (52,2 por cada 100.000 habitantes) a 659 en 2014 (27 por cada 100.000 habitantes), una reducci\u00f3n de casi 50% en solo dos a\u00f1os. Para ese entonces, los grupos criminales hab\u00edan entendido que la violencia atra\u00eda atenci\u00f3n innecesaria sobre ellos y sus econom\u00edas criminales, y que mantener niveles bajos de violencia pod\u00eda jugar a su favor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Al mismo tiempo, el negocio estaba en auge: los narcotraficantes de Medell\u00edn se beneficiaron del aumento del tr\u00e1fico de coca\u00edna y, libres de la amenaza de las luchas territoriales, las bandas consolidaban su control sobre econom\u00edas delictivas como la extorsi\u00f3n y el microtr\u00e1fico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hab\u00edan aprendido una lecci\u00f3n importante: estos pactos significaron que la criminalidad en Medell\u00edn no tendr\u00eda un l\u00edder \u00fanico.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodas las estructuras tomaron la decisi\u00f3n de que no iban a permitir que Medell\u00edn y el Valle de Aburr\u00e1 volviera a tener un patr\u00f3n\u201d, dijo Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El submundo que los negociadores de Paz Total encontrar\u00edan casi una d\u00e9cada despu\u00e9s estaba tomando forma: fragmentado y sin l\u00edderes, pero arraigado, de gran alcance, poderoso y con influencia sobre las propias autoridades.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Asdi-Paz-Total-Composicion-de-la-criminalidad-en-Medellin-2013-2023-InSight-Crime_Sep-2023-3-2.jpg?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224687\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El resultado fue un hampa <a href=\"https:\/\/www.eafit.edu.co\/escuelas\/economiayfinanzas\/cief\/Documents\/gobierno-criminal-medellin.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">formada<\/a> por entre 350 y 400 bandas locales semiindependientes llamadas combos, que responden a entre 15 y 20 bandas criminales mayores que controlan el hampa de Medell\u00edn mediante pactos entre ellas. Algunas de esas estructuras principales forman la direcci\u00f3n de la Oficina, brindando servicios a narcotraficantes transnacionales y otras \u00e9lites mafiosas. Otras est\u00e1n aliadas con traficantes de drogas de las AGC, y algunas m\u00e1s son independientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda empezado un nuevo ciclo de crimen organizado en Medell\u00edn que se mantiene hasta hoy y que la Paz Total busca romper.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las deudas pendientes de la paz urbana<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" height=\"492\" width=\"1024\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Cap-3.jpg?resize=1024%2C492&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224574\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Corr\u00eda el a\u00f1o 2015 y&nbsp;Colombia viv\u00eda aires de paz. El gobierno colombiano se encontraba dialogando con la guerrilla de las Fuerzas Armadas Revolucionarias de Colombia (<a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/farc-perfil\/\" target=\"_blank\" rel=\"noreferrer noopener\">FARC<\/a>) para poner fin a medio siglo de guerra revolucionaria. Medell\u00edn tambi\u00e9n gozaba de paz, aunque muy diferente a la que se negociaba con la guerrilla, ya que, con excepci\u00f3n de estallidos de violencia espor\u00e1dicos, el pacto del fusil se manten\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al regresar a su ciudad natal ese mismo a\u00f1o, Holgu\u00edn se encontr\u00f3 con antiguos colegas criminales con quienes hab\u00eda adelantado el esfuerzo por bajar los \u00edndices de violencia en la ciudad desde la c\u00e1rcel de Bellavista en los 90.&nbsp;Ellos lo pusieron al tanto de los cambios en el hampa desde el pacto de fusil de 2013.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe dijeron que las cosas aqu\u00ed hab\u00edan cambiado mucho [\u2026] se solucionaban [los conflictos] de una forma m\u00e1s pac\u00edfica, dialogando\u201d, cont\u00f3 emocionado Holgu\u00edn. Estas formas pac\u00edficas consist\u00edan en pactos entre criminales para mantener los \u00edndices de violencia bajos con el fin de no llamar la atenci\u00f3n de las autoridades, en vez de dejar la criminalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, Holgu\u00edn vio ecos de los procesos de paz que hab\u00eda tratado de liderar en el pasado y una oportunidad de una paz nueva y duradera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Holgu\u00edn hab\u00eda regresado para resolver un problema familiar, pero decidi\u00f3 quedarse despu\u00e9s de hablar con un viejo conocido, el sacerdote Dar\u00edo Monsalve, quien hab\u00eda acompa\u00f1ado el proceso de la c\u00e1rcel de Bellavista cuando fue obispo auxiliar en Medell\u00edn entre 1993 y 2001.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUsted es un generador de procesos. \u00bfNo ha pensado en reimpulsar el proceso de Medell\u00edn?\u201d, le dijo el sacerdote.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Borrando la l\u00ednea<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con el apoyo de algunos miembros de la Iglesia, Holgu\u00edn empez\u00f3 a trabajar con algunos de sus viejos colegas que lo hab\u00edan acompa\u00f1ado en la negociaci\u00f3n de pactos de no agresi\u00f3n desde Bellavista y que, al igual que \u00e9l, ya viv\u00edan en libertad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hicieron un encuentro en un hotel de Medell\u00edn para organizar el equipo de trabajo y reimpulsar los procesos que se llevaron a cabo en la ciudad en los a\u00f1os 90.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro capt\u00f3 la atenci\u00f3n de los l\u00edderes de La Oficina, remanentes de la m\u00edtica Oficina de Envigado. \u201cLos l\u00edderes de La Oficina y los grupos, los factores reales de poder en la ciudad, me convocaron\u201d, record\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le preguntaron cu\u00e1l era su inter\u00e9s en regresar a la ciudad y \u00e9l les contest\u00f3 que buscar\u00eda impulsar los procesos de convivencia que se llevaron a cabo en el pasado, pero que para eso requer\u00eda la voluntad de paz de los actores armados de la ciudad. Ellos le manifestaron su voluntad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con ese respaldo, Holgu\u00edn sigui\u00f3 adelante con el proyecto.&nbsp;\u201c[Hicimos] reuniones diarias para debatir, para construir\u201d, relat\u00f3.&nbsp;Ah\u00ed naci\u00f3 lo que ser\u00eda el movimiento social para la reconciliaci\u00f3n urbana denominado Sinergia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Busc\u00f3 el apoyo del gobierno local para cumplir su misi\u00f3n. En enero de 2016, Holgu\u00edn, en representaci\u00f3n de Sinergia, le present\u00f3 el proyecto al reci\u00e9n electo alcalde de Medell\u00edn, Federico Guti\u00e9rrez, acompa\u00f1ado del sacerdote Dar\u00edo Monsalve como garante.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLe proponemos al alcalde que vamos a crear un movimiento social, que iba a estar integrado por l\u00edderes sociales de sectores de la ciudad, por la Iglesia y que quer\u00edamos que la institucionalidad entrara a participar\u201d, evoc\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guti\u00e9rrez confirm\u00f3 esa reuni\u00f3n a InSight Crime, pero aclar\u00f3 que la cita la hab\u00eda pedido el exobispo a t\u00edtulo personal, no a nombre del movimiento Sinergia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ese entonces, las cabezas de la criminalidad en Medell\u00edn buscaban llegar a acuerdos con la justicia. Entre julio y noviembre, ocho l\u00edderes y miembros de bandas y combos en la ciudad se <a href=\"https:\/\/www.elcolombiano.com\/antioquia\/combos-aprovechan-un-decreto-de-gestores-de-paz-AI5291772\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">entregaron<\/a> a la justicia, seg\u00fan report\u00f3 el diario El Colombiano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Buscaban <a href=\"https:\/\/es.insightcrime.org\/noticias\/analisis\/surgen-preguntas-sobre-pandilleros-colombianos-busca-estatus-gestores-paz\/\" target=\"_blank\" rel=\"noreferrer noopener\">obtener<\/a> beneficios judiciales a trav\u00e9s de un decreto presidencial expedido en julio de 2016, que permit\u00eda al gobierno solicitar beneficios como la suspensi\u00f3n de medidas de aseguramiento o penas alternativas a quienes fungieran como gestores de paz para posibilitar acuerdos humanitarios.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En noviembre de 2016, tambi\u00e9n se conoci\u00f3 una carta enviada por algunos miembros de La Oficina al entonces presidente Juan Manuel Santos, donde le <a href=\"https:\/\/noticias.caracoltv.com\/antioquia\/con-carta-al-presidente-oficina-de-envigado-busca-espacio-en-proceso-de-paz\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">expon\u00edan<\/a> su deseo de ser incluidos en un proceso exploratorio para alcanzar una paz urbana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, en julio de 2017, un esc\u00e1ndalo de grandes magnitudes salpic\u00f3 a La Oficina, a Sinergia y al gobierno local, poniendo fin a las pocas posibilidades de paz que hab\u00eda en aquel entonces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gustavo Villegas, el entonces secretario de seguridad de Medell\u00edn, quien gestion\u00f3 la rendici\u00f3n de varios mandos medios de la Oficina fue <a href=\"https:\/\/es.insightcrime.org\/noticias\/analisis\/borrando-linea-secretario-seguridad-mafia-medellin\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">capturado<\/a> por presuntamente valerse de su posici\u00f3n para obtener favores por parte de miembros de esa red criminal. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan <a href=\"https:\/\/verdadabierta.com\/los-acuerdos-siniestros-del-secretario-de-seguridad-de-medellin\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">expuso<\/a> el fiscal encargado al juez del caso, estos favores inclu\u00edan que miembros de las bandas se entregaran a la polic\u00eda, para ser pasados como logros de Villegas. Este \u00faltimo les ofrec\u00eda a cambio alternativas de sometimiento a la justicia que les permitieran recibir beneficios jur\u00eddicos, incluso la posibilidad de un estatus como \u201cgestores de paz y convivencia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El enlace de Villegas con La Oficina era presuntamente Julio C\u00e9sar Perdomo, desmovilizado de las AUC y miembro de Sinergia en ese entonces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque quedan muchas cosas por aclarar sobre el caso, este mostr\u00f3 la delgada l\u00ednea entre la mediaci\u00f3n y la colusi\u00f3n. El hecho deriv\u00f3 en una desconfianza hacia el movimiento Sinergia. Muchos de los miembros se retiraron y la organizaci\u00f3n se vio reducida a unos pocos, entre ellos Holgu\u00edn.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este hecho tambi\u00e9n afect\u00f3 la institucionalidad. Por un lado, sembr\u00f3 desconfianza en la ciudadan\u00eda, y por otro, llev\u00f3 a que muchos funcionarios p\u00fablicos se abstuvieran de vincularse a temas de paz, algo que sigue vigente a\u00fan hoy.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPol\u00edticamente nos hizo un da\u00f1o enorme, empezaron a ver a Sinergia como satanizado\u00bb, lament\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al d\u00eda de hoy, las opiniones respecto a Sinergia son encontradas. InSight Crime habl\u00f3 con periodistas, representantes de las instituciones y miembros de organizaciones sociales, quienes ven con recelo a Sinergia, algunos por la presencia de abogados de las estructuras armadas dentro del movimiento, y otros por los antecedentes penales de muchos de sus miembros, entre ellos Holgu\u00edn.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La propuesta de Paz Total<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En 2018, un a\u00f1o despu\u00e9s del esc\u00e1ndalo de Villegas en Medell\u00edn, Colombia eligi\u00f3 a Iv\u00e1n Duque como presidente, pero el nuevo mandatario no era af\u00edn a los temas de paz. Duque fue un fuerte opositor del acuerdo de paz firmado por el anterior gobierno con la guerrilla de las FARC, lo que afect\u00f3 su implementaci\u00f3n. En 2019 puso fin a los di\u00e1logos que se llevaban a cabo con el principal grupo guerrillero colombiano, el Ej\u00e9rcito de Liberaci\u00f3n Nacional (<a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-colombia\/eln-colombia\/#:~:text=El%20Ej\u00e9rcito%20de%20Liberaci\u00f3n%20Nacional,constituido%20como%20una%20guerrilla%20binacional.\" target=\"_blank\" rel=\"noreferrer noopener\">ELN<\/a>), en Quito, Ecuador, luego de un atentado a una escuela de formaci\u00f3n de cadetes de la polic\u00eda colombiana en enero de ese a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El enfoque del gobierno de Duque hizo eco en el gobierno local de Medell\u00edn e influy\u00f3 en el manejo del tema de las bandas criminales. Pasaron cuatro a\u00f1os de gobierno para que el tema de paz se volviera a hablar en Medell\u00edn. Fue el entonces candidato presidencial, Gustavo Petro, quien durante su campa\u00f1a habl\u00f3 de buscar una paz integral en Colombia con diferentes grupos armados.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#b40026\" class=\"has-inline-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/noticias\/analisis\/rey-muerto-rey-puesto-oficina-envigado-medellin-colombia\/\" target=\"_blank\" rel=\"noreferrer noopener\">A rey muerto, rey puesto en la Oficina de Envigado en Medell\u00edn, Colombia<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSent\u00ed la alegr\u00eda de la esperanza\u201d, dijo Holgu\u00edn.&nbsp;Despu\u00e9s de tantos a\u00f1os, se ve\u00eda una perspectiva de paz en el horizonte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Petro result\u00f3 elegido presidente en junio de 2022. Poco despu\u00e9s, Sinergia recibi\u00f3 la visita de Daniel Prada, anteriormente abogado del presidente electo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNos dijo que Gustavo Petro manifestaba [\u2026] que iba a cumplir con el proceso de Paz Total y que quer\u00edan una manifestaci\u00f3n de voluntades\u201d, mencion\u00f3 Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">InSight Crime se comunic\u00f3 con Daniel Prada, quien confirm\u00f3 esta reuni\u00f3n con Sinergia y puntualiz\u00f3 que el objetivo era conocer las voluntades de paz de los grupos, saber cu\u00e1les eran sus expectativas y presentarles la intenci\u00f3n del gobierno de cara a la Paz Total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta luz verde, Sinergia visit\u00f3 las c\u00e1rceles para recoger la voluntad de paz de los l\u00edderes criminales de Medell\u00edn.&nbsp;El proceso tom\u00f3 tiempo. En la estructura actual de la criminalidad en la ciudad, las decisiones se toman a partir de acuerdos y consensos en los que participan muchas cabezas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La voluntad de paz parec\u00eda un\u00e1nime en el hampa de Medell\u00edn. El Colombiano <a href=\"https:\/\/www.elcolombiano.com\/antioquia\/seguridad\/medellin-sera-clave-para-la-paz-total-del-gobierno-de-gustavo-petro-EL18572420\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">report\u00f3<\/a> en su momento sobre una reuni\u00f3n celebrada en agosto de 2022 entre los l\u00edderes del bajo mundo de la ciudad en la que se acord\u00f3 una tregua entre todas las bandas de la ciudad de cara a la Paz Total: no asesinatos, no venganzas, no disputas territoriales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La incertidumbre de la paz urbana<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A finales de agosto de 2022, en una <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Carta-de-los-Pachelly-Paz-Total-InSight-Crime.jpg\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">carta<\/a> enviada al gobierno de Gustavo Petro, la banda criminal \u201clos Pachelly\u201d anunci\u00f3 su voluntad de sumarse al proyecto de la Paz Total y design\u00f3 a Sinergia como sus voceros. Sin embargo, el rol de Sinergia no ha sido reconocido oficialmente dentro del proceso. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de esto, otras estructuras criminales de la ciudad como la Oficina, el Mesa, los Chatas, la Terraza y los Triana expresaron su voluntad de hacer parte de la Paz Total en la ciudad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-13.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224557\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El 2 de junio de 2023, luego de meses de incertidumbre sobre los avances de la paz urbana en Medell\u00edn y sin un piso jur\u00eddico para este tipo de negociaciones, el gobierno nacional instal\u00f3 una mesa de di\u00e1logos en la c\u00e1rcel de Itag\u00fc\u00ed, conocida como el espacio dial\u00f3gico sociojur\u00eddico.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/image-14.png?quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-224559\" style=\"width:440px;height:660px\"\/><figcaption class=\"wp-element-caption\"><em>Alto Comisionado para la Paz de Colombia, Danilo Rueda, anunciando el inicio de la mesa en la c\u00e1rcel de Itag\u00fc\u00ed. Cr\u00e9ditos: InSight Crime<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Un <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Declaracion-Grupos-Armados-Medellin-Paz-Total-InSight-Crime.jpg\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">comunicado<\/a> conjunto del gobierno y los grupos armados de ese mismo d\u00eda expon\u00eda que el proceso buscar\u00eda llevar a cabo las transformaciones para prevenir nuevas violencias y as\u00ed alcanzar una reintegraci\u00f3n exitosa de los integrantes de las estructuras armadas. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hasta ahora los planes para la Paz Total en la ciudad son poco concretos y los retos son grandes.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#b40026\" class=\"has-inline-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/noticias\/arriesgada-apuesta-colombia-paz-total\/#:~:text=An%C3%A1lisis%20de%20InSight%20Crime&amp;text=La%20%E2%80%9Cpaz%20total%E2%80%9D%20contempla%20desmovilizar,la%20justicia%2C%20seg%C3%BAn%20se%20considere.\" target=\"_blank\" rel=\"noreferrer noopener\">La arriesgada apuesta de Colombia por la &#8216;Paz Total&#8217;<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado de la fragmentaci\u00f3n criminal en Medell\u00edn, el gobierno no est\u00e1 negociando con un grupo. sino con los l\u00edderes de m\u00e1s de siete organizaciones criminales. Sin embargo, en esas estructuras no est\u00e1 agrupada la totalidad de la criminalidad organizada en Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jorge Mej\u00eda, coordinador de la delegaci\u00f3n del gobierno en el espacio dial\u00f3gico de la c\u00e1rcel La Paz de Itag\u00fc\u00ed, dijo a InSight Crime que se encuentran en conversaciones con el 90% de la delincuencia organizada de Medell\u00edn. Por fuera de estos di\u00e1logos hay otras bandas y combos, e incluso grandes organizaciones criminales como las AGC, que tienen presencia en la ciudad y con quienes el gobierno ha tenido di\u00e1logos paralelos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, los l\u00edderes que est\u00e1n en la mesa pueden tener intereses diferentes a los miembros de menor rango fuera de la c\u00e1rcel, muchos de los cuales ni siquiera tienen procesos judiciales abiertos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Medell\u00edn ya ha visto en los \u00faltimos meses asesinatos cometidos por miembros de las bandas fuera de la c\u00e1rcel, mientras sus l\u00edderes negocian con el gobierno en prisi\u00f3n. Estos asesinatos parecen responder a <a href=\"https:\/\/www.elespectador.com\/colombia\/medellin\/por-que-preocupa-lo-que-esta-pasando-en-manrique-en-medellin\/\">disputas<\/a> al interior de una de las bandas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igualmente, estructuras armadas de menor alcance como los combos pueden tener expectativas diferentes a las bandas que est\u00e1n sentadas con el gobierno en el marco de la Paz Total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi no se incluyen las estructuras consideradas de bajo impacto, estas van a llenar los vac\u00edos de las grandes, pero de manera m\u00e1s vertiginosa\u201d, advirti\u00f3 Carlos Zapata, presidente del Instituto Popular de Capacitaci\u00f3n, una ONG que trabaja en temas de paz, democracia y derechos humanos, en conversaci\u00f3n con InSight Crime.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la Paz Total deber\u00e1 enfrentar los fantasmas de experiencias pasadas.&nbsp;Como queda claro en la historia de Holgu\u00edn, ni el proceso de paz con las guerrillas en los a\u00f1os 80, ni la ca\u00edda de Pablo Escobar, la desmovilizaci\u00f3n de las milicias o los pactos entre bandas de los 90, la desmovilizaci\u00f3n paramilitar en la d\u00e9cada de los 2000 o los pactos de no agresi\u00f3n de La Oficina despu\u00e9s, ning\u00fan proceso o pacto ha sentado las bases de una paz duradera en la ciudad.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el contrario, esas experiencias han puesto en evidencia un reciclaje de violencia, una permanencia del control de los grupos armados en amplios territorios de la ciudad, la continuaci\u00f3n del ejercicio de rentas il\u00edcitas y una continua injerencia de la criminalidad en las din\u00e1micas de seguridad de Medell\u00edn.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes que desmantelar el bajo mundo de la ciudad, estos procesos han marcado su evoluci\u00f3n, arrastrando muchos de los retos a los que se enfrenta hoy la Paz Total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c[La] criminalidad est\u00e1 totalmente transformada y ha aprendido de todos los procesos de paz, en especial de los incumplimientos del Estado\u201d, dijo a InSight Crime el acad\u00e9mico que acompa\u00f1\u00f3 los pactos en los 90 y que prefiri\u00f3 no ser identificado por motivos de seguridad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Superar los obst\u00e1culos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En el espacio dial\u00f3gico establecido entre las bandas y el gobierno, este \u00faltimo se enfrenta al importante reto de buscar respuestas para cerrar definitivamente los ciclos de violencia en la ciudad, en vez de simplemente negociar los t\u00e9rminos de sometimiento de l\u00edderes y miembros de los grupos criminales. Tambi\u00e9n, deber\u00e1 reconocer las propias falencias del Estado y su ausencia hist\u00f3rica en las \u00e1reas m\u00e1s marginadas de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, las bandas se enfrentan al desaf\u00edo de mostrar su real voluntad de paz, aportando al desmantelamiento de las redes criminales con el fin de evitar que estas expresiones criminales revivan de diferentes formas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201c<\/em>\u00bfQue van a dar las bandas? \u00bfvan a aportar verdad? \u00bfvan a entregar las rutas? \u00bfvan a entregar aliados legales o ilegales? \u00bfnacionales o internacionales? \u00bfva a haber un abandono total de la criminalidad?\u201d, cuestion\u00f3 Juan Diego Restrepo E., director del medio Verdad Abierta, en conversacion con InSight Crime.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En respuesta a esto, Jorge Mej\u00eda asegur\u00f3 a InSight Crime que esa discusi\u00f3n se dar\u00e1 en la mesa una vez se definan los protocolos y la agenda de trabajo, y aclar\u00f3 que los miembros de los grupos han expresado de manera informal estar dispuestos a encarar este tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dudas sobre las motivaciones de los l\u00edderes de las bandas tambi\u00e9n pesan sobre algunos de sus voceros y representantes, incluyendo organizaciones como Sinergia y personas como Holgu\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSinergia es una de muchas organizaciones sociojur\u00eddicas que intenta representar a las bandas en proyectos de paz. Son organizaciones que est\u00e1n regidas por abogados penalistas y por exmiembros de bandas que cada vez que hay un proceso de paz tratan de pegarse all\u00ed con propuestas que terminen beneficiando a los cabecillas que est\u00e1n en las c\u00e1rceles\u00bb, replic\u00f3 el periodista investigativo de Medell\u00edn Nelson Matta a InSight Crime.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frente a esto, Holgu\u00edn, est\u00e1 convencido del compromiso con el proceso de los actores armados sentados en la mesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y aunque cree que no habr\u00e1 soluciones f\u00e1ciles a problemas tan profundamente arraigados, est\u00e1 convencido de que s\u00ed tienen <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Acogimiento-a-la-Justicia-Sinergia-InSight-Crime.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">propuestas<\/a> para plantear en la mesa de di\u00e1logo. \u201cEste espacio dial\u00f3gico se ha generado precisamente para tratar toda esa clase de temas que son inherentes al conflicto urbano\u201d coment\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y donde otros han visto que persisten los retos de las experiencias pasadas, \u00e9l ve las oportunidades para hacer de este proceso algo diferente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSon dos cosas que se recogen [en la mesa]: las experiencias vividas, con todos los aprendizajes que nos han dejado y la participaci\u00f3n activa de las comunidades organizadas en torno a estos escenarios de inclusi\u00f3n y participaci\u00f3n para la concertaci\u00f3n\u201d, reflexion\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su optimismo hacia el proceso se apoya en su experiencia de vida. \u00c9l, un g\u00e1ngster convertido en promotor de paz, est\u00e1 convencido de que quienes est\u00e1n hoy sentados en la mesa con el gobierno puedan tener \u00e9xito donde las generaciones que los antecedieron fallaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre todo, espera que su vida sea un mensaje para otras personas, que como \u00e9l participaron de la guerra urbana en Medell\u00edn:&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAl menos yo soy un buen referente de vida para los jefes de las bandas de hoy d\u00eda, que saben que yo tambi\u00e9n podr\u00eda ser jefe y que decid\u00ed m\u00e1s bien andar tranquilo y andar en paz. Porque estoy en un proceso de paz que me creo y del que hablo con orgullo\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Henry Holgu\u00edn se asom\u00f3 por el balc\u00f3n del segundo piso vac\u00edo de un peque\u00f1o restaurante en La Bayadera, un concurrido barrio industrial de Medell\u00edn. \u201cEsto fue una zona roja, brava\u2026 [&hellip;]<\/p>\n","protected":false},"author":203,"featured_media":231173,"parent":18362,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"single-feature.php","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"newspack_content_restriction_is_exempt":false,"newspack_featured_image_position":"hidden","newspack_hide_page_title":true,"newspack_show_share_buttons":false,"footnotes":""},"categories":[342],"tags":[368,452,4387,438],"newspack_spnsrs_tax":[],"coauthors":[4249,4155],"class_list":["post-236249","page","type-page","status-publish","has-post-thumbnail","hentry","category-investigaciones","tag-colombia-pais","tag-homicidios","tag-paz-colombia","tag-politicas-de-seguridad","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/investigaciones\/un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Un antiguo sicario de Escobar sigue el camino de la &#8216;Paz Total&#8217; en Medell\u00edn, Colombia","url":"http:\/\/insightcrime.org\/es\/investigaciones\/un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/investigaciones\/un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing.jpg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-Paz-Total-Landing.jpg?fit=1600%2C768&quality=100&ssl=1"},"articleSection":"Investigaciones","author":[{"@type":"Person","name":"Sara Garcia"},{"@type":"Person","name":"Douwe den Held"}],"creator":["Sara Garcia","Douwe den Held"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["colombia","homicidios","paz colombia","pol\u00edticas de seguridad"],"dateCreated":"2023-09-13T14:36:00Z","datePublished":"2023-09-13T14:36:00Z","dateModified":"2023-11-27T22:13:30Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"WebPage\",\"headline\":\"Un antiguo sicario de Escobar sigue el camino de la &#8216;Paz Total&#8217; en Medell\\u00edn, Colombia\",\"url\":\"http:\\\/\\\/insightcrime.org\\\/es\\\/investigaciones\\\/un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/insightcrime.org\\\/es\\\/investigaciones\\\/un-antiguo-sicario-de-escobar-sigue-el-camino-de-la-paz-total-en-medellin-colombia\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/insightcrime.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Cover-Paz-Total-Landing.jpg?resize=150%2C150&quality=100&ssl=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/insightcrime.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Cover-Paz-Total-Landing.jpg?fit=1600%2C768&quality=100&ssl=1\"},\"articleSection\":\"Investigaciones\",\"author\":[{\"@type\":\"Person\",\"name\":\"Sara Garcia\"},{\"@type\":\"Person\",\"name\":\"Douwe den Held\"}],\"creator\":[\"Sara Garcia\",\"Douwe den Held\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"InSight Crime\",\"logo\":\"https:\\\/\\\/insightcrime.org\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo.png\"},\"keywords\":[\"colombia\",\"homicidios\",\"paz colombia\",\"pol\\u00edticas de seguridad\"],\"dateCreated\":\"2023-09-13T14:36:00Z\",\"datePublished\":\"2023-09-13T14:36:00Z\",\"dateModified\":\"2023-11-27T22:13:30Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":322275,"url":"https:\/\/insightcrime.org\/es\/noticias\/on-the-radar-colombia-rechaza-los-acercamientos-de-paz-del-tren-de-aragua\/","url_meta":{"origin":236249,"position":0},"title":"On the Radar: Colombia rechaza los acercamientos de paz del Tren de Aragua","author":"Deborah Bonello","date":"17 de octubre de 2025","format":false,"excerpt":"Esta semana analizamos una masiva fuga carcelaria en Guatemala y el rechazo del gobierno de Colombia a una propuesta de paz del Tren de Aragua.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/10\/25-10-16.png?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/10\/25-10-16.png?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/10\/25-10-16.png?fit=1200%2C675&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/10\/25-10-16.png?fit=1200%2C675&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/10\/25-10-16.png?fit=1200%2C675&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":197080,"url":"https:\/\/insightcrime.org\/es\/noticias\/puede-gustavo-petro-superar-desafio-paz-total-colombia\/","url_meta":{"origin":236249,"position":1},"title":"\u00bfPuede Gustavo Petro superar el violento desaf\u00edo de la &#8216;paz total&#8217; en Colombia?","author":"Sara Garcia","date":"6 de septiembre de 2022","format":false,"excerpt":"El proyecto de paz del reci\u00e9n posesionado presidente de Colombia; amenazado por ataque en el sur de pa\u00eds.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Colombia President Gustavo Petro","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/09\/gustavo-petro-2.jpeg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":189063,"url":"https:\/\/insightcrime.org\/es\/noticias\/eln-colombia-proceso-paz-bajo-propias-condiciones\/","url_meta":{"origin":236249,"position":2},"title":"El ELN en Colombia: un proceso de paz bajo sus propias condiciones","author":"Juan Diego Posada","date":"22 de junio de 2022","format":false,"excerpt":"Uno de los grupos criminales m\u00e1s poderosos de Colombia, el ELN, abre las puertas hacia un proceso de paz luego de las elecciones presidenciales en Colombia. No obstante, su propuesta tambi\u00e9n trae exigencias.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Funcionarios del gobierno Santos y miembros de la guerrilla del ELN en conversaciones","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/06\/Proceso-de-paz-ELN-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":197776,"url":"https:\/\/insightcrime.org\/es\/noticias\/arriesgada-apuesta-colombia-paz-total\/","url_meta":{"origin":236249,"position":3},"title":"La arriesgada apuesta de Colombia por la &#8216;Paz Total&#8217;","author":"Juan Diego Posada","date":"13 de septiembre de 2022","format":false,"excerpt":"La propuesta del presidente Gustavo Petro de \"Paz Total\" muestra c\u00f3mo el nuevo gobierno busca desmovilizar los grupos criminales, pero podr\u00eda estar olvidando los escenarios alternos del proyecto.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"President Gustavo Petro of Colombia raises a fist in celebration","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/09\/Colombia-President-Gustavo-Petro-raises-his-fist-at-the-end-of-his-inauguration-speech-Aug-2022-AP_22220013460170-A2.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/09\/Colombia-President-Gustavo-Petro-raises-his-fist-at-the-end-of-his-inauguration-speech-Aug-2022-AP_22220013460170-A2.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/09\/Colombia-President-Gustavo-Petro-raises-his-fist-at-the-end-of-his-inauguration-speech-Aug-2022-AP_22220013460170-A2.jpg?fit=1200%2C690&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/09\/Colombia-President-Gustavo-Petro-raises-his-fist-at-the-end-of-his-inauguration-speech-Aug-2022-AP_22220013460170-A2.jpg?fit=1200%2C690&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/09\/Colombia-President-Gustavo-Petro-raises-his-fist-at-the-end-of-his-inauguration-speech-Aug-2022-AP_22220013460170-A2.jpg?fit=1200%2C690&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":321621,"url":"https:\/\/insightcrime.org\/es\/noticias\/on-the-radar-la-declaracion-de-el-mayo-no-cambiara-nada\/","url_meta":{"origin":236249,"position":4},"title":"On the Radar: La declaraci\u00f3n de El Mayo no cambiar\u00e1 nada","author":"Deborah Bonello","date":"28 de agosto de 2025","format":false,"excerpt":"https:\/\/www.youtube.com\/shorts\/lg1ASzaZ1us Esta semana, Ismael Zambada Garc\u00eda, alias \u201cEl Mayo\u201d, uno de los fundadores del Cartel de Sinaloa, se declar\u00f3 culpable de cargos por tr\u00e1fico de drogas en Estados Unidos. Guyana y Trinidad y Tobago expresaron su apoyo al despliegue militar de Estados Unidos en el Caribe. Y en Colombia, Y\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/08\/25-08-28.png?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/08\/25-08-28.png?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/08\/25-08-28.png?fit=1200%2C675&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/08\/25-08-28.png?fit=1200%2C675&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/08\/25-08-28.png?fit=1200%2C675&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":206194,"url":"https:\/\/insightcrime.org\/es\/noticias\/gamechangers-2022-paz-total-desarmar-grupos-criminales-colombia\/","url_meta":{"origin":236249,"position":5},"title":"GameChangers 2022: \u00bfPodr\u00e1 la &#8216;Paz Total&#8217; desarmar a los grupos criminales en Colombia?","author":"Juan Diego Posada","date":"28 de diciembre de 2022","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, es ciertamente ambicioso. Pero su plan de Paz Total enfrenta un camino dif\u00edcil por delante.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/5.-Colombia-President-Gustavo-Petro-waits-to-give-a-press-conference-Nov-2022-AP22319620199511.jpg?fit=1200%2C450&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/5.-Colombia-President-Gustavo-Petro-waits-to-give-a-press-conference-Nov-2022-AP22319620199511.jpg?fit=1200%2C450&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/5.-Colombia-President-Gustavo-Petro-waits-to-give-a-press-conference-Nov-2022-AP22319620199511.jpg?fit=1200%2C450&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/5.-Colombia-President-Gustavo-Petro-waits-to-give-a-press-conference-Nov-2022-AP22319620199511.jpg?fit=1200%2C450&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/5.-Colombia-President-Gustavo-Petro-waits-to-give-a-press-conference-Nov-2022-AP22319620199511.jpg?fit=1200%2C450&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/pages\/236249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/203"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=236249"}],"version-history":[{"count":6,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/pages\/236249\/revisions"}],"predecessor-version":[{"id":247830,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/pages\/236249\/revisions\/247830"}],"up":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/pages\/18362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/231173"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=236249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=236249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=236249"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=236249"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=236249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}