{"id":205515,"date":"2022-12-27T06:12:28","date_gmt":"2022-12-27T11:12:28","guid":{"rendered":"https:\/\/insightcrime.org\/?p=205515"},"modified":"2025-08-18T19:07:52","modified_gmt":"2025-08-19T00:07:52","slug":"gamechangers-2022-maduro-se-erige-como-el-poder-en-la-sombra-del-hampa-en-venezuela","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/noticias\/gamechangers-2022-maduro-se-erige-como-el-poder-en-la-sombra-del-hampa-en-venezuela\/","title":{"rendered":"GameChangers 2022: Maduro se erige como el poder en la sombra del hampa en Venezuela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante a\u00f1os, el presidente de Venezuela, Nicol\u00e1s Maduro, estuvo en riesgo de perder el poder, dado que las constantes crisis que enfrentaba su gobierno dieron lugar a levantamientos populares, intentos de golpe de Estado y la condena de la comunidad internacional, que lo consideraba una verdadera dictadura. Pero tras sobrevivir a todos los intentos de derrocarlo, Maduro estuvo todo el a\u00f1o pasado afianzando su control del poder en Venezuela, no solo pol\u00edticamente, sino adem\u00e1s poniendo orden en el caos del hampa que \u00e9l mismo permiti\u00f3 prosperar durante los a\u00f1os de crisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAhora que Maduro ha derrotado a la oposici\u00f3n y se siente fuerte, parece que quiere poner todo en orden, enviar el mensaje de que las cosas se hacen cuando \u00e9l las tolera y est\u00e1n bajo su control, o de lo contrario no se hacen\u201d, afirma el polit\u00f3logo Benigno Alarc\u00f3n, director del Centro de Estudios Pol\u00edticos de la Universidad Andr\u00e9s Bello en Caracas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-crisis-y-clientelismo\">Crisis y clientelismo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La corrupci\u00f3n, los grupos armados y las econom\u00edas criminales le ayudaron a Maduro a sobrevivir a una serie de crisis, que comenzaron con el colapso econ\u00f3mico el a\u00f1o despu\u00e9s de que asumiera el poder en 2013.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando las protestas masivas inundaron las calles, se desplegaron grupos militantes armados, conocidos como <em><a href=\"https:\/\/www.hrw.org\/news\/2017\/11\/29\/venezuela-systematic-abuses-opponents\" target=\"_blank\" rel=\"noreferrer noopener\">colectivos<\/a><\/em>, para reprimir las protestas de manera violenta. Cuando el sector petrolero colaps\u00f3, Maduro <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/el-dorado-maduro-bandas-guerrillas-oro-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">recurri\u00f3 al comercio ilegal de oro<\/a> para llenar el vac\u00edo presupuestario. Y cuando el Estado se qued\u00f3 sin dinero para pagarles a las fuerzas de seguridad, <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/desafio-cocaina-maduro\/\" target=\"_blank\" rel=\"noreferrer noopener\">a los militares se les permiti\u00f3 tomar una tajada<\/a> de las ganancias del tr\u00e1fico de drogas, el contrabando y otras econom\u00edas criminales para mantenerlos leales al r\u00e9gimen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/revolucion-cocaina-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">La revoluci\u00f3n de la coca\u00edna en Venezuela<\/a><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Naci\u00f3 entonces un sistema clientelista, mediante el cual Maduro mantuvo de su lado a los miembros del ej\u00e9rcito y al Partido Socialista Unido de Venezuela (PSUV), ofreciendo oportunidades de acceso a la corrupci\u00f3n, a las econom\u00edas criminales, y al control de territorios donde pod\u00edan enriquecerse asoci\u00e1ndose con los grupos criminales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero si bien dicho sistema ayud\u00f3 a mantener a Maduro en el poder, se volvi\u00f3 ca\u00f3tico y se sali\u00f3 de su control.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLleg\u00f3 un momento en que [los pol\u00edticos y los militares] comenzaron a generar recursos para ellos mismos y a manejar las cosas sin ning\u00fan tipo de control\u201d, se\u00f1ala Alarc\u00f3n. \u201c[Y] los grupos armados se convirtieron en los due\u00f1os y se\u00f1ores de sus territorios\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero los tiempos han cambiado. La econom\u00eda <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-06-30\/venezuela-economy-seen-growing-most-in-15-years-as-oil-flows#xj4y7vzkg\" target=\"_blank\" rel=\"noreferrer noopener\">se ha estabilizado<\/a>, las protestas se han apaciguado, la oposici\u00f3n pol\u00edtica <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/11\/17\/elecciones-venezuela-oposicion-dividida-21-de-noviembre-orix\/\" target=\"_blank\" rel=\"noreferrer noopener\">es d\u00e9bil y se encuentra dividida<\/a>, y Venezuela est\u00e1 <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-08-29\/venezuela-and-colombia-to-restart-relations-ending-impasse#xj4y7vzkg\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">reingresando<\/a><a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-08-29\/venezuela-and-colombia-to-restart-relations-ending-impasse#xj4y7vzkg\" target=\"_blank\" rel=\"noreferrer noopener\"> <\/a><a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-08-29\/venezuela-and-colombia-to-restart-relations-ending-impasse#xj4y7vzkg\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">lentamente a la comunidad internacional<\/a>. Esto le ha permitido a Maduro comenzar a recuperar el control.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Limpieza de imagen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o 2022 comenz\u00f3 con una declaraci\u00f3n de intenciones del gobierno de Maduro. El 28 de enero, el superintendente nacional antidrogas, Richard L\u00f3pez Vargas, public\u00f3 <a href=\"https:\/\/www.sunad.gob.ve\/duro-golpe-al-trafico-ilicito-de-drogas-con-la-operacion-mano-dura-de-hierro\/\" target=\"_blank\" rel=\"noreferrer noopener\">un comunicado oficial<\/a> en su cuenta de Twitter, en la que informaba sobre el \u00e9xito de una nueva operaci\u00f3n, Mano de Hierro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El comunicado se\u00f1alaba que las autoridades hab\u00edan detenido a tres presuntos narcotraficantes y, lo que es m\u00e1s inusual, a sus presuntos colaboradores pol\u00edticos: un alcalde municipal del estado de Zulia y dos representantes de la Asamblea Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La declaraci\u00f3n conclu\u00eda con la promesa de erradicar la corrupci\u00f3n y con la frase que se convertir\u00eda en el lema oficial de la operaci\u00f3n: \u201cCaiga quien caiga\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichos arrestos fueron los primeros de <a href=\"https:\/\/www.infobae.com\/america\/venezuela\/2022\/02\/07\/la-feroz-guerra-interna-por-el-poder-en-el-chavismo-detras-del-encarcelamiento-de-alcaldes-diputados-y-militares\/\" target=\"_blank\" rel=\"noreferrer noopener\">una serie de operaciones<\/a> dirigidas contra funcionarios estatales presuntamente corruptos. Durante los meses que siguieron, fueron arrestados miembros de alto y bajo rango de las instituciones militares, <a href=\"https:\/\/elpitazo.net\/sucesos\/bolivar-dgcim-captura-a-cuatro-altos-jefes-policiales-durante-operacion-mano-de-hierro\/\" target=\"_blank\" rel=\"noreferrer noopener\">policiales<\/a> y <a href=\"https:\/\/supremainjusticia.org\/operativo-mano-hierro-altos-funcionarios-detenidos-narcotrafico-contrabando-gasolina-corrupcion\/\" target=\"_blank\" rel=\"noreferrer noopener\">judiciales<\/a>, as\u00ed como <a href=\"https:\/\/twitter.com\/luchaalmada\/status\/1487467566973042692\" target=\"_blank\" rel=\"noreferrer noopener\">l\u00edderes pol\u00edticos<\/a> y funcionarios de empresas estatales, acusados de cargos como contrabando de combustible, tr\u00e1fico de mercurio, extorsi\u00f3n y aceptaci\u00f3n de sobornos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En abril, Maduro dej\u00f3 claro el mensaje detr\u00e1s de la campa\u00f1a: \u201c\u00a1Vamos a ir con mano de hierro contra todas las mafias, se disfracen como se disfracen!\u201d, <a href=\"https:\/\/twitter.com\/VTVcanal8\/status\/1518007204447760481\" target=\"_blank\" rel=\"noreferrer noopener\">dijo<\/a> ante los asistentes al congreso del PSUV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, la proclamaci\u00f3n de Maduro sonaba vac\u00eda. La corrupci\u00f3n desenfrenada y los v\u00ednculos que muchas de las figuras pol\u00edticas y militares m\u00e1s importantes del pa\u00eds mantienen con la criminalidad son un secreto a voces en Venezuela y <a href=\"https:\/\/crsreports.congress.gov\/product\/pdf\/IF\/IF10715\" target=\"_blank\" rel=\"noreferrer noopener\">blanco de numerosas sanciones<\/a> y <a href=\"https:\/\/www.justice.gov\/opa\/page\/file\/1261806\/download\" target=\"_blank\" rel=\"noreferrer noopener\">acusaciones<\/a> en el extranjero. Y, sin embargo, ninguna de las operaciones toc\u00f3 a dichas figuras, lo que llev\u00f3 a preguntarse sobre lo que hab\u00eda realmente detr\u00e1s de la Mano de Hierro de Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los diversos pol\u00edticos y analistas pol\u00edticos consultados por InSight Crime, hay varias respuestas posibles para esa pregunta, pero todas apuntan en la misma direcci\u00f3n: Maduro est\u00e1 consolidando su poder al dejar claro qui\u00e9n puede beneficiarse de los esquemas de corrupci\u00f3n y las econom\u00edas criminales y qui\u00e9n no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMaduro ha utilizado la mano de hierro como una herramienta para reposicionar algunos de los sectores que hab\u00edan escapado de su control y no representaban sus intereses\u201d, afirma un disidente chavista, exrepresentante de la Asamblea Nacional, quien pidi\u00f3 el anonimato por temor a persecuciones pol\u00edticas. \u201cY est\u00e1 usando la mano de hierro como un medio para controlar las distintas facciones que existen dentro del sistema [pol\u00edtico chavista]\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es probable que Maduro tambi\u00e9n pretenda combatir la percepci\u00f3n p\u00fablica de corrupci\u00f3n rampante, como afirma Pablo Andr\u00e9s Quintero, polit\u00f3logo y consultor que reside en Caracas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTambi\u00e9n tenemos que recordar que en 2024 habr\u00e1 elecciones presidenciales y el gobierno necesita limpiar su imagen. Va a haber cierta creaci\u00f3n de marca pol\u00edtica para eliminar de la opini\u00f3n p\u00fablica la idea de que el gobierno es corrupto\u201d, se\u00f1ala Quintero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La creaci\u00f3n de marca pol\u00edtica de Maduro se ha extendido al escenario internacional, donde \u00e9l ha intentado rebatir las acusaciones de complicidad de su r\u00e9gimen <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/revolucion-cocaina-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">con el narcotr\u00e1fico<\/a>, <a href=\"https:\/\/www.sunad.gob.ve\/desde-hace-16-anos-venezuela-es-territorio-libre-de-drogas\/\" target=\"_blank\" rel=\"noreferrer noopener\">promulgando el aumento de las incautaciones de drogas<\/a> y <a href=\"https:\/\/www.vtv.gob.ve\/maduro-balance-escudo-tancol\/\" target=\"_blank\" rel=\"noreferrer noopener\">declarando vehementemente<\/a> que \u201cexterminar\u00e1\u201d a los grupos narcotraficantes colombianos en Venezuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el patr\u00f3n de operaciones antinarc\u00f3ticos indica la existencia de una din\u00e1mica mucho m\u00e1s compleja, donde el objetivo final de Maduro no es erradicar el tr\u00e1fico por completo, sino controlar <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/desafio-cocaina-maduro\/\" target=\"_blank\" rel=\"noreferrer noopener\">qui\u00e9n puede mover drogas<\/a> y d\u00f3nde puede hacerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan cifras <a href=\"https:\/\/www.sunad.gob.ve\/mas-de-41-mil-kilos-de-drogas-incautadas-y-8-mil-detenidos-en-el-ano-202\/\" target=\"_blank\" rel=\"noreferrer noopener\">entregadas<\/a> por las autoridades antinarc\u00f3ticos el 3 de diciembre, las fuerzas de seguridad hab\u00edan incautado 41,6 toneladas m\u00e9tricas de drogas hasta ese punto en 2022. Pero las incautaciones estuvieron distribuidas de manera desigual y no se correspond\u00edan con las rutas de tr\u00e1fico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1710\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?resize=1300%2C1710&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-207303\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?w=1300&amp;quality=100&amp;ssl=1 1300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?resize=228%2C300&amp;quality=100&amp;ssl=1 228w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?resize=778%2C1024&amp;quality=100&amp;ssl=1 778w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?resize=768%2C1010&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?resize=1168%2C1536&amp;quality=100&amp;ssl=1 1168w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?resize=170%2C223&amp;quality=100&amp;ssl=1 170w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-10.png?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las drogas fluyen por la frontera de Venezuela con Colombia, se mueven a lo largo de un laberinto de rutas de tr\u00e1nsito interno y salen por v\u00edas fluviales, a\u00e9reas y terrestres desde sitios ubicados en todo el pa\u00eds. Pero aproximadamente el 80% del total incautado se produjo en solo dos estados: el estado de Zulia, fronterizo con Colombia, que represent\u00f3 alrededor del 70% de las incautaciones, y el estado de Falc\u00f3n, ubicado en la costa Caribe, donde, <a href=\"https:\/\/www.sunad.gob.ve\/fanb-retiene-penero-con-casi-3-toneladas-de-marihuana-en-el-estado-falcon\/\">seg\u00fan cifras oficiales<\/a>, se han producido alrededor del 11% de las incautaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos estados albergan grupos narcotraficantes que anteriormente disfrutaron de la protecci\u00f3n de elementos del Estado venezolano, pero que recientemente se han convertido en sus objetivos: <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/venezuela-cementerio-exfarc-mafia\/\" target=\"_blank\" rel=\"noreferrer noopener\">las Ex-FARC Mafia en Zulia<\/a> y el <a href=\"https:\/\/es.insightcrime.org\/noticias\/captura-narcotraficante-venezuela-vacio-poder-costa-norte\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cartel de Paraguan\u00e1 en Falc\u00f3n<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falc\u00f3n, en particular, era un para\u00edso para los traficantes, y all\u00ed, <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/cartel-paraguana-narcotrafico-poder-politico-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">como InSight Crime inform\u00f3 anteriormente<\/a>, el Cartel de Paraguan\u00e1, pol\u00edticamente conectado, operaba en connivencia con las fuerzas de seguridad. Ahora, sin embargo, se les ha ordenado a las fuerzas de seguridad que arremetan contra el tr\u00e1fico, seg\u00fan le dijo a InSight Crime un funcionario de la Guardia Nacional recientemente desplegado all\u00ed. Y las \u00f3rdenes, creen los funcionarios, vienen directamente de arriba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos que estamos aqu\u00ed estamos buscando cualquier cantidad de droga para poder posicionarnos con el presidente, tenemos que mostrar resultados de alguna manera, demostrar que hemos logrado algo, aunque sea un poco\u201d, dijo el funcionario, quien habl\u00f3 con InSight Crime bajo condici\u00f3n de anonimato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay muchos pol\u00edticos y oficiales militares involucrados en el tr\u00e1fico de drogas, chatarra y combustible. Pero tambi\u00e9n hay un grupo que est\u00e1 tratando de descubrirlos para congraciarse con Maduro\u201d, agreg\u00f3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La verdadera Mano de Hierro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la ret\u00f3rica de Maduro de que con su mano de hierro aplastar\u00e1 a la corrupci\u00f3n, las verdaderas fuerzas del Estado se han desplegado hacia otros lados: contra los grupos criminales y armados que antes operaban en Venezuela con impunidad y, en algunos casos, con <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/rebeldes-paramilitares-guerrilla-colombiana-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">la anuencia<\/a> del r\u00e9gimen. Los resultados han mostrado la voluntad de Maduro de usar la violencia para lograr sus objetivos, pero tambi\u00e9n las limitaciones de sus fuerzas de seguridad, as\u00ed como las complejidades de manejar las relaciones del Estado con los actores criminales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el estado Apure, en la frontera con Colombia, el ej\u00e9rcito venezolano continu\u00f3 su campa\u00f1a contra el Frente 10 de las Ex-FARC Mafia, un grupo guerrillero disidente que anteriormente estuvo aliado con el Estado venezolano, pero que ha sido <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/batalla-apure-chavismo-ex-farc\/\" target=\"_blank\" rel=\"noreferrer noopener\">un objetivo militar importante desde principios de 2021<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, la intervenci\u00f3n decisiva en el conflicto no provino de las fuerzas de seguridad venezolanas, sino del Ej\u00e9rcito de Liberaci\u00f3n Nacional (<a href=\"https:\/\/es.insightcrime.org\/tag\/el-eln\/\" target=\"_blank\" rel=\"noreferrer noopener\">ELN<\/a>), que anunci\u00f3 que se hab\u00eda unido a la lucha contra las ex-FARC, tras <a href=\"https:\/\/www.elespectador.com\/judicial\/no-hubo-combate-fiscalia-elevo-a-27-los-muertos-en-arauca-y-dio-nueva-hipotesis\/\" target=\"_blank\" rel=\"noreferrer noopener\">la masacre<\/a>, a comienzos de a\u00f1o, de presuntos colaboradores del Frente 10 en el vecino departamento de Arauca, Colombia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ELN se coordin\u00f3 con el ej\u00e9rcito venezolano, incluso llevando a cabo operaciones conjuntas, seg\u00fan <a href=\"https:\/\/www.hrw.org\/es\/news\/2022\/03\/28\/colombia\/venezuela-abusos-de-grupos-armados-en-zona-fronteriza\" target=\"_blank\" rel=\"noreferrer noopener\">un informe de Human Rights Watch<\/a> y fuentes de InSight Crime en la regi\u00f3n fronteriza. En cuesti\u00f3n de meses pudieron hacer lo que los militares venezolanos por s\u00ed solos no pudieron en un a\u00f1o de campa\u00f1as militares, y <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/venezuela-cementerio-exfarc-mafia\/\" target=\"_blank\" rel=\"noreferrer noopener\">expulsaron al Frente 10 del pa\u00eds<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La derrota militar del Frente 10 y el debilitamiento de la red disidente a la que este pertenec\u00eda tanto en Colombia como en Venezuela ha dejado el control de la frontera en manos de guerrilleros que tienen <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/rebeldes-paramilitares-guerrilla-colombiana-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">estrechos v\u00ednculos<\/a> con el Estado venezolano, el ELN y el Frente Acacio Medina de las ex-FARC en Amazonas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl hecho de que hayan desplazado al Frente 10 de la frontera venezolana ha llevado a que otros grupos tomen el control de la zona, y estos son grupos que se coordinan con el gobierno y las fuerzas armadas venezolanas\u201d, afirma un l\u00edder social de Apure que pertenece a un movimiento pol\u00edtico que ha tenido v\u00ednculos con grupos guerrilleros y el chavismo, quien pidi\u00f3 el anonimato por razones de seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el hecho de que la guerrilla haya podido hacer lo que los militares no pudieron lograr plantea interrogantes sobre d\u00f3nde reside ahora el poder en su relaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVenezuela, en el caso de Apure, se est\u00e1 convirtiendo en un territorio donde la frontera no est\u00e1 controlada por el Ej\u00e9rcito venezolano o la Guardia Nacional sino por grupos irregulares colombianos\u201d, afirma el l\u00edder social. \u201cEl gobierno venezolano habla de soberan\u00eda, pero est\u00e1 permitiendo que estos grupos operen en nuestro territorio, est\u00e1 entregando la soberan\u00eda de nuestro pa\u00eds\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el a\u00f1o tambi\u00e9n hubo <a href=\"https:\/\/www.instagram.com\/p\/CkTjwtmuIpz\/\" target=\"_blank\" rel=\"noreferrer noopener\">nuevas operaciones militares<\/a> en otro estado clave, donde Maduro ha estado intentando poner orden en el caos criminal: en Bol\u00edvar, centro de la miner\u00eda de oro. Obtener la riqueza mineral de Bol\u00edvar para sus aliados pol\u00edticos y para las arcas estatales <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/gobernadores-bandas-guerra-por-oro-bolivar\/\" target=\"_blank\" rel=\"noreferrer noopener\">ha sido durante mucho tiempo una prioridad de Maduro<\/a>, pero, dado que el comercio de oro se encuentra en manos de grupos armados conocidos como <em>sindicatos<\/em>, <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/venezuela-gold-3-rebelde-sur-ascenso-organizacion-r\/\" target=\"_blank\" rel=\"noreferrer noopener\">no ha obtenido grandes logros<\/a> contra dichos grupos, profundamente arraigados y fuertemente armados, con influencia financiera y social.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1214\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?resize=1500%2C1214&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-207305\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?w=1500&amp;quality=100&amp;ssl=1 1500w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?resize=300%2C243&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?resize=1024%2C829&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?resize=768%2C622&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?resize=276%2C223&amp;quality=100&amp;ssl=1 276w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/image-11.png?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes locales en zonas mineras que son objeto de disputas afirman que esta vez las fuerzas de seguridad no solo se enfrentan a sindicatos no alineados como la Organizaci\u00f3n R (OR) y El Per\u00fa, sino que tambi\u00e9n est\u00e1n atacando a las propias minas, as\u00ed como a los mineros que trabajan en ellas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos militares se est\u00e1n apoderando de las minas y est\u00e1n yendo tras los principales cabecillas\u201d, dijo un minero en el municipio de El Callao, quien pidi\u00f3 el anonimato por razones de seguridad. \u201cNos est\u00e1n sacando de todas las minas\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mano dura con la pol\u00edtica criminal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno de Maduro tambi\u00e9n est\u00e1 intentando mejorar su imagen con respecto al crimen y la seguridad ante los venezolanos, en el periodo previo a las elecciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o pasado se produjo una serie de operaciones de seguridad a gran escala en \u00e1reas donde el control criminal est\u00e1 afectando la econom\u00eda legal y las percepciones de inseguridad, que quiz\u00e1 sean las principales preocupaciones de muchos electores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estados como <a href=\"https:\/\/elpitazo.net\/sucesos\/guarico-l-autoridades-lideran-operativo-para-atrapar-a-integrantes-de-la-banda-carlos-pirela\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gu\u00e1rico<\/a>, <a href=\"https:\/\/primicia.com.ve\/sucesos\/detenido-garitero-del-tren-de-aragua-en-la-colonia-tovar\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aragua<\/a>, <a href=\"https:\/\/efectococuyo.com\/sucesos\/que-ocurre-en-los-valles-del-tuy-con-el-operativo-policial-que-ha-dejado-23-muertes-violentas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Miranda<\/a> y <a href=\"https:\/\/globovision.com\/article\/fanb-activa-operativo-especial-liberacion-de-la-costa-oriental-del-lago-con-360-funcionarios\" target=\"_blank\" rel=\"noreferrer noopener\">Zulia<\/a>, as\u00ed como en el <a href=\"https:\/\/elpitazo.net\/sucesos\/petare-enfrentamientos-con-la-pnb-dejaron-11-muertos-en-jose-felix-ribas\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c1rea Metropolitana de Caracas<\/a>, se han desplegado cientos de funcionarios de seguridad con \u00f3rdenes de perseguir a las bandas dedicadas a la extorsi\u00f3n, el secuestro y el microtr\u00e1fico, como <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-venezuela\/tren-llano\/\" target=\"_blank\" rel=\"noreferrer noopener\">el Tren del Llano<\/a>, la banda de Carlos Capa y la banda de <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-venezuela\/wilexis-alexander-acevedo-monasterios-alias-wilexis\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wilexis<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las operaciones han sido muy agresivas, y los resultados reportados, seg\u00fan los cuales muchos presuntos criminales han sido asesinados o capturados, se han visto empa\u00f1ados por <a href=\"https:\/\/www.elnacional.com\/venezuela\/vienen-a-matar-denuncian-ejecuciones-extrajudiciales-por-parte-de-los-cuerpos-de-seguridad-en-guarico\/\" target=\"_blank\" rel=\"noreferrer noopener\">denuncias<\/a> de ejecuciones extrajudiciales, detenciones arbitrarias y abusos contra la poblaci\u00f3n civil.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/es.insightcrime.org\/investigaciones\/guerrillas-colombo-venezolanas-migracion-guerra-colombia-hacia-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">Las guerrillas colombo-venezolanas: la migraci\u00f3n de la guerra de Colombia hacia Venezuela<\/a><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Las agresivas t\u00e1cticas han producido resultados diversos. Mientras que algunas bandas, como <a href=\"https:\/\/elpitazo.net\/sucesos\/gn-mata-al-curi-lider-de-la-banda-que-opera-entre-sucre-y-monagas\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">la <\/a><a href=\"https:\/\/elpitazo.net\/sucesos\/gn-mata-al-curi-lider-de-la-banda-que-opera-entre-sucre-y-monagas\/\" target=\"_blank\" rel=\"noreferrer noopener\">de<\/a><a href=\"https:\/\/elpitazo.net\/sucesos\/gn-mata-al-curi-lider-de-la-banda-que-opera-entre-sucre-y-monagas\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> El Curi<\/a>, en el estado caribe\u00f1o de Monagas, al parecer han sido aniquiladas, en otros casos, como el del Tren del Llano, en Gu\u00e1rico, las operaciones para eliminar a los cabecillas de la banda <a href=\"https:\/\/ultimasnoticias.com.ve\/noticias\/sucesos\/detuvieron-a-16-de-tres-celulas-asociadas-al-tren-del-llano\/\" target=\"_blank\" rel=\"noreferrer noopener\">solo han producido fragmentaciones<\/a>, por los que las fuerzas de seguridad han quedado enfrentadas a varias c\u00e9lulas aut\u00f3nomas en lugar de una estructura unificada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros grupos, como la banda de Carlos Capa en Miranda y la banda Wilexis en las afueras de Caracas, han demostrado ser a\u00fan m\u00e1s resistentes, y las m\u00faltiples operaciones no han logrado reducir el control que dichos grupos tienen sobre las comunidades o amenazar a sus cabecillas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso el mayor \u00e9xito de Maduro hasta el momento, <a href=\"https:\/\/es.insightcrime.org\/noticias\/venezuela-si-tiene-intenciones-serias-de-acabar-con-el-koki\/\" target=\"_blank\" rel=\"noreferrer noopener\">expulsar de Caracas<\/a> al principal jefe criminal de Venezuela, Carlos Luis Revete, <a href=\"https:\/\/es.insightcrime.org\/noticias-crimen-organizado-venezuela\/carlos-luis-revete-alias-el-koki\/\" target=\"_blank\" rel=\"noreferrer noopener\">alias \u201cEl Koki\u201d<\/a>, y <a href=\"https:\/\/es.insightcrime.org\/noticias\/que-significa-la-muerte-del-koki-para-venezuela\/\" target=\"_blank\" rel=\"noreferrer noopener\">asesinarlo<\/a> mientras se encontraba oculto en las monta\u00f1as de Aragua, no ha llevado a mejoras sostenibles en la seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un a\u00f1o y medio despu\u00e9s de que El Koki huyera de Caracas, y casi un a\u00f1o despu\u00e9s de su muerte, el barrio Cota 905, que anteriormente estuvo sitiado por \u00e9l, contin\u00faa fuertemente militarizado dado que, tras una retirada previa, <a href=\"https:\/\/es.insightcrime.org\/noticias\/tras-muerte-koki-bandas-vuelven-agitar-cota-905-caracas\/\" target=\"_blank\" rel=\"noreferrer noopener\">las pandillas regresaron<\/a> poco despu\u00e9s al territorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los habitantes del barrio le dijeron a InSight Crime que actualmente hay puestos de control de la polic\u00eda y la Guardia Nacional casi cada 500 metros a lo largo de la principal arteria de transporte, y a\u00fan m\u00e1s en el interior del sector. Uno de los habitantes, que pidi\u00f3 el anonimato por razones de seguridad, dice que el barrio se ha militarizado tanto que, para los miembros de las bandas, \u201cser\u00eda un suicidio\u201d intentar retomar la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha presencia, sin embargo, representa un costo enorme para las fuerzas de seguridad. Y en dondequiera que se lleven a cabo estas operaciones se enfrentan dificultades similares para encontrar soluciones a largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstas pol\u00edticas de l\u00ednea dura no funcionan\u201d, afirma Jorge Govea Cabrera, director del Observatorio Venezolano de Violencia (OVV) en el estado Zulia, donde se han realizado m\u00faltiples megaoperaciones en el \u00faltimo a\u00f1o. \u201cNo es solo una cuesti\u00f3n de derechos humanos o moralidad, es solo que no funcionan. Los datos cuantitativos muestran que no hay un cambio significativo en la criminalidad. Puede haber una peque\u00f1a disminuci\u00f3n temporal en la criminalidad, pero luego aumenta r\u00e1pidamente porque los grupos se fracturan y se forman otros nuevos\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1434\" height=\"1406\" src=\"https:\/\/i0.wp.com\/es.insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?resize=1434%2C1406&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-208968\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?w=1434&amp;quality=100&amp;ssl=1 1434w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?resize=300%2C294&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?resize=1024%2C1004&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?resize=768%2C753&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?resize=227%2C223&amp;quality=100&amp;ssl=1 227w, https:\/\/i0.wp.com\/es.insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/es.insightcrime.org\/wp-content\/uploads\/2023\/01\/Venezuela_Presencia-de-grupos-guerrilleros-colombianos-en-Colombia-y-Venezuela-InSight-Crime-Mapa-Sept-2022.jpg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Hacia un nuevo clientelismo criminal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de los contratiempos, debilidades y contradicciones, las estrategias de seguridad de Maduro le han permitido ubicarse en una posici\u00f3n m\u00e1s fuerte que en cualquier otro momento desde que sucedi\u00f3 a Hugo Ch\u00e1vez como presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ch\u00e1vez logr\u00f3 mantenerse en el poder en Venezuela mediante la uni\u00f3n de fuerzas e intereses dispares a su alrededor, no solo con carisma sino adem\u00e1s con una astuta construcci\u00f3n de coaliciones. Maduro se est\u00e1 dirigiendo hacia los mismos niveles de autoridad personal, pero a trav\u00e9s de intrigas, corrupci\u00f3n y fuertes demostraciones de poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 avanzando en esta direcci\u00f3n en lo pol\u00edtico, lo econ\u00f3mico y lo criminal, ubic\u00e1ndose en el lugar donde se cruzan estos diferentes sectores y asegurando que ninguno de ellos pueda prosperar sin \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay mafias de intereses, de autoconservaci\u00f3n, de hegemon\u00eda y de extensi\u00f3n del poder, pero estas generan sus propias redes subordinadas, lo que complica las interconexiones de estos intereses\u201d, afirma el disidente chavista. \u201cMaduro est\u00e1 creando controles sobre estos subordinados que creen que tienen m\u00e1s autonom\u00eda de la que \u00e9l quiere otorgarles\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cosas est\u00e1n cambiando en Venezuela, y el pr\u00f3ximo a\u00f1o traer\u00e1 nuevos retos para Maduro en el pa\u00eds y en el extranjero, que van desde el comienzo de la campa\u00f1a presidencial hasta el papel de Venezuela como intermediario en las conversaciones de paz entre el aliado criminal de Maduro, el ELN, y el que \u00e9l espera que sea un aliado pol\u00edtico: el gobierno del presidente colombiano Gustavo Petro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo indica que se est\u00e1 preparando para estos retos reforzando su control personal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodav\u00eda est\u00e1 jugando el juego de la redistribuci\u00f3n del poder, pero es cada vez m\u00e1s hacia s\u00ed mismo\u201d, afirma el disidente. \u201cA veces cede, a veces impone. Todav\u00eda existen ciertas formulaciones pol\u00edticas que indican que no tiene hegemon\u00eda total, pero creo que est\u00e1 en camino de tener hegemon\u00eda total\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de unos a\u00f1os duros para el presidente venezolano Nicol\u00e1s Maduro, el 2022 fue el a\u00f1o para reforzar su poder en los \u00e1mbitos pol\u00edtico y criminal.<\/p>\n","protected":false},"author":775,"featured_media":206971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"above","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[759],"tags":[3387,534,455],"newspack_spnsrs_tax":[],"coauthors":[4646],"class_list":["post-205515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destacado","tag-gamechangers-es","tag-infografias","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/noticias\/gamechangers-2022-maduro-se-erige-como-el-poder-en-la-sombra-del-hampa-en-venezuela\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"GameChangers 2022: Maduro se erige como el poder en la sombra del hampa en Venezuela","url":"http:\/\/insightcrime.org\/es\/noticias\/gamechangers-2022-maduro-se-erige-como-el-poder-en-la-sombra-del-hampa-en-venezuela\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/noticias\/gamechangers-2022-maduro-se-erige-como-el-poder-en-la-sombra-del-hampa-en-venezuela\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/3.-Venezuela-President-Nicolas-Maduro-looks-out-a-window-as-he-waits-for-the-arrival-of-Guinea-Bissau-President-Umaro-Sissoco-Embalo-Nov-2022-AP22307846227349.jpg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/3.-Venezuela-President-Nicolas-Maduro-looks-out-a-window-as-he-waits-for-the-arrival-of-Guinea-Bissau-President-Umaro-Sissoco-Embalo-Nov-2022-AP22307846227349.jpg?fit=2000%2C750&quality=100&ssl=1"},"articleSection":"Noticias","author":[{"@type":"Person","name":"Unidad Investigativa de Venezuela"}],"creator":["Unidad Investigativa de Venezuela"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["destacado","gamechangers","infograf\u00edas"],"dateCreated":"2022-12-27T11:12:28Z","datePublished":"2022-12-27T11:12:28Z","dateModified":"2025-08-19T00:07:52Z"},"rendered":"<meta name=\"parsely-title\" content=\"GameChangers 2022: Maduro se erige como el poder en la sombra del hampa en Venezuela\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/noticias\/gamechangers-2022-maduro-se-erige-como-el-poder-en-la-sombra-del-hampa-en-venezuela\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/3.-Venezuela-President-Nicolas-Maduro-looks-out-a-window-as-he-waits-for-the-arrival-of-Guinea-Bissau-President-Umaro-Sissoco-Embalo-Nov-2022-AP22307846227349.jpg?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2022-12-27T11:12:28Z\" \/>\n<meta name=\"parsely-section\" content=\"Noticias\" \/>\n<meta name=\"parsely-tags\" content=\"destacado,gamechangers,infograf\u00edas\" \/>\n<meta name=\"parsely-author\" content=\"Unidad Investigativa de Venezuela\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":232558,"url":"https:\/\/insightcrime.org\/es\/investigaciones\/desafio-maduro-reformar-estado-hibrido-venezuela\/","url_meta":{"origin":205515,"position":0},"title":"El desaf\u00edo de Maduro: reformar el Estado h\u00edbrido de Venezuela","author":"Unidad Investigativa de Venezuela","date":"12 de julio de 2023","format":false,"excerpt":"La evoluci\u00f3n del Estado h\u00edbrido en Venezuela, que combina la gobernabilidad con la criminalidad, le ha permitido al presidente Nicol\u00e1s Maduro mantenerse en el poder, incluso a pesar de que su gobierno ha estado durante a\u00f1os luchando contra crisis casi constantes.","rel":"","context":"En \u00abInvestigaciones\u00bb","block_context":{"text":"Investigaciones","link":"https:\/\/insightcrime.org\/es\/category\/investigaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-C5-Venezuela-Hybrid-State-InSight-Crime-Jun-2023-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-C5-Venezuela-Hybrid-State-InSight-Crime-Jun-2023-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-C5-Venezuela-Hybrid-State-InSight-Crime-Jun-2023-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-C5-Venezuela-Hybrid-State-InSight-Crime-Jun-2023-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Cover-C5-Venezuela-Hybrid-State-InSight-Crime-Jun-2023-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":213026,"url":"https:\/\/insightcrime.org\/es\/noticias\/renuncia-ministro-petroleos-venezuela-prefigura-guerra-titanes\/","url_meta":{"origin":205515,"position":1},"title":"Renuncia de Ministro de Petr\u00f3leos de Venezuela prefigura guerra de titanes","author":"Unidad Investigativa de Venezuela","date":"22 de marzo de 2023","format":false,"excerpt":"La renuncia del ministro de petr\u00f3leos de Venezuela Tareck El Aissami, pocos d\u00edas despu\u00e9s de la captura de uno de sus principales aliados, puede ser una se\u00f1al de un distanciamiento pol\u00edtico entre algunas de las m\u00e1s poderosas redes criminales enquistadas en el gobierno.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Tareck El Aissami renuncia a como ministro de Petr\u00f3leo en Venezuela","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/03\/Tareck-el-Aissami-1-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":285956,"url":"https:\/\/insightcrime.org\/es\/noticias\/predicciones-panorama-criminal-tras-elecciones-venezuela\/","url_meta":{"origin":205515,"position":2},"title":"Predicciones del panorama criminal tras las elecciones en Venezuela","author":"Jeremy McDermott","date":"29 de julio de 2024","format":false,"excerpt":"Nicol\u00e1s Maduro se adjudic\u00f3 otros seis a\u00f1os en el poder tras unas disputadas elecciones, lo que provocar\u00e1 otra oleada migratoria y que Venezuela consolide su posici\u00f3n como centro del crimen organizado regional.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Nicol\u00e1s Maduro celebrates winning his third term as president of Venezuela. Nicol\u00e1s Maduro celebra haber ganado su tercer mandato como presidente de Venezuela.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/07\/Venezuela-Maduro-election-victory-elections-and-crime11.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":299940,"url":"https:\/\/insightcrime.org\/es\/noticias\/aumenta-presion-mundial-venezuela-recompensa-crimen\/","url_meta":{"origin":205515,"position":3},"title":"Aumenta la presi\u00f3n mundial sobre Venezuela: recompensas y crimen","author":"Jeremy McDermott","date":"16 de enero de 2025","format":false,"excerpt":"La presi\u00f3n internacional sobre el r\u00e9gimen de Venezuela, que incluye una recompensa de US$25 millones por la captura de Maduro, har\u00e1n que este depende a\u00fan m\u00e1s de las rentas criminales para mantenerse en el poder.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/01\/Wanted-Psters.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":246788,"url":"https:\/\/insightcrime.org\/es\/noticias\/termino-sistema-pranes-carceles-venezuela\/","url_meta":{"origin":205515,"position":4},"title":"\u00bfTermin\u00f3 el sistema de \u00abpranes\u00bb en las c\u00e1rceles de Venezuela?","author":"Unidad Investigativa de Venezuela","date":"15 de noviembre de 2023","format":false,"excerpt":"The system that delegated power in Venezuela\u2019s prisons to pranes, or criminal leaders, seems to be ending after a series of military takeovers of jails by President Nicol\u00e1s Maduro, as he eyes re-election in 2024. On the morning of November 10, security forces stormed\u00a0 the San Felipe Judicial Prison, known\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Presos venezolanos amotinados miran desde el tejado de un centro de detenci\u00f3n dirigido por la Polic\u00eda Nacional Bolivariana en Caracas, Venezuela.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Venezuela-Rioting-inmates-look-down-from-the-roof-of-a-detention-center-run-by-Venezuelas-Bolivarian-police-in-Caracas-27-April-2015-AP508909891865-Featured-1336x768-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Venezuela-Rioting-inmates-look-down-from-the-roof-of-a-detention-center-run-by-Venezuelas-Bolivarian-police-in-Caracas-27-April-2015-AP508909891865-Featured-1336x768-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Venezuela-Rioting-inmates-look-down-from-the-roof-of-a-detention-center-run-by-Venezuelas-Bolivarian-police-in-Caracas-27-April-2015-AP508909891865-Featured-1336x768-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Venezuela-Rioting-inmates-look-down-from-the-roof-of-a-detention-center-run-by-Venezuelas-Bolivarian-police-in-Caracas-27-April-2015-AP508909891865-Featured-1336x768-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Venezuela-Rioting-inmates-look-down-from-the-roof-of-a-detention-center-run-by-Venezuelas-Bolivarian-police-in-Caracas-27-April-2015-AP508909891865-Featured-1336x768-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":208098,"url":"https:\/\/insightcrime.org\/es\/noticias\/reforma-policial-venezuela-inutil-cortar-nexos-crimen-organizado\/","url_meta":{"origin":205515,"position":5},"title":"Reforma policial en Venezuela ser\u00eda in\u00fatil para cortar nexos con crimen organizado","author":"Unidad Investigativa de Venezuela","date":"18 de enero de 2023","format":false,"excerpt":"El presidente de Venezuela Nicol\u00e1s Maduro anunci\u00f3 planes de reformar la polic\u00eda del pa\u00eds, un anuncio que en la superficie podr\u00eda parecer un proyecto para un estado policial, pero de llegar a implementarse, seguramente no lograr\u00eda m\u00e1s que inundar las calles de polic\u00edas propensos a la corrupci\u00f3n que pueden ser\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Polic\u00edas de Venezuela listos para desplegarse","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/01\/policiavenezuelapazactiva-1-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/12\/3.-Venezuela-President-Nicolas-Maduro-looks-out-a-window-as-he-waits-for-the-arrival-of-Guinea-Bissau-President-Umaro-Sissoco-Embalo-Nov-2022-AP22307846227349.jpg?fit=2000%2C750&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/205515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/775"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=205515"}],"version-history":[{"count":25,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/205515\/revisions"}],"predecessor-version":[{"id":235569,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/205515\/revisions\/235569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/206971"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=205515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=205515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=205515"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=205515"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=205515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}