{"id":286989,"date":"2024-08-12T09:57:49","date_gmt":"2024-08-12T14:57:49","guid":{"rendered":"https:\/\/insightcrime.org\/?p=286989"},"modified":"2026-03-13T15:28:10","modified_gmt":"2026-03-13T20:28:10","slug":"circulo-intimo-marset-desmorona-traficante-uruguayo-elude-captura","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/news\/circulo-intimo-marset-desmorona-traficante-uruguayo-elude-captura\/","title":{"rendered":"El c\u00edrculo \u00edntimo de Marset se desmorona mientras el traficante uruguayo elude su captura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La pendiente extradici\u00f3n de otra presunta pieza clave en los planes de lavado de dinero de Sebasti\u00e1n Marset supone su \u00faltimo rev\u00e9s, mientras la red del narcotraficante parece desmoronarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Representantes de Paraguay, Bolivia y Espa\u00f1a se reunieron el 9 de agosto par discutir la extradici\u00f3n de Gianina Garc\u00eda Troche, compa\u00f1era sentimental y supuesta gestora de negocios del famoso narcotraficante Sebasti\u00e1n Marset, por el presunto lavado de millones de d\u00f3lares procedentes del narcotr\u00e1fico. Los pedidos de extradici\u00f3n de Paraguay y Bolivia se producen tras su <a href=\"https:\/\/www.elpais.com.uy\/mundo\/espana\/gianina-garcia-troche-quedo-bajo-arresto-administrativo-en-espana-a-espera-de-la-extradicion\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">detenci\u00f3n<\/a> el 17 de julio en el aeropuerto internacional de Madrid, cuando volaba desde Dubai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/insightcrime.org\/es\/noticias-crimen-organizado-bolivia\/sebastian-marset\/\" target=\"_blank\" rel=\"noreferrer noopener\">Marset<\/a> es un narcotraficante uruguayo buscado internacionalmente. Fue condenado por primera vez por tr\u00e1fico de marihuana en Uruguay en 2013 antes de migrar hacia el tr\u00e1fico de coca\u00edna, y est\u00e1 acusado de coordinar toneladas de env\u00edos de coca\u00edna desde Bolivia a Europa. Tambi\u00e9n es sospechoso de lavar millones de d\u00f3lares a trav\u00e9s de testaferros que van desde tiendas de coches de lujo a equipos de f\u00fatbol profesional.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/insightcrime.org\/es\/noticias\/persecucion-sebastian-marset-fundador-primer-cartel-uruguayo\/\" target=\"_blank\" rel=\"noreferrer noopener\">La persecuci\u00f3n de Sebasti\u00e1n Marset, fundador del Primer Cartel Uruguayo<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Garc\u00eda Troche, sobre quien reposa una circular roja de Interpol desde 2022, fue pedida por Paraguay por su presunto papel en el entramado criminal de Marset. La estructura est\u00e1 acusada de establecer m\u00faltiples frentes de lavado de dinero en Paraguay, pa\u00eds que desempe\u00f1a un <a href=\"https:\/\/insightcrime.org\/es\/noticias\/paraguay-eslabon-esencial-ruta-cocaina-bolivia-europa\/\" target=\"_blank\" rel=\"noreferrer noopener\">papel importante<\/a> en el transporte de coca\u00edna a Europa debido a su proximidad con pa\u00edses productores. Por el momento, no est\u00e1 claro si Garc\u00eda Troche se entreg\u00f3 a las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se la busca en Paraguay en el marco de la <a href=\"https:\/\/insightcrime.org\/es\/noticias\/gigantesca-operacion-antidrogas-arroja-luz-narcopolitica-paraguay\/\" target=\"_blank\" rel=\"noreferrer noopener\">Operaci\u00f3n A Ultraza Py<\/a>, la mayor y m\u00e1s exitosa campa\u00f1a contra el blanqueo de capitales y el tr\u00e1fico de coca\u00edna de la historia del pa\u00eds. Se la acusa de blanquear las ganancias de los negocios internacionales de Marset con la coca\u00edna. Bolivia, donde Garc\u00eda Troche vivi\u00f3 brevemente con Marset y sus hijos, tambi\u00e9n solicit\u00f3 su extradici\u00f3n por tr\u00e1fico de drogas, asociaci\u00f3n il\u00edcita y conspiraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras escapar de las autoridades bolivianas en julio de 2023, la familia desapareci\u00f3 del radar y la mayor\u00eda de los indicios apuntan a que Garc\u00eda Troche y sus hijos se trasladaron a Dubai. Hasta ahora, se desconoce el paradero del propio Marset.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cual-es-el-supuesto-papel-de-garcia-troche\"><strong>\u00bfCu\u00e1l es el supuesto papel de Garc\u00eda Troche?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con millones en transacciones de droga, Marset necesitaba una forma de lavar dinero, as\u00ed que recurri\u00f3 a amigos y familiares para montar negocios aparentemente leg\u00edtimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de esos negocios era Total Cars, una empresa de veh\u00edculos de alta gama que formaba parte del Grupo San Jorge S.A. El establecimiento, con sede en Asunci\u00f3n, Paraguay, se abri\u00f3 presuntamente para blanquear las ganancias del tr\u00e1fico de drogas de Marset. El montaje de Total Cars inclu\u00eda a varias personas ahora detenidas o buscadas en el marco de la Operaci\u00f3n A Ultranza Py. Entre ellas est\u00e1 <a href=\"https:\/\/insightcrime.org\/es\/noticias\/redes-narco-uruguay\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alberto Koube Ayala<\/a>, acusado de lavar dinero a trav\u00e9s de varios otros frentes, como <a href=\"https:\/\/www.contrataciones.gov.py\/proveedor\/grupo-tapyracuai-s-a.html\" target=\"_blank\" rel=\"noreferrer noopener\">Tapiracuai S.A<\/a>. Los tr\u00e1mites para constituir el Grupo San Jorge se hicieron en julio de 2021, y el 75% de las acciones y el papel de presidente recayeron en Garc\u00eda Troche, <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2024\/08\/ID1-273_1514709.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">seg\u00fan<\/a> los documentos judiciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cElla era la mano derecha de Marset, obviamente por confianza, por la cercan\u00eda y a su vez serv\u00eda de prestanombre para poder lavar dinero\u201d, dijo a InSight Crime Nicol\u00e1s Centuri\u00f3n, investigador sobre crimen en Uruguay y analista del Centro Latinoamericano de An\u00e1lisis Estrat\u00e9gico (CLAE).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/insightcrime.org\/es\/noticias\/redes-narco-uruguay\/\" target=\"_blank\" rel=\"noreferrer noopener\">Las redes del narco m\u00e1s buscado de Uruguay<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Garc\u00eda Troche tambi\u00e9n <a href=\"https:\/\/insightcrime.org\/es\/noticias\/redes-narco-uruguay\/\" target=\"_blank\" rel=\"noreferrer noopener\">trabajaba<\/a> como \u201cagente de transporte\u201d, depositando miles de d\u00f3lares mensuales en su cuenta bancaria. La documentaci\u00f3n para justificar estas transferencias result\u00f3 ser falsa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Marset, todas las operaciones comerciales de Garc\u00eda Troche son leg\u00edtimas y est\u00e1n completamente separadas de sus propios negocios turbios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo hay nadie de mi familia dentro y nunca pienso meter a mi familia\u201d, <a href=\"https:\/\/www.youtube.com\/watch?v=Bc2AKBaBvj8\" target=\"_blank\" rel=\"noreferrer noopener\">dijo<\/a> durante una entrevista en el programa Santo y Se\u00f1a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-los-amigos-de-marset-siguen-cayendo\"><strong>Los amigos de Marset siguen cayendo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El arresto de Garc\u00eda Troche es la m\u00e1s reciente de una serie de detenciones de presuntos actores clave cercanos a Marset, cuya red internacional parece estar deshaci\u00e9ndose.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras salir de prisi\u00f3n en su Uruguay natal, Marset <a href=\"https:\/\/insightcrime.org\/es\/noticias-crimen-organizado-bolivia\/sebastian-marset\/\" target=\"_blank\" rel=\"noreferrer noopener\">se traslad\u00f3<\/a> a Paraguay en torno a 2019 para levantar su imperio criminal. Pero no empez\u00f3 de cero. En su lugar, comenz\u00f3 a trabajar con clanes criminales establecidos con profundas conexiones pol\u00edticas, como el encabezado por Miguel \u00c1ngel Insfr\u00e1n Galeano, alias \u201cT\u00edo Rico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00edo Rico est\u00e1 acusado de dirigir la red de tr\u00e1fico de coca\u00edna y lavado de dinero junto con Marset. Los mensajes entre T\u00edo Rico y Marset interceptados por las autoridades paraguayas, incluidas conversaciones sobre asesinatos y sobre c\u00f3mo deshacerse de los cad\u00e1veres, <a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2024\/08\/Ultranza-PY-.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">detallan<\/a> su alianza criminal. Francisco Luis Correa, acusado del <a href=\"https:\/\/insightcrime.org\/es\/noticias\/marcelo-pecci-fiscal-paraguayo-asesinado-colombia\/\" target=\"_blank\" rel=\"noreferrer noopener\">asesinato<\/a> del fiscal antimafia paraguayo Marcelo Pecci, afirm\u00f3 que T\u00edo Rico era una de las personas que estaban detr\u00e1s de la orden de asesinato de Pecci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hermano de T\u00edo Rico, Jos\u00e9 Alberto Insfr\u00e1n Galeano, es el fundador de la megaiglesia <em>Centro de Avivamiento<\/em>, a cuyos servicios asist\u00eda el exdiputado Juan Carlos Ozorio. Ozorio fue detenido m\u00e1s tarde, acusado de lavar dinero para los Insfr\u00e1n como presidente de la Cooperativa San Crist\u00f3bal. Las autoridades creen que el Centro de Avivamiento era tambi\u00e9n una fachada para el lavado de dinero para la familia. Ambos Insfr\u00e1n fueron <a href=\"https:\/\/ministeriopublico.gov.py\/nota\/miguel-angel-insfran-alias-tio-rico-llego-esta-manana-extraditado-desde-brasil-7905\" target=\"_blank\" rel=\"noreferrer noopener\">detenidos<\/a> en 2023.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">VEA TAMBI\u00c9N:<\/mark><\/strong> <a href=\"https:\/\/insightcrime.org\/es\/noticias\/paraguay-aprueba-desafuero-senador-trafico-cocaina\/\" target=\"_blank\" rel=\"noreferrer noopener\">Paraguay aprueba desafuero de senador vinculado al tr\u00e1fico de coca\u00edna<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Federico Santoro Vasallo tambi\u00e9n fue detenido en 2023 y extraditado a Estados Unidos el 11 de julio, donde se enfrenta a cargos de blanqueo de capitales. <a href=\"https:\/\/insightcrime.org\/es\/noticias\/redes-narco-uruguay\/\" target=\"_blank\" rel=\"noreferrer noopener\">Se cree<\/a> que Santoro Vasallo supervisaba los pagos del clan. Cobraba el dinero cuando hab\u00eda que cobrarlo y pagaba a quienes hab\u00eda que pagar. Tambi\u00e9n se le acusa de asesorar a Marset sobre las mejores formas de blanquear su fortuna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la carrera criminal de Santoro Vasallo va m\u00e1s all\u00e1 del lavado de dinero. Anteriormente, fue condenado por trata de personas y supuestamente organiz\u00f3 parte del vuelo iran\u00ed que fue detenido en Argentina con millones en cigarrillos de contrabando fabricados por la tabacalera propiedad del expresidente de Paraguay, Horacio Cartes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros miembros de la familia de Marset est\u00e1n acusados de participar en sus operaciones y han tenido encuentros con la justicia. Su cu\u00f1ado, Sebasti\u00e1n Alberti Rossi, fue encarcelado en Uruguay por asesinato, pero escap\u00f3. El 26 de octubre de 2023 se <a href=\"https:\/\/www.hoy.com.py\/nacionales\/sebastian-marset-cunado-del-narco-se-entrego-en-uruguay-y-podria-ser-clave\" target=\"_blank\" rel=\"noreferrer noopener\">entreg\u00f3<\/a> a las autoridades para cumplir su condena. Se cree que Alberti Rossi desempe\u00f1\u00f3 un papel en la creaci\u00f3n de contactos con productores de coca\u00edna en Bolivia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hermano de Marset, Diego Nicol\u00e1s Marset Alba, fue <a href=\"https:\/\/ladiaria.com.uy\/justicia\/articulo\/2023\/12\/detuvieron-en-brasil-al-hermano-de-sebastian-marset\/https:\/\/ladiaria.com.uy\/justicia\/articulo\/2023\/12\/detuvieron-en-brasil-al-hermano-de-sebastian-marset\/\" target=\"_blank\" rel=\"noreferrer noopener\">detenido<\/a> el 26 de diciembre de 2023 en Brasil. Pero Brasil neg\u00f3 la solicitud de extradici\u00f3n de Paraguay y liber\u00f3 a Marset Alba, alegando que es ciudadano brasile\u00f1o y no es buscado por delitos cometidos en ese pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es probable que, tras la p\u00e9rdida de tantos colegas de confianza, las operaciones de Marset se hayan desgastado. Nunca dirigi\u00f3 una organizaci\u00f3n criminal tradicional. Su clan no controlaba el territorio ni intentaba aumentar su n\u00famero con nuevos reclutas. Marset era un intermediario que utilizaba su red para coordinar env\u00edos internacionales de droga. Y al desmoronarse su red, los negocios il\u00edcitos de Marset pueden haberse visto gravemente afectados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodas las pruebas te dicen que la parte operativa de lo que era el sistema de narcotr\u00e1fico, lavado de dinero y todo lo que era el esquema operativo desapareci\u00f3\u201d, dijo a InSight Crime Carlos Peris, soci\u00f3logo de la Universidad Nacional de Asunci\u00f3n. \u201cYo creo que est\u00e1 muy disminuida [la red de Marset], est\u00e1 tan disminuida hasta llegar al punto en el cual pr\u00e1cticamente ya no existe m\u00e1s ese funcionamiento criminal\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-las-numerosas-fugas-de-marset\"><strong>Las numerosas fugas de Marset<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Marset ha logrado escapar de su captura en numerosas ocasiones, mientras que sus socios han sido detenidos. Pero con el desmoronamiento de su red, su suerte puede estar acab\u00e1ndose.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que logr\u00f3 <a href=\"https:\/\/insightcrime.org\/es\/noticias\/importante-traficante-uruguay-desaparece-bolivia\/\" target=\"_blank\" rel=\"noreferrer noopener\">escapar<\/a> de las autoridades bolivianas en julio de 2023, el paradero de Marset a\u00fan es desconocido. Sin embargo, su apoyo y sus contactos son cada vez m\u00e1s escasos, y su tiempo fuera de prisi\u00f3n puede estar llegando a su fin. El 1 de agosto, el ministro del Interior uruguayo, Nicol\u00e1s Martinelli, declar\u00f3 que las autoridades le estaban cercando. Despu\u00e9s de huir por tanto tiempo, Marset empez\u00f3 a cometer errores, y su tiempo est\u00e1 llegando a su fin, afirm\u00f3 Martinelli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Imagen principal: collage de InSight Crime con im\u00e1genes compartidas por las autoridades paraguayas<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pendiente extradici\u00f3n de otra presunta pieza clave en los planes de lavado de dinero de Sebasti\u00e1n Marset supone su \u00faltimo rev\u00e9s, mientras la red del narcotraficante parece desmoronarse. Tras escapar de las autoridades bolivianas en julio de 2023, la familia desapareci\u00f3 del radar y la mayor\u00eda de los indicios apuntan a que Garc\u00eda Troche y sus hijos se trasladaron a Dubai. Hasta ahora, se desconoce el paradero del propio Marset.<\/p>\n","protected":false},"author":241,"featured_media":286986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"single-feature.php","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"above","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[741],"tags":[559,3411,613,3392,560,629],"newspack_spnsrs_tax":[],"coauthors":[4392],"class_list":["post-286989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bolivia","tag-cocaine","tag-cocaine-europe-organized-crime","tag-marijuana","tag-paraguay","tag-uruguay","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/news\/circulo-intimo-marset-desmorona-traficante-uruguayo-elude-captura\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El c\u00edrculo \u00edntimo de Marset se desmorona mientras el traficante uruguayo elude su captura","url":"http:\/\/insightcrime.org\/es\/news\/circulo-intimo-marset-desmorona-traficante-uruguayo-elude-captura\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/news\/circulo-intimo-marset-desmorona-traficante-uruguayo-elude-captura\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/08\/Marset-Network-Unravels2.jpg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/08\/Marset-Network-Unravels2.jpg?fit=1336%2C767&quality=100&ssl=1"},"articleSection":"News","author":[{"@type":"Person","name":"Christopher Newton"}],"creator":["Christopher Newton"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["bolivia","coca\u00edna","coca\u00edna europa","marihuana","paraguay","uruguay"],"dateCreated":"2024-08-12T14:57:49Z","datePublished":"2024-08-12T14:57:49Z","dateModified":"2026-03-13T20:28:10Z"},"rendered":"<meta name=\"parsely-title\" content=\"El c\u00edrculo \u00edntimo de Marset se desmorona mientras el traficante uruguayo elude su captura\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/news\/circulo-intimo-marset-desmorona-traficante-uruguayo-elude-captura\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/08\/Marset-Network-Unravels2.jpg?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2024-08-12T14:57:49Z\" \/>\n<meta name=\"parsely-section\" content=\"News\" \/>\n<meta name=\"parsely-tags\" content=\"bolivia,coca\u00edna,coca\u00edna europa,marihuana,paraguay,uruguay\" \/>\n<meta name=\"parsely-author\" content=\"Christopher Newton\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":246198,"url":"https:\/\/insightcrime.org\/es\/noticias-crimen-organizado-bolivia\/sebastian-marset\/","url_meta":{"origin":286989,"position":0},"title":"Sebasti\u00e1n Marset","author":"Maria Luisa Valencia","date":"25 de junio de 2026","format":false,"excerpt":"Sebasti\u00e1n Marset, el autoproclamado \u201cRey del Sur\u201d, es el delincuente m\u00e1s notorio de Uruguay y l\u00edder del Primer Cartel Uruguayo (PCU). Fue capturado el 13 de marzo de 2026 en Bolivia.","rel":"","context":"En \u00abBolivia\u00bb","block_context":{"text":"Bolivia","link":"https:\/\/insightcrime.org\/es\/category\/noticias-crimen-organizado-bolivia\/"},"img":{"alt_text":"Sebasti\u00e1n Marset","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-criminal-Marset.jpeg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-criminal-Marset.jpeg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-criminal-Marset.jpeg?fit=1200%2C900&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-criminal-Marset.jpeg?fit=1200%2C900&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-criminal-Marset.jpeg?fit=1200%2C900&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":246018,"url":"https:\/\/insightcrime.org\/es\/noticias\/redes-narco-uruguay\/","url_meta":{"origin":286989,"position":1},"title":"Las redes del narco m\u00e1s buscado de Uruguay","author":"Christopher Newton","date":"8 de noviembre de 2023","format":false,"excerpt":"Sebasti\u00e1n Marset, teji\u00f3 una red intercontinental de personas implicadas en tr\u00e1fico de coca\u00edna, lavado de dinero y asesinatos de reconocidos personajes","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Sebasti\u00e1n Marset arrested in 2013 for marijuana trafficking","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/marset.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":232539,"url":"https:\/\/insightcrime.org\/es\/news\/importante-traficante-uruguay-desaparece-bolivia\/","url_meta":{"origin":286989,"position":2},"title":"Importante traficante de Uruguay vuelve a desaparecer en Bolivia","author":"Christopher Newton","date":"31 de julio de 2023","format":false,"excerpt":"El traficante uruguayo Sebasti\u00e1n Marset ha vuelto a evadir a las autoridades despu\u00e9s de estar a punto de ser capturado en Santa Cruz, Bolivia, un hecho que vuelve a poner en evidencia su habilidad para esconderse detr\u00e1s de la protecci\u00f3n oficial y de identidades falsas.","rel":"","context":"En \u00abNews\u00bb","block_context":{"text":"News","link":"https:\/\/insightcrime.org\/category\/news\/"},"img":{"alt_text":"Armas incautadas durante el allanamiento a la casa de Sebastian Marset en Santa Cruz, Bolivia.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/5dbda258ca24c80138ce41be613519c30da92464-1-1-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":232666,"url":"https:\/\/insightcrime.org\/es\/noticias\/paraguay-aprueba-desafuero-senador-trafico-cocaina\/","url_meta":{"origin":286989,"position":3},"title":"Paraguay aprueba desafuero de senador vinculado al tr\u00e1fico de coca\u00edna","author":"Gavin Voss","date":"29 de mayo de 2023","format":false,"excerpt":"La C\u00e1mara de Diputados de Paraguay aprob\u00f3 el desafuero de un congresista del Partido Colorado acusado de lavado de dinero y asociaci\u00f3n criminal; sin embargo, las autoridades a\u00fan enfrenta grandes obst\u00e1culos para erradicar la corrupci\u00f3n en la clase pol\u00edtica del pa\u00eds.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Erico Galeano con el presidente de Paraguay, Santiago Pe\u00f1a, en un evento pol\u00edtico.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Paraguay-Erico-Galeano-Elites-and-Crime-RDN-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":336536,"url":"https:\/\/insightcrime.org\/es\/noticias\/5-claves-sobre-captura-sebastian-marset\/","url_meta":{"origin":286989,"position":4},"title":"5 claves sobre la captura de Sebasti\u00e1n Marset","author":"Christopher Newton","date":"13 de marzo de 2026","format":false,"excerpt":"El 13 de marzo, las autoridades bolivianas capturaron al escurridizo narcotraficante uruguayo Sebasti\u00e1n Marset en un operativo ejecutado por la polic\u00eda antinarc\u00f3ticos de la naci\u00f3n andina con el respaldo de la Administraci\u00f3n de Control de Drogas (Drug Enforcement Administration, DEA) de Estados Unidos.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet.jpg?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet.jpg?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet.jpg?fit=1200%2C675&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet.jpg?fit=1200%2C675&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet.jpg?fit=1200%2C675&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":336567,"url":"https:\/\/insightcrime.org\/es\/noticias\/cronologia-ascenso-caida-sebastian-marset\/","url_meta":{"origin":286989,"position":5},"title":"El ascenso y ca\u00edda de Sebasti\u00e1n Marset","author":"Christopher Newton","date":"13 de marzo de 2026","format":false,"excerpt":"La carrera criminal de Sebasti\u00e1n Marset se extendi\u00f3 durante varios a\u00f1os y atraves\u00f3 varios pa\u00edses. A continuaci\u00f3n, InSight Crime repasa su trayectoria: desde sus inicios como traficante de marihuana, su ascenso hasta convertirse en un sofisticado intermediario del tr\u00e1fico de coca\u00edna acusado de narcotr\u00e1fico y lavado de dinero, hasta su\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet-2.jpg?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet-2.jpg?fit=1200%2C675&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet-2.jpg?fit=1200%2C675&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet-2.jpg?fit=1200%2C675&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/03\/Imagen-destacada-MArcet-2.jpg?fit=1200%2C675&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/08\/Marset-Network-Unravels2.jpg?fit=1336%2C767&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/286989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/241"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=286989"}],"version-history":[{"count":6,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/286989\/revisions"}],"predecessor-version":[{"id":336638,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/286989\/revisions\/336638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/286986"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=286989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=286989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=286989"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=286989"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=286989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}