{"id":29768,"date":"2017-07-26T00:00:00","date_gmt":"2017-07-26T00:00:00","guid":{"rendered":"https:\/\/insightcrime.org\/?p=29768"},"modified":"2023-04-24T16:01:46","modified_gmt":"2023-04-24T21:01:46","slug":"esquema-fraude-aduanero-argentina-evoca-venezuela","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/esquema-fraude-aduanero-argentina-evoca-venezuela\/","title":{"rendered":"Esquema de fraude aduanero en Argentina evoca a Venezuela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un fraude aduanero que presuntamente permiti\u00f3 a una red criminal robar millones al gobierno argentino guarda un parecido escalofriante con la manera como algunas empresas privadas y funcionarios corruptos en Venezuela se han beneficiado tambi\u00e9n de los esfuerzos del pa\u00eds andino por manipular las cotizaciones de las divisas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades argentinas realizaron 23 allanamientos simult\u00e1neos y detuvieron a diez personas acusadas de estafa al estado en m\u00e1s de US$300 millones entre 2012 y 2015, seg\u00fan <a href=\"https:\/\/www.minseg.gob.ar\/una-banda-que-defraud\u00f3-al-estado-por-m\u00e1s-de-300-millones-de-d\u00f3lares\" target=\"_blank\">un comunicado de prensa<\/a> emitido el 11 de julio por la ministra de Seguridad de Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El esquema se origin\u00f3 en la diferencia entre la tasa oficial del d\u00f3lar frente al peso argentino y su precio informal en el mercado negro. Las autoridades afirman que se usaron 55 empresas de papel para falsificar Declaraciones Juradas Anticipadas de Importaci\u00f3n (DJAI). Esos documentos permit\u00edan a las firmas importadoras comprar d\u00f3lares al gobierno a una tasa subsidiada para la compra de productos extranjeros. La anterior administraci\u00f3n de Argentina <a href=\"https:\/\/money.cnn.com\/2015\/12\/17\/news\/economy\/argentina-peso-fall-currency-peg\/index.html\" target=\"_blank\">elev\u00f3 artificialmente<\/a> el valor del peso, de modo que un d\u00f3lar oficial var\u00eda mucho menos que este en el mercado negro. Pero en el esquema, se generaban DJAIs para bienes que nunca se importaban con el \u00fanico fin de comprar d\u00f3lares oficiales a una tasa menor, antes de venderlos a un precio mucho m\u00e1s alto en el mercado negro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n, abierta el a\u00f1o pasado luego de una denuncia oficial del director de aduanas de Argentina, se centra en una red de empresas textiles de propiedad miembros de la comunidad coreana en Buenos Aires, <a href=\"https:\/\/www.infobae.com\/sociedad\/2017\/07\/10\/la-mafia-del-dolar-importador-nombres-y-empresas-detras-de-un-negociado-de-300-millones\/\" target=\"_blank\">seg\u00fan Infobae<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infobae, que calific\u00f3 de \u201cmafia\u201d la bien estructurada red integrada por contadores profesionales, se\u00f1ala que a\u00fan no hay un solo funcionario acusado de corrupci\u00f3n, aun cuando el bolet\u00edn de prensa oficial admite que se pagaron coimas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lisis de InSight Crime<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El esquema que se est\u00e1 investigando en Argentina ilustra c\u00f3mo el crimen organizado puede sacar provecho de las pol\u00edticas monetarias de un gobierno, as\u00ed como de una buena dosis de corrupci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La suma puede parecer grande, pero otras p\u00e9rdidas regionales por fraudes de este tipo se han medido en <a href=\"\/noticias\/noticias-del-dia\/fraude-contrabando-equivalen-3-5-por-ciento-pib-guatemalteco\" target=\"_blank\">porcentajes del producto interno bruto<\/a> y llegan a los m\u00e1s altos niveles. En Guatemala, por ejemplo, la corrupci\u00f3n <a href=\"\/noticias\/analisis\/explicacion-escandalos-corrupcion-gobierno-guatemala\" target=\"_blank\">lleg\u00f3 hasta el presidente<\/a>, quien lideraba y se beneficiaba de un enorme fraude aduanero, seg\u00fan los investigadores del gobierno a cargo del caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"color: #800000\"><strong>VEA TAMBI\u00c9N:<\/strong><\/span>&nbsp;<a href=\"\/indepth\/elites-y-crimen-organizado\" target=\"_blank\">\u00c9lites y crimen organizado<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El caso de Argentina, parece tener m\u00e1s semejanzas con Venezuela. De hecho, el control de las tasas de cambio y la venta de d\u00f3lares ejercidas por el gobierno de ese pa\u00eds se aprovecharon para desviar hasta US$ 70 millones en una d\u00e9cada, <a href=\"https:\/\/www.nytimes.com\/2015\/05\/06\/world\/americas\/venezuelas-economy-suffers-as-import-schemes-siphon-billions.html?_r=0\" target=\"_blank\">seg\u00fan inform\u00f3 el New York Times<\/a>. Y, siguiendo un modelo regional, la corrupci\u00f3n se mantuvo como factor base para <a href=\"\/noticias\/analisis\/corrupcion-generalizada-venezuela-pasa-factura-presidente-maduro\" target=\"_blank\">permitir esos fraudes<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un fraude aduanero que presuntamente permiti\u00f3 a una red criminal robar millones al gobierno argentino guarda un parecido escalofriante con la manera como algunas empresas privadas y funcionarios corruptos en Venezuela se han beneficiado tambi\u00e9n de los esfuerzos del pa\u00eds andino por manipular las cotizaciones de las divisas.<\/p>\n","protected":false},"author":79,"featured_media":46776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[334],"tags":[428,447],"newspack_spnsrs_tax":[],"coauthors":[4036],"class_list":["post-29768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia","tag-argentina-pais","tag-elites-y-crimen-organizado","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/esquema-fraude-aduanero-argentina-evoca-venezuela\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esquema de fraude aduanero en Argentina evoca a Venezuela","url":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/esquema-fraude-aduanero-argentina-evoca-venezuela\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/esquema-fraude-aduanero-argentina-evoca-venezuela\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/07\/es-17-07-12-Argentina-Customs-Fraud.jpg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/07\/es-17-07-12-Argentina-Customs-Fraud.jpg?fit=350%2C250&quality=100&ssl=1"},"articleSection":"Noticias del d\u00eda","author":[{"@type":"Person","name":"Tristan Clavel"}],"creator":["Tristan Clavel"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["argentina","\u00e9lites y crimen"],"dateCreated":"2017-07-26T00:00:00Z","datePublished":"2017-07-26T00:00:00Z","dateModified":"2023-04-24T21:01:46Z"},"rendered":"<meta name=\"parsely-title\" content=\"Esquema de fraude aduanero en Argentina evoca a Venezuela\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/esquema-fraude-aduanero-argentina-evoca-venezuela\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/07\/es-17-07-12-Argentina-Customs-Fraud.jpg?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2017-07-26T00:00:00Z\" \/>\n<meta name=\"parsely-section\" content=\"Noticias del d\u00eda\" \/>\n<meta name=\"parsely-tags\" content=\"argentina,\u00e9lites y crimen\" \/>\n<meta name=\"parsely-author\" content=\"Tristan Clavel\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":192086,"url":"https:\/\/insightcrime.org\/es\/noticias\/yates-cocaina-paseo-anual-argentina-espana\/","url_meta":{"origin":29768,"position":0},"title":"Yates y coca\u00edna: un paseo anual entre Argentina y Espa\u00f1a","author":"Gabrielle Gorder","date":"19 de julio de 2022","format":false,"excerpt":"Dos argentinos due\u00f1os de restaurantes que resid\u00edan en Espa\u00f1a son buscados por el presunto uso de yates para trasegar coca\u00edna entre Suram\u00e9rica y Europa, un hecho que destaca el uso com\u00fan de embarcaciones privadas para el narcotr\u00e1fico transatl\u00e1ntico.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Yate Quo Vadis usado por traficantes argentinos para mover coca\u00edna entre Argentina y Espa\u00f1a","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/07\/quo-vadis-el-velero-que___pyAQNDURT_720x0__1.webp?fit=720%2C540&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/07\/quo-vadis-el-velero-que___pyAQNDURT_720x0__1.webp?fit=720%2C540&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/07\/quo-vadis-el-velero-que___pyAQNDURT_720x0__1.webp?fit=720%2C540&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/07\/quo-vadis-el-velero-que___pyAQNDURT_720x0__1.webp?fit=720%2C540&quality=100&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":80284,"url":"https:\/\/insightcrime.org\/es\/colombia-organized-crime-news\/jose-bayron-piedrahita-ceballos\/","url_meta":{"origin":29768,"position":1},"title":"Jos\u00e9 Bayron Piedrah\u00edta Ceballos, alias &#8216;El \u00c1rabe&#8217; o &#8216;El Patr\u00f3n de Caucasia&#8217;","author":"InSight Crime","date":"30 de octubre de 2020","format":false,"excerpt":"Jos\u00e9 Bayron Piedrahita Ceballos es uno de los presuntos grandes capos del narcotr\u00e1fico en Colombia. Durante m\u00e1s de veinte a\u00f1os de carrera criminal, logr\u00f3 pasar desapercibido para las autoridades y consolidar su poder. Piedrahita Ceballos estuvo rodeado de grandes y reconocidos capos, pero consigui\u00f3 que sus actividades ilegales se cubrieran\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/insightcrime.org\/category\/colombia-organized-crime-news\/"},"img":{"alt_text":"Perfil criminal - Jos\u00e9 Bayron Piedrah\u00edta Ceballos, alias \u00abEl \u00c1rabe\u00bb o \u00abEl Patr\u00f3n de Caucasia\u00bb, Colombia.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":246970,"url":"https:\/\/insightcrime.org\/es\/noticias\/retos-criminales-aguardan-nuevo-presidente-argentina\/","url_meta":{"origin":29768,"position":2},"title":"Los retos criminales que aguardan al nuevo presidente de Argentina","author":"Christopher Newton","date":"20 de noviembre de 2023","format":false,"excerpt":"Javier Milei se convirti\u00f3 en el pr\u00f3ximo presidente de Argentina gracias a sus promesas de reformas radicales de libre mercado y a su dura propuesta de seguridad. Pero con el aumento de la inseguridad, una econom\u00eda en crisis y una minor\u00eda en el Congreso, la plataforma de Milei se enfrentar\u00e1\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"El Presidente electo Javier Milei pronuncia su discurso de victoria tras ganar las elecciones presidenciales. Cr\u00e9dito: Agustin Marcarian \/ REUTERS","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/milei_victory_speech.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":142186,"url":"https:\/\/insightcrime.org\/es\/noticias\/magnate-aviacion-argentina-organizaba-narcovuelos\/","url_meta":{"origin":29768,"position":3},"title":"Magnate de la aviaci\u00f3n en Argentina organizaba narcovuelos a todo el continente","author":"Shane Sullivan","date":"28 de abril de 2021","format":false,"excerpt":"Pese a las numerosas investigaciones en contra suya, un magnate argentino de la aviaci\u00f3n logr\u00f3 valerse de los vac\u00edos en las normas de registro de aviones en Estados Unidos y ayud\u00f3 a narcotraficantes de toda Latinoam\u00e9rica a buscar aviones para el transporte de sus cargamentos.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2021\/04\/fred-machado-foto-el-periodico___UhPvrGhrv_1200x630__1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":323364,"url":"https:\/\/insightcrime.org\/es\/noticias\/como-la-causa-los-cuadernos-de-las-coimas-amenaza-a-una-expresidenta-en-argentina\/","url_meta":{"origin":29768,"position":4},"title":"C\u00f3mo la causa \u2018Los cuadernos de las coimas\u2019 amenaza a una expresidenta en Argentina","author":"Creusa Mu\u00f1oz","date":"6 de noviembre de 2025","format":false,"excerpt":"Este 6 de noviembre comenz\u00f3 el juicio oral y p\u00fablico por \u201cLos cuadernos de las coimas\u201d, el caso de corrupci\u00f3n m\u00e1s grande de la historia argentina, que investiga un esquema sistem\u00e1tico de sobornos de alto perfil pol\u00edtico y empresarial que oper\u00f3 durante 2003 y 2015, y que tendr\u00eda presuntamente como\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/11\/Flagship-Feature-Image-Cuadernos-de-las-coimas-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/11\/Flagship-Feature-Image-Cuadernos-de-las-coimas-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/11\/Flagship-Feature-Image-Cuadernos-de-las-coimas-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/11\/Flagship-Feature-Image-Cuadernos-de-las-coimas-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/11\/Flagship-Feature-Image-Cuadernos-de-las-coimas-1.jpg?fit=1200%2C690&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":127766,"url":"https:\/\/insightcrime.org\/es\/noticias\/comando-rojo-no-asienta-argentina\/","url_meta":{"origin":29768,"position":5},"title":"Comando Rojo de Brasil a\u00fan no se asienta en Argentina","author":"Parker Asmann","date":"8 de diciembre de 2020","format":false,"excerpt":"Se conocen nuevos detalles sobre las sofisticadas operaciones criminales de un jefe del Comando Rojo que oper\u00f3 en la regi\u00f3n fronteriza entre Argentina y Brasil, pero aparte de unos cuantos incidentes aislados, el grupo a\u00fan no establece una presencia importante en la vecina Argentina.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2020\/12\/20-12-02-Brum-Red-Command-Argentina.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/07\/es-17-07-12-Argentina-Customs-Fraud.jpg?fit=350%2C250&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/29768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=29768"}],"version-history":[{"count":1,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/29768\/revisions"}],"predecessor-version":[{"id":35740,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/29768\/revisions\/35740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/46776"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=29768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=29768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=29768"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=29768"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=29768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}