{"id":6463,"date":"2014-02-28T17:34:08","date_gmt":"2017-03-27T23:59:12","guid":{"rendered":"http:\/\/newwp.insightcrime.org?p=6463"},"modified":"2023-04-24T15:36:46","modified_gmt":"2023-04-24T20:36:46","slug":"caso-de-lavado-de-dinero-en-colombia-es-recordatorio-de-la-influencia-del-cartel-de-cali","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/caso-de-lavado-de-dinero-en-colombia-es-recordatorio-de-la-influencia-del-cartel-de-cali\/","title":{"rendered":"Caso de lavado de dinero en Colombia advierte la influencia del Cartel de Cali"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los hijos de los fundadores del Cartel de Cali, los hermanos Rodr\u00edguez Orejuela, enfrentan cargos por lavado de dinero en Colombia; otro recordatorio de la continua presencia de uno de los pioneros del tr\u00e1fico de coca\u00edna a gran escala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un juez de Bogot\u00e1 ha dictaminado que los cinco hijos de Gilberto y Miguel Rodr\u00edguez Orejuela deben enfrentar un juicio por presuntamente ocultar fondos que se supon\u00eda que sus padres deb\u00edan haber entregado, como parte del trato que realizaron con las autoridades estadounidenses, <a href=\"https:\/\/www.semana.com\/nacion\/articulo\/hijos-de-miguel-gilberto-rodriguez-orejuela-van-juicio-por-lavado-de-activos\/378601-3\" target=\"_blank\">inform\u00f3 Semana<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2006, los capos del Cartel de Cali aceptaron penas de prisi\u00f3n de 30 a\u00f1os en Estados Unidos y acordaron entregar toda su riqueza, proveniente del comercio de droga, a cambio de inmunidad para sus familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #800000\">VEA TAMBI\u00c9N:<\/span><\/strong> <a href=\"\/perfil-del-crimen-organizado\/colombia\" target=\"_blank\">Noticias y perfiles de Colombia<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, las autoridades estadounidenses exigieron a los fiscales colombianos buscar en los informes si hab\u00edan ocultado fortunas a trav\u00e9s de negocios legales dirigidos por familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n que sigui\u00f3 revel\u00f3 transacciones financieras en las empresas familiares, que eran indicio de operaciones de lavado de dinero, as\u00ed como una serie de pr\u00e1cticas comerciales sospechosas y la venta sospechosa de una cadena de farmacias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia tendr\u00e1 ahora que demostrar ante el tribunal que su considerable portafolio financiero no se basa en dinero de la droga.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lisis de InSight Crime<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Cartel de Cali, junto con el Cartel de Medell\u00edn de Pablo Escobar, fue la fuerza motriz del boom de la coca\u00edna colombiana de la d\u00e9cada de los ochenta y los noventa, y despu\u00e9s de la muerte de Escobar, posiblemente fue el cartel de la droga m\u00e1s rico y poderoso del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ca\u00edda de la organizaci\u00f3n sigue influyendo en el mundo criminal de Colombia hoy en d\u00eda, y no s\u00f3lo en las actividades financieras il\u00edcitas de la familia Rodr\u00edguez Orejuela, ya que tratan de aferrarse a los restos de la multimillonaria fortuna&nbsp;que acumularon los l\u00edderes de los carteles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se cree que dos extraficantes de droga del Cartel de Cali, que han cumplido penas de prisi\u00f3n en Estados Unidos, son las principales figuras en la violenta disputa por tr\u00e1fico de drogas, que se libra hoy en Cali y el Valle del Cauca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se cree que Victor Pati\u00f1o Fomeque, alias \u201cEl Qu\u00edmico\u201d, quien tambi\u00e9n trabaj\u00f3 con el sucesor del Cartel de Cali, el Cardel del Norte del Valle (CNDV), es una influencia importante en la <a href=\"\/noticias\/analisis\/15-anos-de-sangre-y-venganza-continua-disputa-del-cartel-del-norte-del-valle\" target=\"_blank\">alianza de traficantes relacionados con el CNDV<\/a> que ahora luchan en nombre de los Urabe\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lucha de esta coalici\u00f3n para controlar la regi\u00f3n se ha complicado por el retorno de otro <a href=\"\/noticias\/noticias-del-dia\/narcos-de-vieja-generacion-alimentan-las-nuevas-guerras-de-la-mafia-de-colombia\" target=\"_blank\">capo en Cali conocido como \u201cEl Se\u00f1or de la R\u201d<\/a>, que acaba de regresar a Colombia y est\u00e1 tratando de retomar el control de las antiguas operaciones del cartel, seg\u00fan la polic\u00eda. El Se\u00f1or de la R es al parecer un miembro de la familia del co-l\u00edder de los hermanos Rodr\u00edguez Orejuela de Cali, Helmer \u2018Pacho\u2019 Herrera -posiblemente su hermano Ramiro Herrera Buitrago, quien dirigi\u00f3 las operaciones del cartel en Nueva York.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los hijos de los fundadores del Cartel de Cali, los hermanos Rodr\u00edguez Orejuela, enfrentan cargos por lavado de dinero en Colombia; otro recordatorio de la continua presencia de uno de los pioneros del tr\u00e1fico de coca\u00edna a gran escala.<\/p>\n","protected":false},"author":16,"featured_media":39711,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[334],"tags":[368,431],"newspack_spnsrs_tax":[],"coauthors":[3821],"class_list":["post-6463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia","tag-colombia-pais","tag-lavado-de-dinero","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/caso-de-lavado-de-dinero-en-colombia-es-recordatorio-de-la-influencia-del-cartel-de-cali\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Caso de lavado de dinero en Colombia advierte la influencia del Cartel de Cali","url":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/caso-de-lavado-de-dinero-en-colombia-es-recordatorio-de-la-influencia-del-cartel-de-cali\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/caso-de-lavado-de-dinero-en-colombia-es-recordatorio-de-la-influencia-del-cartel-de-cali\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/02\/es-65ae5f02870b77a274705a8f9a06ab5b.jpg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/02\/es-65ae5f02870b77a274705a8f9a06ab5b.jpg?fit=280%2C169&quality=100&ssl=1"},"articleSection":"Noticias del d\u00eda","author":[{"@type":"Person","name":"James Bargent"}],"creator":["James Bargent"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["colombia","lavado de dinero"],"dateCreated":"2017-03-27T23:59:12Z","datePublished":"2017-03-27T23:59:12Z","dateModified":"2023-04-24T20:36:46Z"},"rendered":"<meta name=\"parsely-title\" content=\"Caso de lavado de dinero en Colombia advierte la influencia del Cartel de Cali\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/caso-de-lavado-de-dinero-en-colombia-es-recordatorio-de-la-influencia-del-cartel-de-cali\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/02\/es-65ae5f02870b77a274705a8f9a06ab5b.jpg?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2017-03-27T23:59:12Z\" \/>\n<meta name=\"parsely-section\" content=\"Noticias del d\u00eda\" \/>\n<meta name=\"parsely-tags\" content=\"colombia,lavado de dinero\" \/>\n<meta name=\"parsely-author\" content=\"James Bargent\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":187358,"url":"https:\/\/insightcrime.org\/es\/noticias\/el-capo-del-cartel-de-cali-gilberto-rodriguez-orejuela-muere-en-prision\/","url_meta":{"origin":6463,"position":0},"title":"El capo del Cartel de Cali Gilberto Rodr\u00edguez Orejuela muere en prisi\u00f3n","author":"Scott Mistler-Ferguson","date":"2 de junio de 2022","format":false,"excerpt":"La muerte del capo del Cartel de Cali Gilberto Rodr\u00edguez Orejuela en una prisi\u00f3n estadounidense marca el fin de uno de los narcos m\u00e1s notorios de Colombia, y con \u00e9l se va una era de la historia del pa\u00eds.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Cali-Cartel-Capo- Gilberto-Rodr\u00edguez-Orejuela-Dies","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/06\/Orejuela-Death-Cali-Capo.png?fit=350%2C251&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":188766,"url":"https:\/\/insightcrime.org\/es\/noticias-crimen-organizado-colombia\/gilberto-rodriguez-orejuela-alias-el-ajedrecista\/","url_meta":{"origin":6463,"position":1},"title":"Gilberto Rodr\u00edguez Orejuela, alias &#8216;El Ajedrecista&#8217;","author":"InSight Crime","date":"15 de junio de 2022","format":false,"excerpt":"Gilberto Rodr\u00edguez Orejuela, alias \u201cEl Ajedrecista\u201d, fue uno de los cabecillas del extinto Cartel de Cali.","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/insightcrime.org\/es\/category\/noticias-crimen-organizado-colombia\/"},"img":{"alt_text":"Perfil criminal - Gilberto Rodr\u00edguez Orejuela, alias 'El Ajedrecista' - Colombia.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Alias-El-Ajedrecista-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Alias-El-Ajedrecista-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Alias-El-Ajedrecista-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Alias-El-Ajedrecista-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Alias-El-Ajedrecista-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":182338,"url":"https:\/\/insightcrime.org\/es\/noticias\/cali-nuevo-centro-operaciones-carteles-mexicanos-colombia\/","url_meta":{"origin":6463,"position":2},"title":"\u00bfEs Cali un nuevo centro de operaciones de los carteles mexicanos en Colombia?","author":"Gabrielle Gorder","date":"13 de abril de 2022","format":false,"excerpt":"Hasta d\u00f3nde llega la presencia activa de los carteles mexicanos en Colombia, m\u00e1s all\u00e1 de la intermediaci\u00f3n para negociar la compra de drogas, volvi\u00f3 a ser tema de debate luego de la captura de un presunto alto emisario del Cartel de Sinaloa.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/04\/2022-04-13-Alias-Pitt-Cali.jpeg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":134349,"url":"https:\/\/insightcrime.org\/es\/noticias\/madrid-desmantela-red-sicariato-lavado\/","url_meta":{"origin":6463,"position":3},"title":"Madrid desmantela red de sicariato y lavado de dinero","author":"Katie Jones","date":"18 de febrero de 2021","format":false,"excerpt":"Las autoridades de Madrid desmantelaron parte de una sofisticada red dedicada al sicariato y el lavado de dinero transnacional.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2021\/02\/DDP-Machetes.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":80284,"url":"https:\/\/insightcrime.org\/es\/colombia-organized-crime-news\/jose-bayron-piedrahita-ceballos\/","url_meta":{"origin":6463,"position":4},"title":"Jos\u00e9 Bayron Piedrah\u00edta Ceballos, alias &#8216;El \u00c1rabe&#8217; o &#8216;El Patr\u00f3n de Caucasia&#8217;","author":"InSight Crime","date":"30 de octubre de 2020","format":false,"excerpt":"Jos\u00e9 Bayron Piedrahita Ceballos es uno de los presuntos grandes capos del narcotr\u00e1fico en Colombia. Durante m\u00e1s de veinte a\u00f1os de carrera criminal, logr\u00f3 pasar desapercibido para las autoridades y consolidar su poder. Piedrahita Ceballos estuvo rodeado de grandes y reconocidos capos, pero consigui\u00f3 que sus actividades ilegales se cubrieran\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/insightcrime.org\/category\/colombia-organized-crime-news\/"},"img":{"alt_text":"Perfil criminal - Jos\u00e9 Bayron Piedrah\u00edta Ceballos, alias \u00abEl \u00c1rabe\u00bb o \u00abEl Patr\u00f3n de Caucasia\u00bb, Colombia.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/08\/Perfil-Criminal-Jose-Bayron-Piedrahita-Ceballos-Colombia.jpg?fit=1200%2C900&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":142731,"url":"https:\/\/insightcrime.org\/es\/noticias\/banda-criminal-colombiana-blanqueo-us100-millones-ano\/","url_meta":{"origin":6463,"position":5},"title":"Banda criminal colombiana blanque\u00f3 US$100 millones en un a\u00f1o","author":"Shane Sullivan","date":"30 de abril de 2021","format":false,"excerpt":"Una docena de personas en Colombia est\u00e1n acusadas de lavar cerca de US$100 millones pertenecientes a grupos criminales, desde un cartel mexicano hasta un grupo narcotraficante colombiano, una mirada a los intermediarios que ofrecen servicios de lavado de dinero a una variada clientela criminal.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2021\/04\/contract-signing.jpeg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/02\/es-65ae5f02870b77a274705a8f9a06ab5b.jpg?fit=280%2C169&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/6463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=6463"}],"version-history":[{"count":1,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/6463\/revisions"}],"predecessor-version":[{"id":21790,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/6463\/revisions\/21790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/39711"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=6463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=6463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=6463"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=6463"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=6463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}