{"id":7268,"date":"2014-10-13T20:32:03","date_gmt":"2017-03-28T00:04:41","guid":{"rendered":"http:\/\/newwp.insightcrime.org?p=7268"},"modified":"2023-04-24T15:41:41","modified_gmt":"2023-04-24T20:41:41","slug":"fiscales-honduras-asesinadas-barrio-18","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/fiscales-honduras-asesinadas-barrio-18\/","title":{"rendered":"Fiscales de Honduras \u2018asesinadas por la pandilla Barrio 18\u2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El homicidio de dos fiscales en Honduras es un recordatorio de que a pesar del progreso que ha tenido el pa\u00eds con la captura de las cabezas de algunas organizaciones transnacionales de tr\u00e1fico de drogas, todav\u00eda hay un largo camino por recorrer para mitigar la violencia de las pandillas y mejorar la seguridad ciudadana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las fiscales Marlene Banegas y Olga Eufragio, fueron asesinadas el 10 de octubre mientras conduc\u00edan en San Pedro Sula, la ciudad m\u00e1s violenta de Honduras. Banegas recibi\u00f3 m\u00e1s de 50 disparos, los cuales la polic\u00eda afirma, indicar\u00edan que era el principal objetivo, <a href=\"https:\/\/www.laprensa.hn\/inicio\/757096-417\/capturan-a-mareros-por-muerte-de-fiscales\" target=\"_blank\">inform\u00f3 El Heraldo<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Banegas, quien era la coordinadora de la Fiscal\u00eda de Delitos contra la Vida, previamente hab\u00eda liderado la unidad de crimen organizado. Tambi\u00e9n hab\u00eda trabajado como coordinadora regional de la Fiscal\u00eda General de la Rep\u00fablica en el norte de Honduras. Eufragio era fiscal de Protecci\u00f3n al Medio Ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.laprensa.hn\/honduras\/757339-417\/la-mara-18-mat%C3%B3-a-las-fiscales-jefe-de-la-polic%C3%ADa\" target=\"_blank\">El jefe de la polic\u00eda de Honduras afirm\u00f3<\/a> que la pandilla \u201cMara 18\u201d \u2013o Barrio 18- estar\u00eda detr\u00e1s de los asesinatos. La polic\u00eda arrest\u00f3 a cuatro presuntos miembros de la pandilla luego del tiroteo el d\u00eda de los asesinatos y seg\u00fan el jefe de la polic\u00eda, se cree que por lo menos dos de ellos est\u00e1n involucrados en el caso de las fiscales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Banegas hab\u00eda reportado haber recibido amenazas de Barrio 18 antes de su muerte, y hab\u00eda sido removida de varias investigaciones por su seguridad, <a href=\"https:\/\/www.elheraldo.hn\/pais\/757070-331\/honduras-fiscales-asesinadas-eran-honestas-y-combativas\" target=\"_blank\">inform\u00f3 El Heraldo<\/a>. La fiscal hab\u00eda estado involucrada en un proceso contra Barrio 18, en el cual tres miembros de la pandilla fueron encontrados culpables por la masacre de 17 personas en una tienda de zapatos en 2010. Luego de la sentencia en agosto de 2013 a Banegas se le asign\u00f3 un equipo de polic\u00edas escoltas para protegerla de la pandilla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lisis de InSight Crime<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Honduras recientemente ha tenido algunos \u00e9xitos muy <a href=\"\/noticias\/noticias-del-dia\/que-sigue-lucha-antidrogas-honduras\" target=\"_blank\">significativos en el combate contra el crimen organizado<\/a>. Con el apoyo de Estados Unidos la polic\u00eda antidrogas ha logrado&nbsp;<a href=\"\/noticias\/noticias-del-dia\/honduras-captura-lideres-clan-valle\" target=\"_blank\">desmantelar<\/a>&nbsp;una de las organizaciones narcotraficantes m\u00e1s grandes del pa\u00eds, el clan de los Valle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero como muestran estos asesinatos, Honduras a\u00fan se enfrenta a la enorme tarea de mejorar la seguridad ciudadana y abordar la violencia de las pandillas. Capturando a aquellos detr\u00e1s de los asesinatos de Banegas y Eufragio y otorg\u00e1ndoles un juicio justo enviar\u00eda un mensaje a las pandillas de que no pueden atacar al Estado impunemente. Hay pocas esperanzas de mejor\u00eda para el sistema judicial de Honduras si aquellos que manejan los casos relacionados con las pandillas temen por sus vidas. Seg\u00fan el comisionado nacional de los Derechos Humanos, <a href=\"https:\/\/proceso.hn\/nacionales\/item\/89314-imparables-asesinatos-de-abogados-83-han-muerto-en-%C3%BAltimos-cinco-a%C3%B1os.html\" target=\"_blank\">83 abogados han sido asesinados en el pa\u00eds desde 2010<\/a>. Esto incluye el <a href=\"\/news\/briefs\/honduras-top-anti-money-laundering-prosecutor-murdered\" target=\"_blank\">asesinato del a\u00f1o pasado de un fiscal por un caso de lavado de dinero<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lucha por proteger a aquellos que tratan los casos de crimen organizado es un problema end\u00e9mico a lo largo de Latinoam\u00e9rica, incluyendo pa\u00edses <a href=\"\/news\/briefs\/colombian-mexican-traffickers-offer-1m-for-murder-of-peruvian-prosecutor\" target=\"_blank\">como Per\u00fa<\/a> y Guatemala, donde un abogado que manejaba un caso contra el cartel mexicano de los Zetas fue<a href=\"\/news\/briefs\/news\/briefs\/guatemala-prosecutor-killed-after-zetas-arrests\" target=\"_blank\"> asesinado y desmembrado en 2011<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El homicidio de dos fiscales en Honduras es un recordatorio de que a pesar del progreso que ha tenido el pa\u00eds con la captura de las cabezas de algunas organizaciones transnacionales de tr\u00e1fico de drogas, todav\u00eda hay un largo camino por recorrer para mitigar la violencia de las pandillas y mejorar la seguridad ciudadana.<\/p>\n","protected":false},"author":4,"featured_media":41356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[334],"tags":[375,398],"newspack_spnsrs_tax":[],"coauthors":[3660],"class_list":["post-7268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia","tag-barrio-18-grupo","tag-honduras-pais","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/fiscales-honduras-asesinadas-barrio-18\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fiscales de Honduras \u2018asesinadas por la pandilla Barrio 18\u2019","url":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/fiscales-honduras-asesinadas-barrio-18\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/fiscales-honduras-asesinadas-barrio-18\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/10\/es-20141013_honduras_fiscales.jpeg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/10\/es-20141013_honduras_fiscales.jpeg?fit=362%2C240&quality=100&ssl=1"},"articleSection":"Noticias del d\u00eda","author":[{"@type":"Person","name":"Elyssa Pachico"}],"creator":["Elyssa Pachico"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["barrio 18","honduras"],"dateCreated":"2017-03-28T00:04:41Z","datePublished":"2017-03-28T00:04:41Z","dateModified":"2023-04-24T20:41:41Z"},"rendered":"<meta name=\"parsely-title\" content=\"Fiscales de Honduras \u2018asesinadas por la pandilla Barrio 18\u2019\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/fiscales-honduras-asesinadas-barrio-18\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/10\/es-20141013_honduras_fiscales.jpeg?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2017-03-28T00:04:41Z\" \/>\n<meta name=\"parsely-section\" content=\"Noticias del d\u00eda\" \/>\n<meta name=\"parsely-tags\" content=\"barrio 18,honduras\" \/>\n<meta name=\"parsely-author\" content=\"Elyssa Pachico\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":273259,"url":"https:\/\/insightcrime.org\/es\/noticias\/como-investigamos-masacre-prision-femenina-honduras\/","url_meta":{"origin":7268,"position":0},"title":"Detr\u00e1s de la historia: C\u00f3mo investigamos la masacre en la prisi\u00f3n femenina de Honduras","author":"InSight Crime","date":"10 de abril de 2024","format":false,"excerpt":"El 16 de agosto de 2023, InSight Crime public\u00f3 una investigaci\u00f3n sobre una de las masacres m\u00e1s mort\u00edferas registradas en una prisi\u00f3n femenina en Latinoam\u00e9rica. En un reciente espacio de Twitter, dos de nuestras investigadoras conversaron sobre la metodolog\u00eda de la investigaci\u00f3n, las impresiones acerca de la PNFAS, y el\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Women survivors of the massacre in the Honduras women's prison. \n","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":232637,"url":"https:\/\/insightcrime.org\/es\/noticias\/masacre-penal-femenino-honduras-tragedia-anunciada\/","url_meta":{"origin":7268,"position":1},"title":"Masacre en penal femenino de Honduras: una tragedia anunciada\u00a0","author":"Victoria Dittmar","date":"21 de junio de 2023","format":false,"excerpt":"El asesinato de decenas de mujeres en el penal femenino de Honduras ocurri\u00f3 en un contexto de creciente tensi\u00f3n entre pandillas.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Humo sale del penal del PNFAS en Honduras, donde 48 mujeres fueron asesinadas en violencia entre pandillas","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/af09886383-1-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":267310,"url":"https:\/\/insightcrime.org\/es\/noticias\/inseguridad-persiste-tras-investigacion-masacre-honduras\/","url_meta":{"origin":7268,"position":2},"title":"Persisten preocupaciones de seguridad a pesar de acusaciones por masacre en prisi\u00f3n femenina de Honduras","author":"Victoria Dittmar","date":"5 de febrero de 2024","format":false,"excerpt":"A m\u00e1s de medio a\u00f1o de la masacre m\u00e1s mort\u00edfera en una prisi\u00f3n femenina en Latinoam\u00e9rica, el gobierno de Honduras comienza a mostrar avances en la investigaci\u00f3n de los hechos, pero a\u00fan se queda corto en cambios sist\u00e9micos de seguridad.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Honduras has moved to indict nine women accused of their participation in a prison massacre that claimed the lives of 46 female prisoners. Honduras ha tomado medidas para procesar a nueve mujeres acusadas de su participaci\u00f3n en una masacre carcelaria que se cobr\u00f3 la vida de 46 reclusas.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/02\/PNFAS-Honduras.jpeg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":139153,"url":"https:\/\/insightcrime.org\/es\/noticias\/se-aclara-supuesto-rol-presidente-honduras-conspiracion-traficar-drogas\/","url_meta":{"origin":7268,"position":3},"title":"Se aclara el supuesto rol del presidente de Honduras en conspiraci\u00f3n para traficar drogas","author":"Parker Asmann","date":"23 de marzo de 2021","format":false,"excerpt":"Si bien los fiscales de Estados Unidos suelen ser reacios a nombrar en los casos criminales a presidentes en funciones, esta vez han hecho una excepci\u00f3n con respecto al presidente de Honduras, Juan Orlando Hern\u00e1ndez, indicando claramente que \u00e9l recibi\u00f3 sobornos de narcotraficantes y tuvo participaci\u00f3n de primera mano en\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2021\/03\/21-03-19-JOH-GFR.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":232580,"url":"https:\/\/insightcrime.org\/es\/noticias\/guerra-antipandillas-honduras-ataca-fuente-violencia\/","url_meta":{"origin":7268,"position":4},"title":"Guerra antipandillas en Honduras ataca solo una fuente de violencia","author":"Sean Doherty","date":"28 de junio de 2023","format":false,"excerpt":"El gobierno de Honduras ha intensificado su campa\u00f1a contra las pandillas tras los recientes estallidos de violencia criminal, pero su respuesta limitada pasa por alto las variadas din\u00e1micas de crimen organizado en juego.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/706048f0-1433-11ee-924b-8104a08ea010-e1687984610513-1.jpg?fit=349%2C249&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":171117,"url":"https:\/\/insightcrime.org\/es\/news\/ms13-en-honduras-ampliando-papel-trafico-regional-drogas\/","url_meta":{"origin":7268,"position":5},"title":"\u00bfLa MS13 en Honduras est\u00e1 ampliando su papel en el tr\u00e1fico regional de drogas?","author":"Parker Asmann","date":"5 de noviembre de 2021","format":false,"excerpt":"Un presunto l\u00edder de la MS13 en Honduras y uno de sus c\u00f3mplices fueron acusados de tr\u00e1fico internacional de coca\u00edna por parte de fiscales estadounidenses, lo que plantea nuevas preguntas sobre el papel de la pandilla en el tr\u00e1fico regional de drogas.","rel":"","context":"En \u00abNews\u00bb","block_context":{"text":"News","link":"https:\/\/insightcrime.org\/category\/news\/"},"img":{"alt_text":"presunto l\u00edder de MS13 en Honduras","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2021\/11\/21-11-04-El-Porky-Honduras.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2014\/10\/es-20141013_honduras_fiscales.jpeg?fit=362%2C240&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/7268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=7268"}],"version-history":[{"count":1,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/7268\/revisions"}],"predecessor-version":[{"id":23443,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/7268\/revisions\/23443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/41356"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=7268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=7268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=7268"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=7268"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=7268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}