{"id":8131,"date":"2015-08-27T20:35:53","date_gmt":"2017-03-28T00:10:59","guid":{"rendered":"http:\/\/newwp.insightcrime.org?p=8131"},"modified":"2023-04-24T15:47:33","modified_gmt":"2023-04-24T20:47:33","slug":"asesinatos-entre-pandilleros-historia-nunca-acabar-honduras","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/noticias\/analisis\/asesinatos-entre-pandilleros-historia-nunca-acabar-honduras\/","title":{"rendered":"Asesinatos entre pandilleros: La historia de nunca acabar en Honduras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El ajuste de cuentas entre pandilleros de una misma organizaci\u00f3n dentro de los penales hondure\u00f1os es una pr\u00e1ctica hist\u00f3rica y recurrente. Las c\u00e1rceles de este pa\u00eds se han ba\u00f1ado de sangre pandillera por 16 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tan solo en marzo pasado, luego de que el gobierno del presidente Juan Orlando Hern\u00e1ndez removiera al menos 105 presos a diferentes centros penales, como parte de su operaci\u00f3n \u201cCero Privilegios\u201d, pandilleros de Barrio 18 se asesinaron entre ellos en pugnas internas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 11 de marzo los principales l\u00edderes de esta pandilla: Nahum Montes Medina, alias \u201cTacoma;\u201d Howen Alexis Romero, alias \u201cRat\u00f3n\u201d y Olv\u00edn Reinaldo Arriaga Baca, alias \u201cPorqui\u201d fueron removidos del penal de San Pedro Sula con el prop\u00f3sito de debilitar a la pandilla en prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nueve d\u00edas despu\u00e9s, siete miembros de Barrio 18 fueron estrangulados por compa\u00f1eros tanto en el penal de T\u00e1mara y San Pedro Sula, supuestamente por intentar abusar sexualmente de algunas visitas de sus compa\u00f1eros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actos similares han demostrado a lo largo de los a\u00f1os el modo en que los pandilleros resuelven sus pugnas internas, generalmente para reacomodar l\u00edderes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mejor ejemplo es la primera batalla entre compa\u00f1eros de la Mara Salvatrucha (MS13) ocurrido en 2000, una historia que ha permanecido en el silencio por a\u00f1os, pero hoy revelamos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La ruptura del \u201cSUR\u201d<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En 1997 los internos del penal de San Pedro Sula replicaron el modelo carcelario de California llamado SUR (South Union Race por sus iniciales en ingl\u00e9s), un concepto donde pandillas enemigas se toleran y se protegen al interior del presidio para enfrentar a otras organizaciones criminales, mientras que en las calles siguen manteniendo enemistad. La tregua dur\u00f3 cerca de dos a\u00f1os hasta que su ruptura signific\u00f3 un quiebre en la l\u00f3gica pandilleril, desencaden\u00f3 las primeras muertes entre pandilleros, seg\u00fan el testimonio de un par de mareros que lo vivieron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era 1999, el penal sampedrano reclu\u00eda en un mismo m\u00f3dulo <span style=\"font-size: 12pt;line-height: 115%;font-family: 'Times New Roman','serif'\">\u2014<\/span>y sin barreras f\u00edsicas<span style=\"font-size: 12pt;line-height: 115%;font-family: 'Times New Roman','serif'\">\u2014<\/span> a las pandillas Mara Salvatrucha (MS13), Barrio 18, Wanderer 13, La 75, Sunseri, Poison, Barrio Pobre y Vatos Locos.<\/p>\n\n\n\n<div class=\"pull-quotes-right\">\n<div class=\"pull-quotes-body\">Saybo murmura y repite que Geo \u201cnos vendi\u00f3, nos vendi\u00f3\u201d.<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para entonces, Barrio 18 era mayor en n\u00famero. Quienes estuvieron all\u00ed calculan que eran cerca de 80 reclusos de Barrio 18 y apenas 30 de la MS13. La expansi\u00f3n de Barrio 18 no fue exclusivamente num\u00e9rica, sino espacial y de influencia, tanto que al interior contaba con un perro pitbull color negro llamado Little Satan\u00e1s. Para cuando Little Satan\u00e1s estaba a manos de Barrio 18, la gente de la MS13 se sent\u00eda amenazada en el SUR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geofredo Cort\u00e9s Ortiz, alias \u201cGeo\u201d, de la MS13, era el \u201cpalabrero\u201d de la pandilla y, por consiguiente, el representante de la misma en el SUR. Hab\u00eda sido deportado de Los \u00c1ngeles y tra\u00eda consigo un historial delictivo que ocult\u00f3 por largo tiempo a la pandilla. Durante su vida en California fue miembro de la pandilla Play Boys, enemiga mortal de la MS13. Repatriado, el instinto de sobrevivencia lo oblig\u00f3 a camuflarse como marero para sobrevivir en Honduras. Geo estaba en la boca del lobo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el lado de Barrio 18, quien dirig\u00eda las huestes era \u201cSpanky\u201d, un joven salvadore\u00f1o que cumpl\u00eda condena en San Pedro Sula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ambiente que se viv\u00eda en el m\u00f3dulo jam\u00e1s fue de armon\u00eda y menos para finales de 1999 cuando el clima se volvi\u00f3 m\u00e1s tenso. Los desacuerdos entre pandillas desataron el rumor de que el SUR terminar\u00eda. As\u00ed que inquietos, los pandilleros de la MS13 pensaron romper la tregua antes de ser v\u00edctimas y se lo manifestaron a Geo en m\u00e1s de una ocasi\u00f3n, quien como respuesta les pidi\u00f3 mantener la calma.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La traici\u00f3n de Geo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSaybo\u201d es quien ha narrado la mayor parte de esta historia porque estuvo ah\u00ed. Tiene 12 a\u00f1os de haberse retirado de la MS13 y es por eso que lleva tachadas las letras de tinta de la pandilla en sus hombros. Desde el interior del penal de T\u00e1mara, al norte de Tegucigalpa, asegura m\u00e1s de una vez que Geo traicion\u00f3 a la MS13.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geo sab\u00eda realmente que Barrio 18 estaba planeando atacar a la MS13, el mismo Spanky, l\u00edder de Barrio 18, se lo dijo. Spanky tambien le dijo a Geo que desarmara a sus compa\u00f1eros si quer\u00eda evitarse una muerte nauseabunda a manos de ellos. Geo deb\u00eda retirar todos los machetes hechizos a sus compa\u00f1eros y apaciguarlos con la idea de que el SUR se respetar\u00eda, que nada pasar\u00eda. Saybo escucho a Geo decir estas palabras m\u00e1s de una vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plan para entregar a la MS13 era una estrategia que no s\u00f3lo consist\u00eda en corromper a su l\u00edder, ten\u00eda el respaldo de los guardias del penal y del resto de las pandillas. Por eso en una ocasi\u00f3n los custodios realizaron un decomiso sorpresa a la MS13 donde les encontr\u00f3 un arsenal de machetes hechizos que previamente Geo les hab\u00eda levantado con el pretexto de que la paz todav\u00eda reinaba en el SUR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #800000\">VEA TAMBI\u00c9N:<\/span><\/strong> <a target=\"_blank\" href=\"\/noticias-sobre-crimen-organizado-en-el-salvador\/mara-salvatrucha-ms-13\">Noticias y perfil de MS13<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte del plan con Spanky, el l\u00edder del Barrio 18, Geo fue acusado por las armas decomisadas y encerrado en una celda de castigo junto a su compa\u00f1ero Cuervo. La MS13 eligi\u00f3 de emergencia a Oso y Soro como representantes de la pandilla, quedando debilitada y desarmada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos semanas despu\u00e9s y siguiendo la maquinaci\u00f3n, integrantes de la pandilla La 75 cortaron el cable que abastec\u00eda de electricidad a la secci\u00f3n de la MS13, enardeciendo los \u00e1nimos. La provocaci\u00f3n ten\u00eda el objetivo de enervar a los miembros de la MS13 para responder la agresi\u00f3n para ser sancionados por las autoridades del SUR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oso y Soro siguiendo los protocolos hablaron con dem\u00e1s l\u00edderes del Barrio 18 y otras pandillas como los Vatos Locos y los Wanderers 13. Narraron lo sucedido, quer\u00edan un enfrentamiento uno a uno y a pu\u00f1o limpio con el responsable. Los representantes del SUR accedieron maquiav\u00e9licamente a que se realizara ese enfrentamiento a golpes para solucionar el problema. Las pandillas hab\u00edan acordado atacar a la MS13 en cuanto comenzara la justa contra La 75.<\/p>\n\n\n\n<div class=\"pull-quotes\">\n<div class=\"pull-quotes-body\">Varios estaban acostados en sus camas cuando comenzaron a llover machetazos. Saybo y un pu\u00f1ado lograron huir por un peque\u00f1o boquete ubicado en el techo de la secci\u00f3n. Geo los hab\u00eda traicionado<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Y as\u00ed sucedi\u00f3, el 12 de noviembre mientras oscurec\u00eda, los guardias pusieron candado a las puertas para que nadie saliera. Armados con pedazos de metal afilados miembros de Barrio 18, Wanderers 13, Barrio Pobre, La 75, Posion y Sunseri desgarraron y atravesaron sin escr\u00fapulos a varios miembros de la MS13 y Vatos Locos durante casi una hora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Varios estaban acostados en sus camas cuando comenzaron a llover machetazos. Saybo y un pu\u00f1ado lograron huir por un peque\u00f1o boquete ubicado en el techo de la secci\u00f3n. Geo los hab\u00eda traicionado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcio Arturo S\u00e1nchez, alias Recio y miembro de la MS13, antes de reducirse a cenizas el 14 de febrero de 2012 cuando el penal de Comayagua se quem\u00f3, se dedic\u00f3 a escribir tres peque\u00f1os libros donde describi\u00f3 el desenlace de aquel ba\u00f1o de sangre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cV\u00ed como un pandillero de Barrio 18 le cortaba la cabeza a un miembro de la MS13, me detuve y les pregunt\u00e9 acerca de que pasaba con el SUR. El diablo se hab\u00eda apoderado de sus mentes repentinamente\u201d, escribi\u00f3 en su libro \u201cErrores y secretos de las maras\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"color: #800000\">VEA TAMBI\u00c9N:<\/span><\/strong> <a target=\"_blank\" href=\"\/noticias-sobre-crimen-organizado-en-el-salvador\/barrio-18\">Noticias y perfil de Barrio 18<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El saldo fue de 11 muertos y 31 heridos, dos pertenecientes a los Vatos Locos y el resto a la MS13. Todos murieron a punta de armas cortopunzantes como lo indicaba un reporte de la Comisi\u00f3n Interamericana de Derechos Humanos. Los cuerpos presentaban m\u00faltiples laceraciones, estaban irreconocibles. Algunos no ten\u00edan cabeza y otros m\u00e1s no ten\u00edan orejas, varias de ellas se las dieron de tragar a Little Satan\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTen\u00edamos un perro que se comi\u00f3 algunos de los cuerpos que lastimosamente fueron asesinados\u201d recuerda Scrappy, un viejo miembro de Barrio 18, asesinado un par de a\u00f1os atr\u00e1s, pero que ese d\u00eda se manufactur\u00f3 un collar con las orejas de las v\u00edctimas como s\u00edmbolo de victoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La escena era un batidero de v\u00edsceras. Sobrevivientes de la MS13 y Vatos Locos fueron reacomodados y aislados en una escuela del penal. La matanza termin\u00f3 con el SUR y comenz\u00f3 una guerra dentro de la MS13.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geo y Cuervo fueron trasladados al centro penal de T\u00e1mara cinco d\u00edas despu\u00e9s como medida preventiva. Permanecieron apartados por un a\u00f1o hasta que sus compa\u00f1eros relacionaron los hechos y pagaron un abogado para transferirlos nuevamente a la prisi\u00f3n sampedrana. Saybo murmura y repite que Geo \u201cnos vendi\u00f3, nos vendi\u00f3\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El brutal asesinato de Geo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una reuni\u00f3n dentro del penal se celebr\u00f3 antes de la llegada de Geo para decidir c\u00f3mo asesinarlo, eso significaba la primera orden de muerte en contra de un compa\u00f1ero. Geo deb\u00eda pagar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su cacer\u00eda abri\u00f3 un cap\u00edtulo nuevo para la MS13. \u201cEl Veloz\u201d, un miembro de la pandilla, le relat\u00f3 a un custodio el plan para asesinar a Geo, revelaci\u00f3n que le cost\u00f3 la vida. Esa fuga de informaci\u00f3n nuevamente puso en un dilema a la MS13 quienes deb\u00edan tambi\u00e9n asesinar su primer delator, seg\u00fan Saybo. El Veloz inesperadamente se le adelant\u00f3 a Geo, y tambi\u00e9n deb\u00eda pagar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saybo describe con sus manos y sin ninguna se\u00f1al de dolor como El Veloz fue golpeado y despu\u00e9s atravesado con un fierro en la garganta por parte de \u201cEl Piojo\u201d.\u201d\u00a1Los sapos deben morir!\u201d, es el grito que a\u00fan recuerda Saybo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A un a\u00f1o de lo sucedido, lleg\u00f3 Geo. En el penal los compa\u00f1eros estaban listos y realizaron una reuni\u00f3n donde se le pidi\u00f3 que explicara lo sucedido en 1999.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo se necesita m\u00e1s, pasa al frente\u201d, le ordenaron. Atormentado, no se atrev\u00eda a dar un paso adelante, describe Saybo. Entonces alguien lo puso en el centro. Apenas comenz\u00f3 a decir palabra cuando lo obligaron a callarse. \u201cPara hablar a la MS13 tienes que tener respeto\u201d, le reprocharon. Entonces lo obligaron a hincarse.<\/p>\n\n\n\n<div class=\"pull-quotes\">\n<div class=\"pull-quotes-body\">En ese momento Shaggy pas\u00f3 sigilosamente con un fierro afilado por su espalda sin que se percatara e inesperadamente y de manera abrupta lo atraves\u00f3 dejando ver el machete por el pecho<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHasta llor\u00f3, pidi\u00f3 perd\u00f3n y todo, hincado\u201d, recuerda a m\u00e1s de diez a\u00f1os, a quien es ampliamente considerado como el primer pandillero de la MS13 en Honduras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le dieron la oportunidad de defenderse y con l\u00e1grimas en los ojos argument\u00f3 que gracias a \u00e9l la pandilla se hab\u00eda expandido por Honduras. En ese momento \u201cShaggy\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">pas\u00f3 sigilosamente con un fierro afilado por su espalda sin que se percatara e inesperadamente y de manera abrupta lo atraves\u00f3 dejando ver el machete por el pecho. De inmediato Largo se fue al acecho para \u201cpedacearlo\u201d con un cuchillo, como describe Saybo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agonizando se tir\u00f3 al suelo mientras los orificios de su cuerpo borboteaban sangre. El pandillero \u201cAguila\u201d salt\u00f3 de su cama y con furia le clav\u00f3 un enorme pedazo de fierro en el coraz\u00f3n. En un reflejo Geo se levant\u00f3, pero pronto una multitud de pandilleros comenzaron a rematarlo. Entre ellos Saybo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El boquete que ten\u00eda a la altura del coraz\u00f3n permiti\u00f3 que los compa\u00f1eros le retiraran el \u00f3rgano a pedazos y con la mano. Lo arrastraron al ba\u00f1o y lo subieron a las pilas de lavabo para decapitarlo. Con la cabeza comenzaron a patearla como si a\u00fan muerto se le pudiese faltar al respeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, en las pilas los pandilleros rebanaban y desmembraban el cuerpo con navajas Gillete. Cada extremidad de Geo era pasada entre los miembros con el prop\u00f3sito de reducir su cuerpo a la materia m\u00e1s m\u00ednima. Los restos de tejido fueron echados por la tuber\u00eda de los ba\u00f1os. A las afueras nadie se percataba. Una televisi\u00f3n con alto volumen ayud\u00f3 a disipar el ruido y los gritos. Era el 8 de octubre de 2000.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un saco echaron los huesos y con las pesas de ejercicio molieron cada uno de los restos \u00f3seos hasta reducirlos a polvo. Saybo asegura que el cr\u00e1neo pateado fue la \u00faltima extremidad en desaparecer, ten\u00eda tatuada las letras MS, y hab\u00edan que respetarlas hasta el final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ah\u00ed qued\u00f3 Geo y ah\u00ed qued\u00f3 la primer evidencia de c\u00f3mo los pandilleros ajustan cuentas en las prisiones hondure\u00f1as.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ajuste de cuentas entre pandilleros de una misma organizaci\u00f3n dentro de los penales hondure\u00f1os es una pr\u00e1ctica hist\u00f3rica y recurrente. Las c\u00e1rceles de este pa\u00eds se han ba\u00f1ado de sangre pandillera por 16 a\u00f1os.<\/p>\n","protected":false},"author":45,"featured_media":43041,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[340],"tags":[375,398,1500,3021],"newspack_spnsrs_tax":[],"coauthors":[3971],"class_list":["post-8131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-barrio-18-grupo","tag-honduras-pais","tag-ms13-es","tag-prisiones-es","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/noticias\/analisis\/asesinatos-entre-pandilleros-historia-nunca-acabar-honduras\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Asesinatos entre pandilleros: La historia de nunca acabar en Honduras","url":"http:\/\/insightcrime.org\/es\/noticias\/analisis\/asesinatos-entre-pandilleros-historia-nunca-acabar-honduras\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/noticias\/analisis\/asesinatos-entre-pandilleros-historia-nunca-acabar-honduras\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2015\/08\/es-15-08-19-Honduras-MS13-Prison.png?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2015\/08\/es-15-08-19-Honduras-MS13-Prison.png?fit=250%2C180&quality=100&ssl=1"},"articleSection":"An\u00e1lisis","author":[{"@type":"Person","name":"Carlos Garcia"}],"creator":["Carlos Garcia"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["barrio 18","honduras","ms13","prisiones"],"dateCreated":"2017-03-28T00:10:59Z","datePublished":"2017-03-28T00:10:59Z","dateModified":"2023-04-24T20:47:33Z"},"rendered":"<meta name=\"parsely-title\" content=\"Asesinatos entre pandilleros: La historia de nunca acabar en Honduras\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/noticias\/analisis\/asesinatos-entre-pandilleros-historia-nunca-acabar-honduras\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2015\/08\/es-15-08-19-Honduras-MS13-Prison.png?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2017-03-28T00:10:59Z\" \/>\n<meta name=\"parsely-section\" content=\"An\u00e1lisis\" \/>\n<meta name=\"parsely-tags\" content=\"barrio 18,honduras,ms13,prisiones\" \/>\n<meta name=\"parsely-author\" content=\"Carlos Garcia\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":232637,"url":"https:\/\/insightcrime.org\/es\/noticias\/masacre-penal-femenino-honduras-tragedia-anunciada\/","url_meta":{"origin":8131,"position":0},"title":"Masacre en penal femenino de Honduras: una tragedia anunciada\u00a0","author":"Victoria Dittmar","date":"21 de junio de 2023","format":false,"excerpt":"El asesinato de decenas de mujeres en el penal femenino de Honduras ocurri\u00f3 en un contexto de creciente tensi\u00f3n entre pandillas.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Humo sale del penal del PNFAS en Honduras, donde 48 mujeres fueron asesinadas en violencia entre pandillas","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/af09886383-1-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6313,"url":"https:\/\/insightcrime.org\/es\/noticias-crimen-organizado-el-salvador\/barrio-18-perfil-2\/","url_meta":{"origin":8131,"position":1},"title":"Barrio 18","author":"InSight Crime","date":"14 de noviembre de 2023","format":false,"excerpt":"La pandilla 18, tambi\u00e9n conocida como Barrio 18, es una de las maras m\u00e1s numerosas del hemisferio occidental, equiparable en muchos aspectos a su rival m\u00e1s conocido, la Mara Salvatrucha (MS13). Aunque la pandilla tiene c\u00e9lulas en operaci\u00f3n desde Centroam\u00e9rica hasta Canad\u00e1, se ha debilitado mucho en El Salvador despu\u00e9s\u2026","rel":"","context":"En \u00abEl Salvador\u00bb","block_context":{"text":"El Salvador","link":"https:\/\/insightcrime.org\/es\/category\/noticias-crimen-organizado-el-salvador\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Grupo-Criminal-Barrio-18.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Grupo-Criminal-Barrio-18.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Grupo-Criminal-Barrio-18.jpg?fit=1200%2C900&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Grupo-Criminal-Barrio-18.jpg?fit=1200%2C900&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/11\/Grupo-Criminal-Barrio-18.jpg?fit=1200%2C900&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":267310,"url":"https:\/\/insightcrime.org\/es\/noticias\/inseguridad-persiste-tras-investigacion-masacre-honduras\/","url_meta":{"origin":8131,"position":2},"title":"Persisten preocupaciones de seguridad a pesar de acusaciones por masacre en prisi\u00f3n femenina de Honduras","author":"Victoria Dittmar","date":"5 de febrero de 2024","format":false,"excerpt":"A m\u00e1s de medio a\u00f1o de la masacre m\u00e1s mort\u00edfera en una prisi\u00f3n femenina en Latinoam\u00e9rica, el gobierno de Honduras comienza a mostrar avances en la investigaci\u00f3n de los hechos, pero a\u00fan se queda corto en cambios sist\u00e9micos de seguridad.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Honduras has moved to indict nine women accused of their participation in a prison massacre that claimed the lives of 46 female prisoners. Honduras ha tomado medidas para procesar a nueve mujeres acusadas de su participaci\u00f3n en una masacre carcelaria que se cobr\u00f3 la vida de 46 reclusas.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/02\/PNFAS-Honduras.jpeg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":273259,"url":"https:\/\/insightcrime.org\/es\/noticias\/como-investigamos-masacre-prision-femenina-honduras\/","url_meta":{"origin":8131,"position":3},"title":"Detr\u00e1s de la historia: C\u00f3mo investigamos la masacre en la prisi\u00f3n femenina de Honduras","author":"InSight Crime","date":"10 de abril de 2024","format":false,"excerpt":"El 16 de agosto de 2023, InSight Crime public\u00f3 una investigaci\u00f3n sobre una de las masacres m\u00e1s mort\u00edferas registradas en una prisi\u00f3n femenina en Latinoam\u00e9rica. En un reciente espacio de Twitter, dos de nuestras investigadoras conversaron sobre la metodolog\u00eda de la investigaci\u00f3n, las impresiones acerca de la PNFAS, y el\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Women survivors of the massacre in the Honduras women's prison. \n","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2024\/04\/Honduras-PNFAS-Modulo-1-Sobrevivientes-prision-genero-crimen-Instituto-Nacional-Penitenciario.jpeg?fit=1024%2C768&quality=100&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":148965,"url":"https:\/\/insightcrime.org\/es\/noticias\/ejercito-honduras-duras-criticas-actos-violentos-carceles\/","url_meta":{"origin":8131,"position":4},"title":"Ej\u00e9rcito de Honduras recibe duras cr\u00edticas tras actos violentos en c\u00e1rceles","author":"Chris Dalby","date":"21 de junio de 2021","format":false,"excerpt":"Una masacre entre las pandillas Barrio 18 y MS13 en la prisi\u00f3n m\u00e1s tristemente c\u00e9lebre de Honduras plantea dudas acerca de si el papel del ej\u00e9rcito est\u00e1 siendo efectivo, tras haber asumido la responsabilidad de la seguridad de las prisiones en diciembre de 2019.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"An ambulance enters La Tolva Prison in Honduras","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2021\/06\/Carcel-LaTolva.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":232580,"url":"https:\/\/insightcrime.org\/es\/noticias\/guerra-antipandillas-honduras-ataca-fuente-violencia\/","url_meta":{"origin":8131,"position":5},"title":"Guerra antipandillas en Honduras ataca solo una fuente de violencia","author":"Sean Doherty","date":"28 de junio de 2023","format":false,"excerpt":"El gobierno de Honduras ha intensificado su campa\u00f1a contra las pandillas tras los recientes estallidos de violencia criminal, pero su respuesta limitada pasa por alto las variadas din\u00e1micas de crimen organizado en juego.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/706048f0-1433-11ee-924b-8104a08ea010-e1687984610513-1.jpg?fit=349%2C249&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2015\/08\/es-15-08-19-Honduras-MS13-Prison.png?fit=250%2C180&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/8131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=8131"}],"version-history":[{"count":3,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/8131\/revisions"}],"predecessor-version":[{"id":71487,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/8131\/revisions\/71487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/43041"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=8131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=8131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=8131"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=8131"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=8131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}