{"id":8682,"date":"2016-04-09T11:36:21","date_gmt":"2016-04-09T16:36:21","guid":{"rendered":"http:\/\/newwp.insightcrime.org?p=8682"},"modified":"2023-10-25T11:09:27","modified_gmt":"2023-10-25T16:09:27","slug":"elites-crimen-organizado-honduras-juan-ramon-matta-ballesteros","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/investigaciones\/elites-crimen-organizado-honduras-juan-ramon-matta-ballesteros\/","title":{"rendered":"\u00c9lites y crimen organizado en Honduras: Juan Ram\u00f3n Matta Ballesteros"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la ma\u00f1ana del 5 de abril de 1988, Juan Ram\u00f3n Matta Ballesteros sali\u00f3 de su mansi\u00f3n en Tegucigalpa para irse a trotar. Matta Ballesteros era buscado por asesinato, narcotr\u00e1fico y otros cr\u00edmenes en varios pa\u00edses, pero en Honduras se sent\u00eda seguro. Sol\u00eda organizar fiestas con altos funcionarios en su casa, y ten\u00eda conexiones con oficiales militares.<sup>1<\/sup> &nbsp;En sus negocios legales empleaba miles de lugare\u00f1os, quienes lo honraban porque prove\u00eda medicinas, constru\u00eda escuelas y hac\u00eda donaciones a causas ben\u00e9ficas.<sup>2<\/sup> &nbsp;Se dice que una vez le ofreci\u00f3 al gobierno pagar la creciente deuda externa, ofrecimiento que al parecer por lo menos un pol\u00edtico lo tom\u00f3 en serio.<sup>3<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Matta Ballesteros tambi\u00e9n les hab\u00eda ayudado a los militares hondure\u00f1os y a Estados Unidos en su lucha contra el comunismo en la regi\u00f3n. Mediante una aerol\u00ednea que \u00e9l hab\u00eda establecido, Estados Unidos enviaba suministros a los Contras, grupo contrarrevolucionario nicarag\u00fcense, debido a la guerra de poder de Washington contra el gobierno sandinista que hab\u00eda tomado el poder tras derrocar en 1979 a la dictadura corrupta de Nicaragua, que era apoyada por Estados Unidos. El gobierno de Estados Unidos le hac\u00eda pagos a su aerol\u00ednea por la ayuda prestada, a pesar de que la propia Administraci\u00f3n para el Control de Drogas de Estados Unidos (DEA por sus iniciales en ingl\u00e9s) hab\u00eda clasificado a Matta Ballesteros en la Categor\u00eda I de los \u201ctransgresores de la DEA\u201d.<sup>4<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando Matta Ballesteros regres\u00f3 de trotar, descubri\u00f3 con sorpresa que lo estaban esperando militares y polic\u00edas hondure\u00f1os, as\u00ed como cuatro mariscales. Un mariscal estadounidense que estaba en el lugar dijo que Matta Ballesteros intent\u00f3 huir pero fue capturado. Se present\u00f3 un forcejeo. \u201cDurante el forcejeo, tanto Matta Ballesteros como los oficiales hondure\u00f1os lanzaron pu\u00f1etazos y patadas\u201d, escribi\u00f3 m\u00e1s adelante el mariscal en una declaraci\u00f3n juramentada.<sup>5<\/sup> &nbsp;\u201cDe repente vi que Matta Ballesteros hab\u00eda sido derribado al suelo, en un intento por detenerlo\u201d.<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile has-background\" style=\"background-color:#f4f6f3;grid-template-columns:24% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/Elites_Crimen_Organizado_Honduras.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"1024\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM.png?resize=790%2C1024&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-242213 size-full\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM.png?resize=790%2C1024&amp;quality=100&amp;ssl=1 790w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM.png?resize=232%2C300&amp;quality=100&amp;ssl=1 232w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM.png?resize=768%2C995&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM.png?resize=400%2C518&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM.png?resize=706%2C915&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM.png?w=1096&amp;quality=100&amp;ssl=1 1096w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-17-at-6.55.44-PM-790x1024.png?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 790px) 100vw, 790px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-color has-small-font-size wp-block-paragraph\" style=\"color:#161616ad;font-style:normal;font-weight:400;letter-spacing:0px\"><em>*<\/em>Este art\u00edculo es parte de una serie que estudia la relaci\u00f3n entre \u00e9lites y crimen organizado. Lea el informe completo de Honduras (<a href=\"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/Elites_Crimen_Organizado_Honduras.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">pdf<\/a>). Vea las otras partes de la serie <a href=\"https:\/\/insightcrime.org\/es\/investigaciones\/elites-y-crimen-organizado-en-honduras\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a>.<\/p>\n<\/div><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"182\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/RAMON-MATTA-3.jpg?resize=250%2C182&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244468\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/RAMON-MATTA-3.jpg?w=250&amp;quality=100&amp;ssl=1 250w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/RAMON-MATTA-3.jpg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/RAMON-MATTA-3.jpg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Las autoridades hondure\u00f1as finalmente acorralaron a Matta Ballesteros cerca del veh\u00edculo que el mariscal conduc\u00eda, lo esposaron, pusieron una capucha negra sobre su cabeza y lo obligaron a entrar al coche. Matta Ballesteros sigui\u00f3 forcejeando, pidiendo misericordia y pateando la puerta del coche, que ya hab\u00eda sido cerrada. \u201cNo me hagan esto, por favor\u201d, gritaba. \u201cNo me entreguen a los gringos\u201d.<sup>6<\/sup>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Matta Ballesteros ten\u00eda raz\u00f3n de estar preocupado. En Honduras pod\u00eda ser un hombre altamente influyente, pero Estados Unidos lo requer\u00eda por la muerte de un agente de la DEA en M\u00e9xico, y all\u00ed enfrentar\u00eda la pena de muerte. \u201cYo no tuve nada que ver con eso\u201d, gritaba, probablemente refiri\u00e9ndose a la muerte del agente. \u201cD\u00e9jenme ver a mis hijos por \u00faltima vez. Ellos me van a matar\u201d.<sup>7<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el carro del mariscal hab\u00eda dos polic\u00edas hondure\u00f1os y un escolta militar, quienes condujeron a Matta Ballesteros a una base de la fuerza a\u00e9rea hondure\u00f1a a una hora de distancia. All\u00ed las autoridades de Estados Unidos y Honduras lo embarcaron en un avi\u00f3n y lo llevaron a Rep\u00fablica Dominicana. Menos de 24 horas m\u00e1s tarde se encontraba en una prisi\u00f3n de Estados Unidos enfrentando cargos de secuestro, asesinato y narcotr\u00e1fico.<sup>8<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando apareci\u00f3 la noticia del extraordinario sometimiento de Matta Ballesteros, Honduras entr\u00f3 en conmoci\u00f3n. El ej\u00e9rcito guard\u00f3 silencio en cuanto al arresto y el presidente habl\u00f3 de \u201cexpulsar\u201d al supuesto asesino y narcotraficante.<sup>9<\/sup> &nbsp;Pero el 6 de abril, unos 300 manifestantes marcharon hacia el centro de Tegucigalpa; esa noche, varios estudiantes quemaron una bandera de Estados Unidos y una copia de la Constituci\u00f3n hondure\u00f1a frente al Congreso.<sup>10<\/sup> &nbsp;Varios congresistas y juristas reprocharon a los militares y la polic\u00eda por el \u201csecuestro\u201d, as\u00ed como a los tribunales que ordenaron la b\u00fasqueda y confiscaci\u00f3n de las propiedades de Matta Ballesteros.<sup>11<\/sup> &nbsp;El 8 de abril, al menos mil manifestantes marcharon hacia la embajada de Estados Unidos.<sup>12<\/sup> &nbsp;En el alboroto que sigui\u00f3, un anexo de la embajada de Estados Unidos fue incendiado, as\u00ed como unos 20 veh\u00edculos;<sup>13<\/sup> &nbsp;se hicieron varios disparos y murieron cinco personas. D\u00edas despu\u00e9s los medios de comunicaci\u00f3n dijeron que \u201clas protestas m\u00e1s violentas contra EUA en Latinoam\u00e9rica\u201d.<sup>14<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El incidente en la embajada fue la culminaci\u00f3n de una retorcida y sanguinaria relaci\u00f3n entre Matta Ballesteros, el ej\u00e9rcito y el gobierno de Estados Unidos. Relaci\u00f3n que se encuentra en la base de un fen\u00f3meno muy importante en Honduras, que implica el desarrollo de una \u00e9lite relativamente nueva. Este grupo no hac\u00eda parte de las \u00e9lites tradicionales o transnacionales que por largo tiempo hab\u00edan controlado los recursos econ\u00f3micos del pa\u00eds y dirigido sus riendas pol\u00edticas. Por el contrario, surgi\u00f3 de las fuerzas armadas, una instituci\u00f3n tradicionalmente considerada como m\u00fasculo de la \u00e9lite, y no como su cerebro. Y aqu\u00ed es donde debemos empezar esta historia.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-antecedentes-el-surgimiento-de-los-militares-hondurenos-como-una-elite-burocratica\">Antecedentes \u2013 El surgimiento de los militares hondure\u00f1os como una \u00e9lite burocr\u00e1tica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las fuerzas armadas hondure\u00f1as han estado siempre en la cima de la pir\u00e1mide del gobierno, o muy cerca de ella, pero no siempre han tenido el poder directamente. Por m\u00e1s de cien a\u00f1os despu\u00e9s de su fundaci\u00f3n en 1825,<sup>15<\/sup> &nbsp;el ej\u00e9rcito particip\u00f3 en las guerras civiles y en las agitaciones pol\u00edticas, a veces en los m\u00e1rgenes y otras veces liderando eventos que m\u00e1s tarde fueron caracterizados como \u201clevantamientos revolucionarios\u201d. En varias ocasiones, los generales se convirtieron en presidentes tras sus victorias en el campo de batalla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El m\u00e1s representativo fue el general Francisco Moraz\u00e1n. Considerado como el Sim\u00f3n Bol\u00edvar centroamericano, Moraz\u00e1n se convirti\u00f3 en presidente de la Confederaci\u00f3n Centroamericana antes de que se desintegrara al final de la d\u00e9cada de los treinta del siglo XIX. Moraz\u00e1n sigue presente en los nombres de provincias, parques, calles y una academia militar en Honduras. Los pol\u00edticos de la \u00e9poca se hab\u00edan forjado esencialmente en los campos de batalla, pero los militares no dirig\u00edan las riendas del poder. Se puede decir m\u00e1s bien que durante este per\u00edodo eran los protectores de los intereses de los dem\u00e1s en lugar de un actor pol\u00edtico y econ\u00f3mico como tal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"714\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/honduras-es.png?resize=1000%2C714&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244628\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/honduras-es.png?w=1000&amp;quality=100&amp;ssl=1 1000w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/honduras-es.png?resize=300%2C214&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/honduras-es.png?resize=768%2C548&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/honduras-es.png?resize=400%2C286&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/honduras-es.png?resize=706%2C504&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/honduras-es.png?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, durante sus primeros cien a\u00f1os, el ej\u00e9rcito estaba organizado en peque\u00f1os enclaves, era una fuerza dividida, con estructura poco centralizada y sin alcance nacional. Estas fuerzas dispares proteg\u00edan inicialmente los intereses de las \u00e9lites tradicionales, es decir, a quienes cultivaban cacao y caf\u00e9 y eran due\u00f1os de haciendas ganaderas en esos enclaves. Con el tiempo, su lista de clientes aument\u00f3 y lleg\u00f3 a incluir multinacionales que cultivaban frutas y otros productos,<sup>16<\/sup> \u00a0pero su funci\u00f3n segu\u00eda siendo en gran parte la misma. Y aunque las fuerzas armadas proporcionaban un medio de movilidad social, los militares no ten\u00edan ninguna participaci\u00f3n directa en las actividades econ\u00f3micas que proteg\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de los a\u00f1os treinta, esta situaci\u00f3n empez\u00f3 a cambiar. En 1932, Honduras eligi\u00f3 a un oficial del ej\u00e9rcito como presidente, el general Tiburcio Carias Andino. El gobierno de Carias \u2014 que dur\u00f3 16 a\u00f1os \u2014 es clave para entender c\u00f3mo las fuerzas armadas comenzaron a establecerse como un grupo de intereses independientes y finalmente como una \u00e9lite burocr\u00e1tica. Es en parte por ello por lo que Carias inici\u00f3 el proceso de institucionalizaci\u00f3n de las fuerzas armadas. \u00c9l centraliz\u00f3 la estructura del ej\u00e9rcito y ampli\u00f3 sus alcances. Su administraci\u00f3n cre\u00f3 adem\u00e1s el R\u00e9gimen de Pensiones Militares en 1935. Esta ser\u00eda la base para lo que se llam\u00f3 m\u00e1s tarde el Instituto de Previsi\u00f3n Militar (IPM), que fue un antecedente del sistema nacional de seguridad social y m\u00e1s tarde desfalcar\u00eda a varias empresas estatales importantes.<sup>17<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidencia de Carias marc\u00f3 adem\u00e1s el comienzo de un per\u00edodo en el que el personal militar comenz\u00f3 a ser pol\u00edticamente m\u00e1s activo. El general era militante del Partido Nacional que actuaba en su propio inter\u00e9s y en el de su partido.<sup>18<\/sup> &nbsp;Ello inclu\u00eda el encarcelamiento, la deportaci\u00f3n y \u2014 al parecer \u2014 el asesinato de opositores pol\u00edticos, especialmente del Partido Comunista Hondure\u00f1o y de su rival, el Partido Liberal. Tambi\u00e9n censur\u00f3 a los medios de comunicaci\u00f3n. En esencia, Carias estaba construyendo una casta dentro del ej\u00e9rcito, que trascend\u00eda su identidad militar y pronto influir\u00eda en la toma de decisiones a nivel nacional con regularidad y lograr\u00eda consolidarse econ\u00f3micamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para finales de los a\u00f1os cincuenta, el ej\u00e9rcito estaba listo para dar el siguiente paso. Comenz\u00f3 por absorber a la polic\u00eda civil, convirti\u00e9ndola en una guardia nacional. Luego, en 1963, justo antes de las elecciones generales en las que el candidato presidencial del Partido Liberal parec\u00eda ir tras la victoria, el general Oswaldo L\u00f3pez Arellano lider\u00f3 un golpe militar. El golpe de Estado fue el comienzo de un per\u00edodo de r\u00e9gimen militar casi ininterrumpido que dur\u00f3 hasta 1982, gran parte de \u00e9l bajo L\u00f3pez Arellano. Dado que sus alianzas pol\u00edticas florecieron y se volvieron cada vez m\u00e1s conscientes de sus propios intereses, los militares ya no eran s\u00f3lo un apoderado de las \u00e9lites. Ahora se centrar\u00edan en reforzar y asegurar su propio modus vivendi.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/lopez_arrellano.jpg?resize=250%2C250&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244458\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/lopez_arrellano.jpg?w=250&amp;quality=100&amp;ssl=1 250w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/lopez_arrellano.jpg?resize=150%2C150&amp;quality=100&amp;ssl=1 150w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/lopez_arrellano.jpg?resize=200%2C200&amp;quality=100&amp;ssl=1 200w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/lopez_arrellano.jpg?resize=100%2C100&amp;quality=100&amp;ssl=1 100w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/lopez_arrellano.jpg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/lopez_arrellano.jpg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este cambio fue evidente en varios sentidos. Los militares ampliaron su control sobre los sectores civiles del gobierno. Efectivamente, las fuerzas armadas tomaron el control del Instituto Nacional Agrario (INA) bajo la apariencia de un intento de reforma agraria. Asumieron el control del funcionamiento de las aduanas y de los servicios de patrulla en las fronteras, los aeropuertos y otras infraestructuras vitales. El control de estos puestos les garantiz\u00f3 a los militares acceso a recursos, tanto l\u00edcitos como il\u00edcitos, como se podr\u00e1 constatar mediante las relaciones de algunos funcionarios militares con contrabandistas. Adem\u00e1s, el ej\u00e9rcito aument\u00f3 su participaci\u00f3n en una serie de entidades p\u00fablicas. El portafolio econ\u00f3mico del ej\u00e9rcito se ampli\u00f3, incluyendo desde empresas de telecomunicaciones y pasando por franquicias de armas hasta bancos. Ser parte del ej\u00e9rcito tambi\u00e9n ten\u00eda ventajas econ\u00f3micas. Las empresas ya no pagaban los mismos impuestos de importaci\u00f3n o sobre las ganancias, lo que les daba una ventaja competitiva.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"856\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=1024%2C856&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244630\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=1024%2C856&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=300%2C251&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=768%2C642&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=1536%2C1284&amp;quality=100&amp;ssl=1 1536w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=1200%2C1003&amp;quality=100&amp;ssl=1 1200w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=1568%2C1311&amp;quality=100&amp;ssl=1 1568w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=400%2C334&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?resize=706%2C590&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol.jpg?w=1980&amp;quality=100&amp;ssl=1 1980w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/table1Honduras-productive-sectorEspanol-1024x856.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante este per\u00edodo, militares activos y retirados continuaron fortaleciendo sus v\u00ednculos con la clase pol\u00edtica tradicional. La mayor\u00eda de estos oficiales trabajaban con el Partido Nacional, de orientaci\u00f3n conservadora, pero otros comenzaron a trabajar con el Partido Liberal, que era m\u00e1s centralista. Ambos partidos suministraron miembros de sus gabinetes a los gobiernos militares en las d\u00e9cadas de los sesenta y setenta Dentro de ellos estaba Ram\u00f3n Lobo Sosa un terrateniente y l\u00edder del Partido Nacional que era Ministro de Comunicaciones y Obras P\u00fablicas entre 1965 y 1971 bajo la administraci\u00f3n L\u00f3pez Arrellano. (Luego ser\u00eda diputado y estar\u00eda ligado \u2014 junto con su familia \u2014 al crimen organizado.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las relaciones entre oficiales y pol\u00edticos iniciaron un proceso por el que se hizo m\u00e1s dif\u00edcil distinguir entre estas diversas \u00e9lites. Con mayor frecuencia, sus intereses coincid\u00edan en momentos cruciales de la pol\u00edtica, la econom\u00eda y la sociedad. En el sector privado, altos funcionarios compraron funerarias, cementerios, concesionarios, gasolineras, aserraderos, servicios de autobuses y empresas de seguridad privada. Algunos se hicieron socios de importantes instituciones financieras. Por ejemplo, en 1974, L\u00f3pez Arellano fund\u00f3 el Banco Ficensa, y luego se hizo socio de Credomatic, una empresa de servicios financieros que administra transacciones internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las operaciones desde el interior de las \u00e9lites del pa\u00eds permitieron abrir el camino para otros medios de ascenso social. El poder pol\u00edtico, en combinaci\u00f3n con mayor poder econ\u00f3mico, signific\u00f3 mayor convivencia de estas \u00e9lites. Pronto los hijos de los militares empezaron a casarse con hijos de la \u00e9lite tradicional, estableciendo nuevos linajes pol\u00edtico-militares que actualmente definen sus propios caminos en el poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1981, bajo presi\u00f3n de Estados Unidos, el ej\u00e9rcito anunci\u00f3 que supervisar\u00eda el regreso de los civiles al gobierno. Para entonces, el ej\u00e9rcito se hab\u00eda establecido firmemente como una \u00e9lite burocr\u00e1tica y seguir\u00eda siendo un actor sumamente importante en la pol\u00edtica y en la vida econ\u00f3mica hondure\u00f1a durante la siguiente d\u00e9cada, en parte debido al inter\u00e9s de Estados Unidos en financiar guerras contra sus enemigos en la regi\u00f3n. La ayuda militar de Estados Unidos a Honduras ascendi\u00f3 a US$333 millones desde 1980 hasta 1989 (en d\u00f3lares de 2011), la segunda ayuda en la regi\u00f3n despu\u00e9s de El Salvador.<sup>19<\/sup> &nbsp;La ayuda general de Estados Unidos a Honduras tambi\u00e9n se dispar\u00f3, llegando a US$289,1 millones en 1985, y la mayor parte de esta ayuda no estaba dirigida a los militares;<sup>20<\/sup> &nbsp;en esa d\u00e9cada, Estados Unidos ofreci\u00f3 cerca de US$2.500 millones (d\u00f3lares de 2011) en ayuda total.<sup>21<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Honduras, este dinero significaba su estabilidad. Fortalec\u00eda al gobierno y a la econom\u00eda, mientras que las exportaciones tradicionales menguaban y las iniciativas para modernizar la econom\u00eda fallaban. La ayuda extranjera le inyect\u00f3 al ej\u00e9rcito un incre\u00edble poder militar y capacidad de influencia, los cuales us\u00f3, como se se\u00f1al\u00f3 anteriormente, para ingresar en los c\u00edrculos de las otras \u00e9lites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s el ejemplo m\u00e1s simb\u00f3lico del alcance de los militares se present\u00f3 cuando el jefe de las fuerzas armadas, Gustavo \u00c1lvarez Mart\u00ednez, cre\u00f3 la Asociaci\u00f3n para el Progreso de Honduras (APROH) en 1983. Esta era una asociaci\u00f3n empresarial ultraconservadora&nbsp; (algunos dicen que \u201cfascista\u201d).<sup>22&nbsp;23<a href=\"#U\"><\/a><\/sup> &nbsp;Entre sus miembros fundadores se encontraba Miguel Facusse, posiblemente el miembro m\u00e1s poderoso de la \u00e9lite del pa\u00eds. Facusse fue el asesor econ\u00f3mico del presidente civil que se eligi\u00f3 entonces, y se desempe\u00f1\u00f3 como vicepresidente de la APROH.<sup>24<a href=\"#W\"><\/a><\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, Mart\u00ednez fue destituido como jefe de las fuerzas armadas en 1984, y sali\u00f3 de la APROH, y del pa\u00eds, en medio de rumores de un posible golpe militar. La experiencia de la APROH significar\u00eda una lecci\u00f3n para algunos miembros de la \u00e9lite del pa\u00eds, quienes comenzaron a distanciarse de los militares.&nbsp; Aunque la asociaci\u00f3n continu\u00f3 siendo un veh\u00edculo para que los administradores del poder en el pa\u00eds canalizaran sus intereses pol\u00edticos y econ\u00f3micos, los militares estuvieron marginados en gran parte de estas alianzas y tratos secretos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquel fue el principio del fin del ascenso de los militares, al menos por el momento. La regi\u00f3n estaba cambiando, pero los oficiales militares tardaron en reaccionar. Estados Unidos estaba amainando sus esfuerzos por financiar guerras en Honduras \u2014una pol\u00edtica que hab\u00eda hecho que los militares y el gobierno hondure\u00f1os parecieran d\u00e9biles y cooptados por Washington\u2014.<sup>25<\/sup> Marginado y avergonzado, el ej\u00e9rcito comenz\u00f3 una lenta retirada de la pol\u00edtica. No por casualidad este retiro se dio cuando Estados Unidos cambi\u00f3 sus pol\u00edticas de lucha contra el comunismo por la lucha contra las drogas en la regi\u00f3n. Hacia 1988, las lealtades de los militares se dividieron entre su benefactor oficial, Estados Unidos, y su benefactor no oficial, Juan Ram\u00f3n Matta Ballesteros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-matta-ballesteros-una-vida-de-crimen\">Matta Ballesteros: una vida de crimen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La historia de Matta Ballesteros est\u00e1 plagada de versiones confusas y contradictorias. Seg\u00fan \u00e9l mismo, naci\u00f3 en Tegucigalpa en 1945 y fue el segundo de cuatro hermanos.<sup>26<\/sup> &nbsp;Algunos dicen que era un ratero indigente;<sup>27<\/sup> &nbsp;otros dicen que ped\u00eda dinero en los autobuses.<sup>28<\/sup> &nbsp;Fuentes consultadas para este reporte y que solicitaron el anonimato, indican que los antecedentes m\u00e1s conocidos de la vida criminal de Matta Ballesteros se remontan a inicios de los a\u00f1os 70 en la colonia \u201cSoto\u201d de Comayag\u00fcela,&nbsp; Distrito Central de Honduras. Para entonces, en&nbsp; ese popular barrio se forjaban los grandes expendedores de marihuana y a la edad de 24 o 25 a\u00f1os ya se le ubicaba a Matta Ballesteros como el vendedor de drogas m\u00e1s poderoso e influyente del lugar.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"175\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/ramon_matta.jpg?resize=153%2C175&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244470\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/ramon_matta.jpg?w=153&amp;quality=100&amp;ssl=1 153w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/ramon_matta.jpg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/ramon_matta.jpg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 153px) 100vw, 153px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u201cRecuerdo que lo conoc\u00edamos como el \u2018pusher man\u2019 porque en ese tiempo era una de las canciones que mas pegaba\u201d, un TK explic\u00f3 a InSight Crime. \u201cEra un himno para muchos amigos del barrio que se dedicaban a la venta de marihuana y todo mundo sab\u00eda que Matta era el mejor haciendo eso.&nbsp; Viv\u00eda en la casa que estaba colindando el cementerio y todo mundo sab\u00eda que \u201candaba en la mo\u00f1a\u201d. Ya para entonces en su casa se ve\u00edan filas de gente pobre que llegaban a pedirle dinero, regalos, de todo!. Todo lo mundo lo quer\u00eda y ciertamente desde joven ya lo ve\u00edan como un benefactor.&nbsp; Pero tambi\u00e9n ya para ese tiempo se ve\u00eda&nbsp; que \u201cla bola\u201d (polic\u00eda antidrogas) entraba y sal\u00eda de su casa con paquetes de todo tipo y de todo tama\u00f1o\u201d.<sup>29<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, Matta Ballesteros logr\u00f3 llegar a M\u00e9xico y luego a Estados Unidos, donde al parecer trabaj\u00f3 como jornalero en Texas y como empleado de un supermercado en la ciudad de Nueva York.<sup>30<\/sup> &nbsp;De pronto se conect\u00f3 con grupos que se dedicaban al contrabando y al tr\u00e1fico de drogas ilegales. A finales de los sesenta, la red se extendi\u00f3 a Washington DC, donde un ex agente de la DEA afirm\u00f3 que lo hab\u00eda detenido en 1969, cargando 50 kilos de coca\u00edna en el aeropuerto internacional de Dulles.<sup>31<\/sup> &nbsp;Otra versi\u00f3n dice que fue detenido en Dulles en 1970, con 24,5 kilos de coca\u00edna.<sup>32<\/sup> &nbsp;En todo caso, evadi\u00f3 los cargos de tr\u00e1fico de drogas y fue condenado por violaciones a la inmigraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades estadounidenses recluyeron a Matta Ballesteros en la Base A\u00e9rea Eglin en Florida, pero \u00e9l escap\u00f3 y regres\u00f3 a M\u00e9xico, donde comenz\u00f3 a tener un incre\u00edble poder dentro del hampa y cumpli\u00f3 un papel clave en el comercio de coca\u00edna.<sup>33<\/sup> &nbsp;Aunque fue detenido en al menos dos ocasiones m\u00e1s en los a\u00f1os setenta en M\u00e9xico, logr\u00f3 conseguir su libertad y establecer relaciones a\u00fan m\u00e1s profundas con el creciente mundo criminal mexicano.<sup>34<\/sup> &nbsp;Durante este per\u00edodo, al parecer conoci\u00f3 a Alberto Sicilia Falcan, un traficante cubano que viv\u00eda en M\u00e9xico, y a Miguel F\u00e9lix Gallardo, mexicano proveniente de la famosa provincia de Sinaloa, que se encontraba construyendo lo que se conocer\u00eda como el Cartel de Guadalajara.<sup>35<\/sup> &nbsp;Matta Ballesteros tambi\u00e9n lleg\u00f3 a Colombia, donde se conect\u00f3 con quienes estaban conformando lo que se conocer\u00eda como el Cartel de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pronto se convirti\u00f3 en un importante negociante de todo tipo de mercanc\u00edas, desde coca\u00edna hasta piedras preciosas y armas para Estados Unidos. Conect\u00f3 a las hampas mexicanas y colombianas, proporcionando un puente vital por Centroam\u00e9rica para el transporte de coca\u00edna. Las conect\u00f3 adem\u00e1s con su pa\u00eds natal, donde lleg\u00f3 a ser parte de una empresa de contrabando de esmeraldas, coca\u00edna y armas dirigida por Mar\u00eda y Mario Ferrari. Y m\u00e1s adelante conect\u00f3 a la CIA con su ej\u00e9rcito apoderado en Nicaragua, los Contras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La red de tr\u00e1fico de esmeraldas se extend\u00eda desde Colombia hasta M\u00e9xico,<sup>36<\/sup> &nbsp;y por un tiempo el negocio fue bueno. Adem\u00e1s de traficar mercanc\u00edas ilegales hacia el norte, Matta Ballesteros y Mario Ferrari eran propietarios de una discoteca. Los Ferrari operaban con impunidad gracias a sus conexiones militares. Pose\u00edan una concesionaria de autom\u00f3viles y una empresa cervecera ubicada en una propiedad del director de la Prisi\u00f3n Central, el coronel militar Ram\u00f3n Reyes S\u00e1nchez.<sup>37<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La red de los Ferrari fue, al parecer, la primera conexi\u00f3n directa de Matta Ballesteros con los militares hondure\u00f1os. Los militares se aseguraban de que sus socios traficantes no fueron enjuiciados y facilitaban su paso por aeropuertos, fronteras y aduanas, que eran controladas por el ej\u00e9rcito en ese momento. Como lo detallan Julie Marie Bunck y Michael Ross Fowler en \u201cBullets, Bribes and Intimidation\u201d [\u201cBalas, sobornos e intimidaci\u00f3n\u201d], cuando Matta Ballesteros quer\u00eda que, por ejemplo, se destruyeran sus antecedentes judiciales y las investigaciones contra \u00e9l, acud\u00eda a los Ferrari.<sup>38<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En determinado momento surgi\u00f3 un conflicto entre los Ferrari y Matta Ballesteros. Algunas fuentes dicen que la disputa fue por un acuerdo sobre drogas en el que Matta Ballesteros sent\u00eda que hab\u00eda sido estafado.<sup>39<\/sup> &nbsp;En diciembre de 1977, secuaces de Matta Ballesteros secuestraron a los Ferrari y los llevaron a Colombia, donde Matta Ballesteros supervis\u00f3 personalmente su tortura, seg\u00fan testific\u00f3 m\u00e1s tarde uno de los asesinos; luego fueron llevados de nuevo a Honduras y ultimados, dijo el mismo asesino.<sup>40<\/sup> &nbsp;Seis meses m\u00e1s tarde, los cuerpos de los Ferrari fueron encontrados en un pozo en una finca en las afueras de Tegucigalpa.<sup>41<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Informes posteriores de los peri\u00f3dicos El Tiempo y La Prensa sobre los asesinatos de los Ferrari \u2014as\u00ed como una cr\u00f3nica elaborada por la periodista Thelma Mej\u00eda para Transnational Institute<sup>42<\/sup>\u2014&nbsp; hallaron que hubo un grupo de colaboradores militares en el crimen y comenzaron un lento proceso que puso en evidencia la complicidad de los militares en el tr\u00e1fico de drogas y en operaciones de contrabando por todo el pa\u00eds.<sup>43<\/sup> &nbsp;Entre estos colaboradores se encontraba el ya mencionado coronel Reyes S\u00e1nchez; el coronel Leonidas Torres Arias, jefe del servicio de inteligencia \u201cG2\u201d (el equivalente de la CIA); el teniente coronel Juan \u00c1ngel Barahona, jefe de Interpol; y el coronel Armando Calidonio, miembro de la Direcci\u00f3n Nacional de Investigaci\u00f3n (DNI), una unidad especial de investigaciones (y padre de Armando Calidonio Alvarado, futuro diputado por el Partido Nacional y luego electo alcalde de San Pedro Sula en el 2013).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los implicados en el asesinato, el coronel Torres Arias merece menci\u00f3n especial. El Tiempo dijo que el asesinato fue planeado desde la oficina de inteligencia de Torres Arias en el G2 junto con Matta Ballesteros. Pero la participaci\u00f3n de Torres Arias en las operaciones de Matta Ballesteros parece haber ido mucho m\u00e1s all\u00e1 de ayudar a aniquilar a sus rivales. El coronel tambi\u00e9n fue el mediador para los contactos oficiales en otros pa\u00edses, en particular con un coronel paname\u00f1o llamado Manuel Noriega. Los dos coroneles se conectaron a finales de los a\u00f1os setenta, seg\u00fan Jos\u00e9 Bland\u00f3n, un exfuncionario paname\u00f1o que trabaj\u00f3 para Noriega y testific\u00f3 ante el Congreso de Estados Unidos en la d\u00e9cada de los ochenta.<sup>44<\/sup> &nbsp;(Noriega se convertir\u00eda m\u00e1s tarde en un dictador militar, que gobern\u00f3 a Panam\u00e1 entre 1983 y 1989, tiempo durante el cual facilit\u00f3 el transporte ilegal de drogas a Estados Unidos y prepar\u00f3 el terreno para la invasi\u00f3n de Estados Unidos a Panam\u00e1 en 1989). Torres Arias fue inicialmente apoyado por la CIA, que se hizo la de la vista gorda frente a su participaci\u00f3n en el narcotr\u00e1fico debido a sus fuertes creencias anticomunistas.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"286\" height=\"280\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/torres_arias.jpg?resize=286%2C280&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244473\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/torres_arias.jpg?w=286&amp;quality=100&amp;ssl=1 286w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/torres_arias.jpg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/torres_arias.jpg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En otras palabras, Torres Arias fue el agente clave que le proporcion\u00f3 a Matta Ballesteros un camino hacia la \u00e9lite burocr\u00e1tica militar en Honduras (y Panam\u00e1). Aunque fue expulsado de su cargo tras revelaciones de que mantuvo reuniones secretas con el fin de conseguir armas ilegales para los rebeldes salvadore\u00f1os, se cree que Torres Arias fue cercano al hampa durante a\u00f1os despu\u00e9s de salir del ej\u00e9rcito,<sup>45<\/sup> &nbsp;proporcionando estrechos v\u00ednculos entre Matta Ballesteros y cuerpos oficiales del ej\u00e9rcito hondure\u00f1o en la d\u00e9cada de los ochenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de varias declaraciones p\u00fablicas que relacionaban a los militares con el crimen, no hubo condenas para ninguno de los supuestos conspiradores del asesinato de los Ferrari. Las declaraciones m\u00e1s conocidas vinieron del jefe de la Interpol Juan \u00c1ngel Barahona, quien, despu\u00e9s de haber sido vinculado p\u00fablicamente con el crimen, implic\u00f3 a los militares en actividades de narcotr\u00e1fico y en el asesinato de los Ferrari, diciendo que \u201cmuchas estrellas\u201d hab\u00edan sido implicadas \u2014una referencia a las insignias de los oficiales de m\u00e1s alto rango en las fuerzas armadas\u2014. Tambi\u00e9n dijo que el jefe de las fuerzas armadas en aquel momento, el general Policarpo Paz Garc\u00eda, hab\u00eda ocultado grabaciones y documentos que conectaban a altos funcionarios militares con el narcotr\u00e1fico.<sup>46<\/sup> &nbsp;Barahona fue posteriormente detenido por calumnia, puesto en confinamiento solitario y sin posibilidad de acceder a su abogado.<sup>47<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El padre de Mario Ferrari escribi\u00f3 una carta al diario El Tiempo, en la que dec\u00eda que su hijo hab\u00eda trabajado estrechamente con las autoridades militares y que ellas eran responsables de su muerte.<sup>48<\/sup> &nbsp;Pero en los a\u00f1os que siguieron el gobierno detuvo la investigaci\u00f3n, y finalmente la clausur\u00f3; los oficiales militares implicados nunca fueron acusados. Matta Ballesteros huy\u00f3, y permaneci\u00f3 sobre todo en Espa\u00f1a en los a\u00f1os siguientes. Finalmente fue absuelto de los cargos de asesinato, despu\u00e9s de entregarse a las autoridades algunos a\u00f1os m\u00e1s tarde.<sup>49<\/sup><a href=\"#AX\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno tambi\u00e9n orden\u00f3 un informe interno sobre el tema, que no encontr\u00f3 ninguna mala actuaci\u00f3n por parte de los militares. La oficina de prensa del ej\u00e9rcito escribi\u00f3: \u201cNing\u00fan oficial en servicio dentro del instituto armado ha estado involucrado en los cr\u00edmenes de tr\u00e1fico de drogas y estupefacientes, en el caso de los esposos Ferrari, ni en los hechos de sangre sobre los que profesamente ha informado la prensa\u201d. Ir\u00f3nicamente, en el mismo comunicado la oficina de prensa admiti\u00f3 que \u201calgunos miembros de las Fuerzas Armadas pudieron haber cometido irregularidades en el desempe\u00f1o de sus funciones, por acci\u00f3n o por omisi\u00f3n\u201d.<sup>50<\/sup>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-matta-ballesteros-el-ejercito-y-la-cia\">Matta Ballesteros, el ej\u00e9rcito y la CIA<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"961\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=1024%2C961&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244633\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=1024%2C961&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=300%2C282&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=768%2C721&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=1536%2C1441&amp;quality=100&amp;ssl=1 1536w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=1200%2C1126&amp;quality=100&amp;ssl=1 1200w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=1568%2C1471&amp;quality=100&amp;ssl=1 1568w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=400%2C375&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?resize=706%2C662&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol.jpg?w=1980&amp;quality=100&amp;ssl=1 1980w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallasterosDrugTrafficNetEpanol-1024x961.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El tr\u00e1fico de drogas continu\u00f3 y, seg\u00fan muchos informes, aument\u00f3 en los a\u00f1os despu\u00e9s de los asesinatos de los Ferrari. Algunos dec\u00edan que ello se deb\u00eda a las conexiones que se generaron en los a\u00f1os setenta entre narcotraficantes y altos rangos del ej\u00e9rcito, incluyendo los supuestos v\u00ednculos de Matta Ballesteros con el jefe de las fuerzas armadas, el general Paz Garc\u00eda. Este \u00faltimo se convirti\u00f3 en jefe de Estado tras el llamado \u201cgolpe de coca\u00edna\u201d en 1978, que Matta Ballesteros supuestamente ayud\u00f3 a financiar.<sup>51<\/sup> &nbsp;No hay ning\u00fan documento oficial que respalde esta afirmaci\u00f3n, pero el interlocutor clave entre Matta Ballesteros y los militares, Torres Arias, permaneci\u00f3 en servicio durante toda la administraci\u00f3n de Paz Garcia.<sup>52<\/sup> &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El modus operandi para el transporte de drogas ilegales era similar al de hoy. Los cargamentos de marihuana y coca\u00edna se transportaban a trav\u00e9s de aguas hondure\u00f1as, donde \u201cnaves madre\u201d colombianas los descargaban en barcos camaroneros hondure\u00f1os, para luego seguir su viaje hacia Estados Unidos por mar, aire o tierra.<sup>53<\/sup> &nbsp;Esto ocurr\u00eda con el conocimiento y la complicidad de la armada hondure\u00f1a, seg\u00fan el testimonio de un agente de la DEA en 1986.<sup>54<\/sup> &nbsp;Este agente dijo que cuando \u00e9l le notificaba a la marina sobre alguna actividad sospechosa, los funcionarios se demoraban en actuar o dec\u00edan que no ten\u00edan combustible para perseguir a los traficantes. Y a\u00f1adi\u00f3 que Torres Arias, jefe de los servicios de inteligencia, estuvo implicado en el tr\u00e1fico de drogas. \u201cEra dif\u00edcil llevar a cabo investigaciones y esperar a que las autoridades hondure\u00f1as ayudaran a hacer las detenciones cuando era a ellas a quienes est\u00e1bamos tratando de investigar\u201d, dijo el agente de la DEA.<sup>55<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas actividades de narcotr\u00e1fico tambi\u00e9n ocurr\u00edan con el visto bueno de funcionarios de inteligencia de Estados Unidos que en ese momento se encontraban involucrados en una guerra contra el gobierno sandinista de Nicaragua. Esta guerra, y la lucha contra el comunismo en general, eran prioritarias para Estados Unidos, que por lo tanto permit\u00eda la circulaci\u00f3n de drogas hacia el norte y de armas y suministros hacia el sur, a menudo bajo la supervisi\u00f3n de Matta Ballesteros y sus aliados militares. Bland\u00f3n, por ejemplo, dijo que hacia la d\u00e9cada de los ochenta Torres Arias y Noriega participaban en el negocio de las drogas y traficaban armas, muchas de ellas para los insurgentes salvadore\u00f1os. Y agreg\u00f3 que las mismas pistas de aterrizaje clandestinas en Honduras utilizadas por aviones que llevaban armas al ej\u00e9rcito financiado por Estados Unidos y conocido como los Contras, tambi\u00e9n se usaban para el tr\u00e1fico de estupefacientes.<sup>56<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el centro de la ayuda estadounidense a los Contras estaba SETCO, una aerol\u00ednea que Matta Ballesteros estableci\u00f3 en Tegucigalpa. SETCO conectaba a Matta Ballesteros con los militares hondure\u00f1os y el gobierno de Estados Unidos, que utilizaba la aerol\u00ednea para llevar suministros a los Contras a lo largo de la frontera de Honduras y Nicaragua en la d\u00e9cada de los ochenta. Los registros muestran que el Departamento de Estado le pag\u00f3 US$185,924.25 a SETCO entre enero y agosto de 1986.<sup>57<\/sup>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA principios de 1984, SETCO era la principal empresa usada por los Contras en Honduras para transportar insumos y personal para la Fuerza Democr\u00e1tica Nicarag\u00fcense (FDN), una facci\u00f3n de los Contras, haciendo al menos un mill\u00f3n de entregas de municiones, alimentos, uniformes y otros suministros militares para los Contras entre 1983 y 1985\u201d, seg\u00fan consta en el informe Kerry, que lleva el nombre del entonces senador y actualmente secretario de Estado John Kerry, quien dirigi\u00f3 la investigaci\u00f3n del Comit\u00e9 de Relaciones Exteriores del Senado sobre el apoyo de Estados Unidos a los Contras.<sup>58<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Matta Ballesteros tambi\u00e9n utilizaba la aerol\u00ednea para llevar drogas hacia el norte, a sus socios en M\u00e9xico. El informe a\u00f1ade que otras agencias de Estados Unidos sab\u00edan del rol de SETCO en el tr\u00e1fico de drogas. \u201cUn informe investigativo de la aduana en 1983 se\u00f1ala que \u2018SETCO significa Servicios Ejecutivos Turistas Commander y es dirigido por Juan Ram\u00f3n Mata [sic] Ballesteros, un transgresor Clase I de la DEA\u2019\u201d, dice el informe Kerry. \u201cSeg\u00fan la Agencia Antidrogas [sic] \u2018La aerol\u00ednea SETCO es una sociedad formada por negociantes americanos que tienen tratos con Matta y trafican narc\u00f3ticos a Estados Unidos\u00b4\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"695\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/setco_airlines.jpg?resize=1024%2C695&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244481\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/setco_airlines.jpg?w=1024&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/setco_airlines.jpg?resize=300%2C204&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/setco_airlines.jpg?resize=768%2C521&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/setco_airlines.jpg?resize=400%2C271&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/setco_airlines.jpg?resize=706%2C479&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/setco_airlines.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Estos contactos les proporcionaron considerable protecci\u00f3n a Matta Ballesteros y a sus aliados militares mientras traficaban coca\u00edna y marihuana a Estados Unidos. Tambi\u00e9n les permitieron fortalecer sus contactos con el ej\u00e9rcito hondure\u00f1o, que estaba creciendo con la ayuda de Estados Unidos. La prioridad de la CIA era clara: mantener a los Contras a flote a cualquier precio. Para mencionar un solo ejemplo, el agente de la DEA que hab\u00eda trabajado en Honduras dijo que le cont\u00f3 a Estados Unidos sobre la participaci\u00f3n de Torres Arias en el narcotr\u00e1fico, pero que el coronel segu\u00eda siendo un aliado de Estados Unidos durante este per\u00edodo.<sup>59<\/sup> &nbsp;La oficina de la DEA en Honduras fue cerrada en 1983 por \u201crazones presupuestarias\u201d.<sup>60<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn lugar de actuar decididamente para acabar con el narcotr\u00e1fico intensificando la presencia de la DEA en el pa\u00eds y usando la ayuda que Estados Unidos les ofrec\u00eda a los hondure\u00f1os como apoyo, Estados Unidos cerr\u00f3 la oficina de la DEA en Tegucigalpa y pareci\u00f3 haber ignorado el asunto\u201d, se lee en el informe Kerry.<sup>61<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ayuda de Estados Unidos tambi\u00e9n pareci\u00f3 envalentonar a ciertos sectores de los militares hondure\u00f1os. En 1984, el FBI incaut\u00f3 un cargamento de coca\u00edna por valor de US$40 millones en una pista de aterrizaje al sur de Florida. El FBI dijo que el dinero iba a ser utilizado en un complot para asesinar al entonces presidente de Honduras, Roberto Suazo C\u00f3rdova. Un hombre fue detenido en Estados Unidos, y el agregado militar de Honduras en Chile fue implicado y extraditado a Estados Unidos para enfrentar cargos relacionados con el caso. Sin embargo, altos funcionarios de inteligencia de Estados Unidos intervinieron en su favor \u2014aparentemente por los \u201cservicios\u201d prestados a Estados Unidos en la guerra declarada a los Contra\u2014 y lograron reducir su condena a cinco a\u00f1os en la prisi\u00f3n de la base a\u00e9rea de Eglin. El otro sospechoso fue condenado a 30 a\u00f1os en una c\u00e1rcel de Estados Unidos por su participaci\u00f3n en el caso.<sup>62<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cParece que un factor apremiante en las relaciones entre Estados Unidos y Honduras era el apoyo a la pol\u00edtica estadounidense en la regi\u00f3n, sobre todo el apoyo a la guerra contra los Contras\u201d, agreg\u00f3 la Comisi\u00f3n Kerry en su mordaz evaluaci\u00f3n del tema. \u201cMientras el gobierno de Honduras ofreciera apoyo, los dem\u00e1s temas eran de importancia secundaria\u201d.<sup>63<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos temas generaron dudas alrededor de las actividades de Matta Ballesteros, quien hacia mediados de la d\u00e9cada de los ochenta era uno de los narcotraficantes m\u00e1s importantes en el hemisferio. Con aliados en Colombia y M\u00e9xico, as\u00ed como con un grupo de altos oficiales militares hondure\u00f1os y de la CIA que proteg\u00edan sus negocios il\u00edcitos, Matta Ballesteros parec\u00eda relativamente intocable. En particular, sus conexiones con el servicio hondure\u00f1o de inteligencia militar, o G2, parec\u00edan de gran alcance. Seg\u00fan un exmiembro del servicio diplom\u00e1tico, el G2 solicit\u00f3 un pasaporte para Matta Ballesteros en 1982. \u201cMe aboqu\u00e9 al entonces canciller\u2026 para consultarle el caso\u201d, explic\u00f3 el exdiplom\u00e1tico. \u201c\u00c9ste vino e hizo unas aproximaciones y recuerdo encogi\u00f3 sus hombros y nos dijo: d\u00e9nselo, es una petici\u00f3n de alto nivel y es parte de negociaciones que desconozco\u201d.<sup>64<\/sup>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-el-asesinato-de-un-agente-el-final-de-una-relacion\">El asesinato de un agente, el final de una relaci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En 1985 todo cambi\u00f3 para Matta Ballesteros, cuando el Cartel de Guadalajara, enfurecido por el \u00e9xito de la DEA en el decomiso de grandes extensiones de sus cultivos de marihuana en M\u00e9xico y en los env\u00edos de coca\u00edna a Estados Unidos,<sup>65<\/sup> &nbsp;secuestraron y mataron<sup>66<\/sup> a Enrique Camarena, un agente de la DEA. El asesinato de Camarena se dio lentamente. Un a\u00f1o despu\u00e9s de su muerte, las autoridades mexicanas entregaron varias horas de grabaciones de audio de una sesi\u00f3n de tortura del agente y su piloto, quien tambi\u00e9n fue asesinado.&nbsp; En las grabaciones, Camarena gime de dolor y ruega por su vida, mientras que entrega informaci\u00f3n confidencial acerca de informantes de la DEA y otros agentes.<sup>67<\/sup> &nbsp;\u201cCon la paliza que me has dado, \u00bfcrees que te voy a mentir?\u201d, les preguntaba a sus interrogadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Camarena y su piloto fueron encontrados enterrados en un campo de Guadalajara, junto con otros cuerpos.<sup>68<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de la muerte de Camarena, el gobierno estadounidense comenz\u00f3 una b\u00fasqueda implacable de justicia. En los a\u00f1os siguientes, numerosos miembros y l\u00edderes del Cartel de Guadalajara fueron detenidos y condenados en M\u00e9xico. Otros fueron atrapados en M\u00e9xico y llevados ilegalmente a Estados Unidos para ser juzgados all\u00ed. El mismo Matta Ballesteros fue detenido en Colombia en 1986, pero, con ayuda del Cartel de Medell\u00edn,<sup>69<\/sup> &nbsp;escap\u00f3 y logr\u00f3 regresar a Honduras, donde se sent\u00eda protegido por su vasta red y por su riqueza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al principio, esta protecci\u00f3n fue abundante. Matta Ballesteros era una figura p\u00fablica en Honduras, igual de conocido como empresario y fil\u00e1ntropo como narcotraficante. Se dice que ten\u00eda plantaciones de caf\u00e9, tabaco y especias, as\u00ed como lecher\u00edas y tierras dedicadas a la ganader\u00eda en Honduras; fund\u00f3 adem\u00e1s empresas de construcci\u00f3n y agroindustriales.<sup>70<\/sup> &nbsp;Construy\u00f3 escuelas, y en sus negocios se emplearon por lo menos 4.000 personas.<sup>71 &nbsp;<\/sup>Daba dinero en efectivo en la puerta de su casa y sol\u00eda llamar a las farmacias para garantizar medicinas para los enfermos.<sup>72<\/sup> &nbsp;Se dice tambi\u00e9n que alguna vez ofreci\u00f3 US$25.000 durante un Telet\u00f3n; su ofrecimiento fue rechazado, pero de todas formas despert\u00f3 simpat\u00edas.<sup>73<\/sup> &nbsp;Fue, seg\u00fan varias fuentes militares consultadas para este estudio, humilde y sencillo \u2014el tipo de persona que disfrutaba comiendo en la cocina con sus cocineras\u2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Matta Ballesteros tambi\u00e9n ejerci\u00f3 una influencia pol\u00edtica significativa. Organizaba fiestas en su mansi\u00f3n, donde supuestamente recib\u00eda a pol\u00edticos, militares y al entonces jefe de polic\u00eda de Honduras.<sup>74<\/sup> &nbsp;En cierto momento, como su socio Pablo Escobar lo hab\u00eda hecho en Colombia, ofreci\u00f3 p\u00fablicamente pagar la deuda externa del pa\u00eds. Los funcionarios hondure\u00f1os pensaron que la oferta podr\u00eda haber sido m\u00e1s que simb\u00f3lica, y en 1986, el entonces ministro de finanzas, Reginaldo Panting, consider\u00f3 que el dinero de Matta Ballesteros \u201cser\u00eda bien recibido en nuestro pa\u00eds, ya que nos ayudar\u00eda a mejorar nuestra balanza de pagos\u201d.<sup>75<\/sup>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"962\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=1024%2C962&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244635\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=1024%2C962&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=300%2C282&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=768%2C721&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=1536%2C1443&amp;quality=100&amp;ssl=1 1536w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=1200%2C1127&amp;quality=100&amp;ssl=1 1200w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=1568%2C1473&amp;quality=100&amp;ssl=1 1568w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=400%2C376&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?resize=706%2C663&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol.jpg?w=1980&amp;quality=100&amp;ssl=1 1980w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosEliteNetworkEspanol-1024x962.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los comentarios sobre la deuda externa ofrecen una mirada a la mentalidad de los gobernantes hondure\u00f1os con respecto al capital il\u00edcito. Honduras era una econom\u00eda de enclave, dependiente del capital extranjero para su crecimiento y desarrollo econ\u00f3mico. Esto se intensific\u00f3 en los a\u00f1os ochenta, cuando, dado que las exportaciones tradicionales disminuyeron, el pa\u00eds se inclin\u00f3 por la ayuda de Estados Unidos y m\u00e1s tarde por la de los bancos multilaterales. Visto desde esta perspectiva, el capital ganado en el extranjero por Matta Ballesteros encaja bien en el modelo econ\u00f3mico de Honduras. \u00c9l era, en cierto modo, un nuevo empresario que podr\u00eda facilitar inversi\u00f3n extranjera directa y ofrecer miles de puestos de trabajo. Al contrario de lo que ocurri\u00f3 con Escobar, su generosidad fue agradecida p\u00fablicamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el cerco pronto se cerr\u00f3 alrededor de Matta Ballesteros. Ello se debi\u00f3 en parte a su implicaci\u00f3n en el caso Camarena. Pero tambi\u00e9n se debi\u00f3 al cambio de pol\u00edtica interna de Estados Unidos. En los a\u00f1os ochenta, Estados Unidos padec\u00eda una oleada de violencia, parte de la cual estaba relacionada con el aumento del consumo interno de drogas y el tr\u00e1fico de drogas al interior de las ciudades. Para los pol\u00edticos y funcionarios del gobierno estadounidense, traficantes extranjeros como Escobar y Matta Ballesteros eran siempre chivos expiatorios convenientes. Con el tiempo, estos temores incluso remplazaron la amenaza comunista y llevaron al derrocamiento y encarcelamiento de uno de los muchos socios regionales de Matta Ballesteros y Escobar, el gobernante militar paname\u00f1o Manuel Noriega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de 1988, el gobierno de Estados Unidos discut\u00eda abiertamente el caso de Matta Ballesteros y sus nexos con militares de alto rango hondure\u00f1os. Entre ellos se encontraba quien por mucho tiempo fue su conexi\u00f3n con las fuerzas armadas, el exjefe de inteligencia Torres Arias, quien hab\u00eda regresado a Honduras en 1987, poco m\u00e1s de un a\u00f1o despu\u00e9s del arribo de Matta Ballesteros.<sup>76<\/sup> &nbsp;Funcionarios antinarc\u00f3ticos enviaron preguntas escritas a la audiencia de un comit\u00e9 del Congreso de Estados Unidos, en las que hac\u00edan referencias a informes seg\u00fan los cuales Torres Arias era un \u201cconsejero influyente\u201d del entonces jefe de las fuerzas armadas, el general Humberto Regalado, y del nuevo jefe de inteligencia militar.<sup>77<\/sup>&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"289\" height=\"175\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_livingroom.jpeg?resize=289%2C175&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244485\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_livingroom.jpeg?w=289&amp;quality=100&amp;ssl=1 289w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_livingroom.jpeg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_livingroom.jpeg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 289px) 100vw, 289px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En los d\u00edas siguientes, una lista de posibles colaboradores de Matta Ballesteros, presuntamente elaborada por Estados Unidos, fue le\u00edda en voz alta en la radio hondure\u00f1a. La lista inclu\u00eda al ministro de Defensa, el director de inteligencia militar, el jefe de la armada, el jefe de personal de las fuerzas armadas y el exdirector de la escuela de comando militar.<sup>78<\/sup> &nbsp;Tambi\u00e9n se insinuaba que Matta Ballesteros contaba entre sus socios al jefe de la polic\u00eda, Leonel Riera Lunati, y que empleaba a un grupo de exmiembros de las Fuerzas Especiales de Honduras para que trabajaran para \u00e9l y para su empresa de seguridad.<sup>79<\/sup> &nbsp;En una respuesta escrita acerca de la pregunta sobre la relaci\u00f3n entre Torres Arias y Regalado, el Departamento de Estado rest\u00f3 importancia a dicha conexi\u00f3n. \u201cNo creemos que sea un asesor influyente\u201d, dice, refiri\u00e9ndose a Torres Arias. \u201cEs normal que Torres conociera a Regalado y a otros oficiales militares hondure\u00f1os con quienes prest\u00f3 servicio\u201d.<sup>80<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el gobierno estadounidense estaba claramente preocupado.<sup>81<\/sup> &nbsp;La audiencia del Congreso sobre el asunto en marzo de 1988 comenz\u00f3 con referencias del congresista Benjam\u00edn Gilman, de Nueva York, sobre los problemas en Honduras. \u201cUn miembro del Cartel de Medell\u00edn, Juan Matta Ballesteros, se ha establecido en Honduras\u201d, dijo. \u201cYa est\u00e1 extendiendo su influencia corruptora en esa sociedad. Est\u00e1 intentando comprar a funcionarios del gobierno hondure\u00f1o. Ballesteros es un fuerte narcotraficante que conoce bien su negocio\u201d.<sup>82<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El congresista se\u00f1al\u00f3 adem\u00e1s la presunta participaci\u00f3n de militares hondure\u00f1os en las actividades criminales de Matta Ballesteros. \u201cTambi\u00e9n me preocupan los recientes informes de que algunos militares hondure\u00f1os pueden estar involucrados con el narcotr\u00e1fico, y espero que no dirijamos nuestra mirada hacia otros intereses de seguridad all\u00ed\u201d, dijo, en referencia a la guerra que se estaba adelantando contra el r\u00e9gimen sandinista en Nicaragua. \u201cEspero que el se\u00f1or Ballesteros no haya logrado a\u00fan construir una red de tr\u00e1fico de drogas en Honduras, con la colaboraci\u00f3n de algunos de estos militares corruptos\u201d.<sup>83<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque le hab\u00eda restado importancia a las conexiones de Torres Arias con las altas esferas del ej\u00e9rcito hondure\u00f1o, el Departamento de Estado tambi\u00e9n estaba preocupado por lo que estaba ocurriendo en Honduras. Durante esa misma audiencia, el subsecretario del Departamento de Estado en la Oficina para Asuntos Interamericanos, Elliott Abrams, se\u00f1al\u00f3 que el tr\u00e1fico de coca\u00edna hab\u00eda aumentado inmediatamente despu\u00e9s de la llegada de Matta Ballesteros al pa\u00eds.<sup>84<\/sup> &nbsp;En febrero de 1988, el Departamento de Estado de Estados Unidos emiti\u00f3 una declaraci\u00f3n sobre estas preocupaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste Departamento y muchos funcionarios hondure\u00f1os, incluyendo los dirigentes de las fuerzas armadas, est\u00e1n seriamente preocupados ante la posibilidad de que el tr\u00e1fico de drogas haya aumentado significativamente ahora que Juan Ram\u00f3n Matta Ballesteros regres\u00f3 a Honduras proveniente de Colombia\u201d, dijo el Departamento de Estado. \u201cCreemos que \u00e9l est\u00e1 tratando de crear una red de tr\u00e1fico de drogas en Honduras, sin duda con la colaboraci\u00f3n de algunos funcionarios corruptos. Sin embargo, no creemos que tal corrupci\u00f3n se haya generalizado a\u00fan\u201d.<sup>85<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mensaje era claro. Ya era hora de cortar lazos con Matta Ballesteros, y el 5 de abril las Fuerzas Especiales Hondure\u00f1as y la polic\u00eda, junto con cuatro mariscales de Estados Unidos, lo interceptaron despu\u00e9s de regresar de trotar en la ma\u00f1ana, lo ataron y lo llevaron a Rep\u00fablica Dominicana. De all\u00ed fue trasladado a Estados Unidos para enfrentar cargos por el caso de Enrique Camarena, entre otros cargos;<sup>86<\/sup> aquel puede ser considerado una detenci\u00f3n extraoficial.&nbsp; Miles de hondure\u00f1os, descontentos con aquella acci\u00f3n, y presuntamente alentados por los militares, incendiaron un anexo del Consulado de Estados Unidos.<sup>87<\/sup> &nbsp;Cinco personas murieron, y funcionarios de Estados Unidos dijeron que las autoridades hondure\u00f1as se tardaron dos horas en intervenir.<sup>88<\/sup> &nbsp;Matta Ballesteros fue condenado despu\u00e9s por secuestro en un tribunal de Los \u00c1ngeles,<sup>89<\/sup> &nbsp;y por tr\u00e1fico de drogas en un juicio aparte; permanece en una prisi\u00f3n federal de Estados Unidos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conclusiones-una-relacion-mutuamente-beneficiosa\">Conclusiones \u2013 Una relaci\u00f3n mutuamente beneficiosa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La relaci\u00f3n entre Matta Ballesteros y las \u00e9lites burocr\u00e1ticas militares surgi\u00f3 de las oportunidades y las circunstancias, pero se volvi\u00f3 esencial para ambas partes. Esta relaci\u00f3n comenz\u00f3 porque Matta Ballesteros y sus aliados criminales del momento, los Ferrari, necesitaban ayuda del ej\u00e9rcito para el tr\u00e1fico de drogas ilegales y esmeraldas. El ej\u00e9rcito controlaba los aeropuertos, las fronteras, las aduanas y las oficinas de inmigraci\u00f3n, entre otras agencias vitales del gobierno. Este control de puestos burocr\u00e1ticos lo convert\u00eda en un obst\u00e1culo para el tr\u00e1fico de mercanc\u00edas il\u00edcitas. En lugar de lidiar con ese obst\u00e1culo, la red criminal decidi\u00f3 cooptar al ej\u00e9rcito y hacerlo jugar en su equipo. Era una relaci\u00f3n simbi\u00f3tica en el nivel operativo m\u00e1s b\u00e1sico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, la relaci\u00f3n trascendi\u00f3 este nivel b\u00e1sico y lleg\u00f3 a incluir a los niveles m\u00e1s altos de las fuerzas armadas e incluso del gobierno. Hasta ahora no est\u00e1 claro c\u00f3mo logr\u00f3 penetrarlos. Tampoco est\u00e1 claro si esta penetraci\u00f3n se dio de abajo hacia arriba o de arriba hacia abajo. Lo que est\u00e1 claro es que lleg\u00f3 hasta el coraz\u00f3n de los servicios de inteligencia militar. Torres Arias, el aliado clave de Matta Ballesteros, no era s\u00f3lo un guardia de frontera o un soldado de bajo rango cuando presuntamente particip\u00f3 en el asesinato de los Ferrari: era el jefe del servicio de inteligencia militar G2. Esta distinci\u00f3n es importante \u2014y los servicios que \u00e9l ofrec\u00eda eran vitales\u2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arias Torres parece haber sido el protector y el conducto a trav\u00e9s del cual Matta Ballesteros desarroll\u00f3 una relaci\u00f3n profunda y duradera con los militares. Si bien en un principio s\u00f3lo prest\u00f3 protecci\u00f3n, con el tiempo se convirti\u00f3 en un arma ofensiva, ofreci\u00e9ndole acceso a equipos, armas y personal. Lo m\u00e1s seguro es que Matta Ballesteros utiliz\u00f3 estas ayudas para matar a sus poderosos aliados, los Ferrari, una vez ellos le dejaron de ser \u00fatiles o lo hicieron enfurecer. Torres Arias tambi\u00e9n ayud\u00f3 a establecer contactos en otros pa\u00edses, como Panam\u00e1, donde su relaci\u00f3n con Manuel Noriega result\u00f3 igualmente importante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de ese momento, lo que surgi\u00f3 fue nada menos que una alianza entre la red de Matta Ballesteros y la \u00e9lite militar burocr\u00e1tica. Matta Ballesteros utiliz\u00f3 sus contactos en el ej\u00e9rcito para crear un corredor amplio y lucrativo para el transporte de drogas hacia el norte, junto con sus socios en Colombia y M\u00e9xico. H\u00e1bilmente logr\u00f3 cruzar sus intereses con los del ej\u00e9rcito y con los del otro benefactor de este \u00faltimo, Estados Unidos \u2014un tema que trataremos m\u00e1s adelante\u2014. El uso de la aerol\u00ednea SETCO fue, por ejemplo, un movimiento de un experto ajedrecista que entend\u00eda c\u00f3mo satisfacer las necesidades de los jugadores pol\u00edticos locales e internacionales, al mismo tiempo que lograba sus propios prop\u00f3sitos. En otras palabras, era un juego en el que todos ganaban.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"791\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=1024%2C791&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244637\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=1024%2C791&amp;quality=100&amp;ssl=1 1024w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=300%2C232&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=768%2C593&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=1536%2C1187&amp;quality=100&amp;ssl=1 1536w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=1200%2C927&amp;quality=100&amp;ssl=1 1200w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=1568%2C1212&amp;quality=100&amp;ssl=1 1568w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=400%2C309&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?resize=706%2C546&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol.jpg?w=1980&amp;quality=100&amp;ssl=1 1980w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/MattaBallesterosMutualBenRelationEspanol-1024x791.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, Matta Ballesteros se convirti\u00f3 en uno de los m\u00e1s poderosos narcotraficantes del mundo, acumulando una fortuna que, seg\u00fan algunos, alcanz\u00f3 miles de millones de d\u00f3lares.<sup>90<\/sup> &nbsp;Utiliz\u00f3 su capital econ\u00f3mico en el extranjero para evitar enfrentar cualquier pena de prisi\u00f3n, sobornando y amenazando a los funcionarios y autoridades de las prisiones cuando fuera necesario, en lugares como Colombia y posiblemente Espa\u00f1a. Y us\u00f3 su capital pol\u00edtico y social para evitar llegar a la c\u00e1rcel en Honduras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es tentador imaginar lo que le habr\u00eda sucedido a Matta Ballesteros si hubiese tomado un camino ligeramente diferente. Su base econ\u00f3mica, pol\u00edtica y social le hab\u00eda proporcionado una buena posici\u00f3n que le hubiera permitido hacer una transici\u00f3n hacia una \u00e9lite m\u00e1s consolidada. (Como veremos, se trata de una transici\u00f3n que su familia ha intentado continuar, pero con poco \u00e9xito). Adem\u00e1s, \u00e9l ten\u00eda maneras de ganarse a la gente del com\u00fan, que iban m\u00e1s all\u00e1 de su fama como narcotraficante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas aves siempre mantienen limpio su nido\u201d, le dijo un militar en retiro a InSight Crime. \u201cY Moncho (Ram\u00f3n) quer\u00eda vivir en Honduras, quer\u00eda ayudar al pa\u00eds, no lo quer\u00eda para traficar. Si usted me pregunta \u2018\u00bfc\u00f3mo mira el pueblo a los narcos?\u2019, la respuesta es sencilla, ellos dan empleo, dan de comer a la gente, le ayudan, los protegen, les hacen sentir que son parte de ellos; por eso la gente los admira. Y siendo pragm\u00e1tico, \u00bfqu\u00e9 prefiere el pueblo: morirse de hambre con honor o comer con deshonor los tres tiempos al d\u00eda por la actividad del narco? La respuesta es clara\u201d.<sup>91<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando Matta Ballesteros estuvo preso unos d\u00edas en una c\u00e1rcel capitalina, luego de escapar de una c\u00e1rcel en Colombia y de regresar a Honduras, la gente lo visitaba y \u201clas filas eran enormes\u201d, le dijo un exmilitar a InSight Crime. \u201cLe llevaban comida y \u00e9l les retribu\u00eda con cari\u00f1os [dinero]. Luego llegaban a su casa en la colonia Los \u00c1ngeles [en Tegucigalpa], por eso cuando lo extraditaron salieron a las calles a defenderlo y protestar; \u00e9l ya hab\u00eda elaborado una red social de protecci\u00f3n\u201d, se\u00f1al\u00f3 el exmilitar.<sup>92<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, fue este capital pol\u00edtico y social el que lo hizo parecer tan peligroso para Estados Unidos y aceler\u00f3 su conversi\u00f3n de aliado anticomunista a enemigo narcotraficante. Su desafiante imagen p\u00fablica despu\u00e9s de que regres\u00f3 a Honduras, junto con su implicaci\u00f3n en el asesinato de un agente de la DEA, lo hicieron un f\u00e1cil chivo expiatorio para la clase pol\u00edtica de Estados Unidos, que estaba en la b\u00fasqueda de responsables durante un per\u00edodo de agitaci\u00f3n interna. Ese asesinato, y su manifiesta ambici\u00f3n de convertirse en un agente leg\u00edtimo del poder, finalmente se volvieron contra \u00e9l. Y tambi\u00e9n afectaron a su familia. Sus hijos no pod\u00edan ingresar a las escuelas dirigidas por la \u00e9lite del pa\u00eds.<sup>93<\/sup> &nbsp;Los clubes campestres estaban fuera de sus l\u00edmites. Incluso su intento de financiar una Telet\u00f3n fue rechazado debido a su reputaci\u00f3n de narcotraficante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este incidente \u2014tal vez el primer intento p\u00fablico de Matta Ballesteros por ganar legitimidad entre las \u00e9lites\u2014 termin\u00f3 siendo humillante. \u00c9l le ofreci\u00f3 una gran donaci\u00f3n a la Fundaci\u00f3n Telet\u00f3n, pero fue rechazada por su principal promotor, el empresario de medios de comunicaci\u00f3n Rafael Ferrari, quien dijo p\u00fablicamente que ese dinero no era bienvenido. \u201cRecuerdo cuando don Rafael Ferrari lleg\u00f3 en medio de la Telet\u00f3n para rechazar esta donaci\u00f3n, que creo que era de m\u00e1s de un mill\u00f3n de lempiras, mucho dinero en aquel entonces, con lo que se hubiera llegado a la meta, o incluso se hubiera excedido, pero fue muy valiente al rechazar ese dinero de la droga; fue un golpe para Matta\u201d, le dijo a InSight Crime un periodista que cubri\u00f3 el evento.<sup>94<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este caso demuestra que Matta Ballesteros nunca habr\u00eda podido ser parte de una \u00e9lite en el sentido tradicional porque sus actos criminales, en particular el asesinato de un agente de la DEA, eran demasiado p\u00fablicos y la figura de un traficante de drogas muy bajo en la escala social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ambici\u00f3n tambi\u00e9n cumpli\u00f3 un papel central en la ca\u00edda de los militares hondure\u00f1os. Ir\u00f3nicamente, los militares hubieran podido alcanzar su gran poder pol\u00edtico sin Matta Ballesteros. Hab\u00edan surgido como una \u00e9lite burocr\u00e1tica antes de que \u00e9l se convirtiera en su benefactor no oficial. Las fuerzas armadas hab\u00edan pasado de protectoras de la riqueza del pa\u00eds a participantes activas y beneficiarias de la misma. Esto hac\u00eda parte de un proyecto que los militares hab\u00edan elaborado para controlar las agencias m\u00e1s importantes del gobierno y los recursos del Estado, as\u00ed como para desarrollar una visi\u00f3n pol\u00edtica que iba m\u00e1s all\u00e1 de las fronteras de clase. El poder de los militares era tal que logr\u00f3 atraer a las \u00e9lites tradicionales, y eventualmente tambi\u00e9n a las transnacionales, posicion\u00e1ndose hasta convertirse en un agente de poder a largo plazo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"174\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_in_jail.jpg?resize=288%2C174&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244639\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_in_jail.jpg?w=288&amp;quality=100&amp;ssl=1 288w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_in_jail.jpg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_ballesteros_in_jail.jpg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, algunos miembros de esta \u00e9lite burocr\u00e1tica buscaban ganar m\u00e1s poder obteniendo parte de los grandes ingresos ilegales que estaban a la mano. Esta tentaci\u00f3n es comprensible. El dinero de la droga era significativo, y sin duda ven\u00eda acompa\u00f1ado de poder. Trabajar con las figuras del hampa les facilit\u00f3 a algunos militares los recursos necesarios para emprender nuevos negocios y ampliar su alcance pol\u00edtico y su influencia. Y, como veremos, algunas de las familias que presuntamente trabajaban con Matta Ballesteros se han convertido en parte de la nueva \u00e9lite que hoy dirige al pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si esta estrategia pas\u00f3 de los altos mandos a los bajos es algo que se desconoce, y quiz\u00e1 es irrelevante. La relaci\u00f3n del ej\u00e9rcito con Matta Ballesteros alcanz\u00f3 los niveles m\u00e1s altos del organismo. Otros miembros de la instituci\u00f3n desconoc\u00edan esa relaci\u00f3n, se beneficiaron de ella o participaron directamente en ella durante al menos una d\u00e9cada, a pesar de sus claras repercusiones para la din\u00e1mica interna del ej\u00e9rcito. Por ejemplo, hay quienes dicen que esta relaci\u00f3n pudo haber fomentado el golpe de Estado a finales de los a\u00f1os setenta, que puso al general Paz Garc\u00eda en el poder. Aunque hay poca evidencia que respalde esta afirmaci\u00f3n, el funcionario identificado como el contacto clave de Matta en el ej\u00e9rcito (Torres Arias) mantuvo sus poderosas conexiones con altos mandos militares durante a\u00f1os despu\u00e9s de que hubiera estado conectado con Matta Ballesteros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No hubo ninguna oposici\u00f3n visible a la conexi\u00f3n de los militares con Matta Ballesteros hasta que \u00e9sta puso en peligro la relaci\u00f3n de la instituci\u00f3n con Estados Unidos. Tras la captura de Matta Ballesteros en abril de 1988, The New York Times inform\u00f3 que se hab\u00edan presentado \u201chostiles enfrentamientos entre facciones\u201d del ej\u00e9rcito hondure\u00f1o en los d\u00edas previos a su detenci\u00f3n, entre aquellos que quer\u00edan seguir trabajando con el traficante y aquellos que quer\u00edan romper los v\u00ednculos con \u00e9l. El art\u00edculo menciona las audiencias del Congreso en las que Bland\u00f3n y otras personas se refer\u00edan a la complicidad del ej\u00e9rcito hondure\u00f1o con el narcotr\u00e1fico como el punto de inflexi\u00f3n.<sup>95<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los d\u00edas siguientes a la captura y extradici\u00f3n de Mata, las instituciones del Estado parec\u00edan estar en una situaci\u00f3n de confusi\u00f3n generalizada y cruce de acusaciones sobre qui\u00e9n hab\u00eda sido el responsable de lo sucedido con el narcotraficante. Aunque la captura de Matta se habr\u00eda dado por una orden emitida por un juzgado de la capital hondure\u00f1a, Salom\u00f3n Jim\u00e9nez Castro, entonces presidente de la Corte Suprema de Justicia afirm\u00f3 a los medios de prensa que ese poder del Estado hab\u00eda sido completamente ajeno a la extradici\u00f3n de Matta. Mientras tanto el Ministro de Relaciones Exteriores, declaraba que el supuesto traficante de drogas hab\u00eda sido secuestrado por una iniciativa de autoridades hondure\u00f1as en respuesta a una orden emanada del poder judicial y calificaba la situaci\u00f3n como irregular. En la entrevista el funcionario dijo tambi\u00e9n que en su oficina no se hab\u00eda registrado ninguna solicitud de extradici\u00f3n del parte del gobierno de Estados Unidos pero que estaban vigentes varios tratados de extradici\u00f3n entre ambos pa\u00edses y que uno de ellos era el de 1912 que hab\u00eda sido aprobado y ratificado por ambos pa\u00edses.&nbsp;&nbsp; Tan solo un d\u00eda antes el entonces Ministro de Gobernaci\u00f3n, Romualdo Bueso Pe\u00f1alba afirmaba tambi\u00e9n a la prensa nacional que Juan Ram\u00f3n Matta no pod\u00eda ser extraditado de Honduras porque no exist\u00eda un tratado de extradici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en vez de salvar a Honduras mediante la verg\u00fcenza p\u00fablica y un arresto ilegal, el gobierno de Estados Unidos es en parte culpable por la alianza de los militares hondure\u00f1os con los traficantes. Estados Unidos le hab\u00eda estado enviando se\u00f1ales contradictorias a su aliado, debido a sus otros intereses pol\u00edticos en la regi\u00f3n. Espec\u00edficamente, la relaci\u00f3n activa de la CIA con SETCO, la aerol\u00ednea de Matta Ballesteros, as\u00ed como con figuras como Arias Torres, en la d\u00e9cada de los ochenta, fue una luz verde no oficial de que las ganancias ilegales del mundo de la droga eran aceptables, en tanto sirvieran al prop\u00f3sito mayor de la lucha contra el comunismo. El mensaje cambi\u00f3 s\u00f3lo despu\u00e9s de que el aliado criminal de los militares hondure\u00f1os participara en el asesinato de un agente antidrogas de Estados Unidos. Este asesinato, junto con una creciente presi\u00f3n por hacer frente a la violencia del narcotr\u00e1fico en el pa\u00eds, llev\u00f3 al gobierno de Estados Unidos a dar un ultim\u00e1tum a los militares hondure\u00f1os con respecto a Matta Ballesteros: o \u00e9l o nosotros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arresto de Matta Ballesteros signific\u00f3 el final de una era para el ej\u00e9rcito hondure\u00f1o. La decadencia y la arrogancia que lo hab\u00edan caracterizado, sobre todo en la d\u00e9cada de los ochenta, llegaron a un final abrupto y p\u00fablico. Su principal benefactor oficial (Estados Unidos) esencialmente lo hab\u00eda humillado al cambiar sus prioridades y detener a su benefactor no oficial (Matta Ballesteros). La inconformidad popular que se present\u00f3 despu\u00e9s del arresto ilustra cu\u00e1nto capital pol\u00edtico y social hab\u00eda construido Matta Ballesteros en Honduras. Ilustra adem\u00e1s la frustraci\u00f3n de la poblaci\u00f3n por el hecho de que su pa\u00eds hab\u00eda sido utilizado como una base militar estadounidense durante casi una d\u00e9cada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la extraordinaria captura de Matta Ballesteros, los militares hondure\u00f1os cayeron en un purgatorio pol\u00edtico. Aunque la captura de Matta Ballesteros no caus\u00f3 este cambio, s\u00ed contribuy\u00f3 a ello. El gobierno civil no tard\u00f3 en sustituir supervisores militares que hab\u00edan dirigido varios departamentos durante a\u00f1os. Entre \u00e9stos se encontraban Hondutel, el Instituto Agrario y los servicios de inmigraci\u00f3n. APROH se distanci\u00f3 de la base militar que hab\u00eda creado. Y el gobierno restableci\u00f3 formalmente una fuerza de polic\u00eda civil, independiente del ej\u00e9rcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aun as\u00ed, varios exmilitares utilizaron este periodo para iniciar negocios y carreras pol\u00edticas, con lo cual prepararon el terreno para la siguiente generaci\u00f3n de \u00e9lites burocr\u00e1ticas. Sin duda, la \u00e9lite burocr\u00e1tica que surgi\u00f3 durante el medio siglo antes del arresto de Matta Ballesteros no desapareci\u00f3 luego de eso, sino que s\u00f3lo cambi\u00f3 de engranaje, mostr\u00e1ndose ahora como el principal organismo de lucha contra el crimen en el pa\u00eds y aprovechando su antigua alianza con el Partido Nacional. Los resultados son evidentes en la clase gobernante de hoy.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-epilogo-la-nueva-elite-burocratica-y-el-crimen-organizado\">Ep\u00edlogo: La nueva \u00e9lite burocr\u00e1tica y el crimen organizado<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El 31 de julio de 2014, las autoridades hondure\u00f1as confiscaron 17 propiedades pertenecientes a Juan Ram\u00f3n Matta Waldurraga, hijo de Juan Ram\u00f3n Matta Ballesteros.<sup>98<\/sup> &nbsp;Durante mucho tiempo ha habido rumores sobre la participaci\u00f3n de Matta Waldurraga en el tr\u00e1fico de drogas, y la familia ha tenido varios encuentros con la ley desde que Matta Ballesteros fue encarcelado. En 1993, la polic\u00eda colombiana detuvo a Jaime Garc\u00eda Garc\u00eda, cu\u00f1ado de Matta Ballesteros, y lo acus\u00f3 de tr\u00e1fico de coca\u00edna a Estados Unidos a trav\u00e9s de Costa Rica.<sup>99<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2004, un avi\u00f3n cargado de drogas ilegales aterriz\u00f3 frente a una de las propiedades de Matta Waldurraga en la provincia de Olancho, supuestamente procedente de Colombia.<sup>100<\/sup> &nbsp;En los a\u00f1os siguientes, las autoridades colombianas tambi\u00e9n confiscaron propiedades y detectaron movimientos de grandes cantidades de dinero de la familia dentro y fuera de ese pa\u00eds.<sup>101<\/sup> &nbsp;En 2005, el director de inmigraci\u00f3n de Honduras fue detenido por permitir que catorce colombianos vinculados a Matta Waldurraga ingresaran al pa\u00eds sin visas.<sup>102<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las entrevistas realizadas para este informe, funcionarios activos y retirados se refirieron con frecuencia a Matta Waldurraga como el sucesor de su padre en el tr\u00e1fico de drogas, as\u00ed como una persona que gestiona contratos del gobierno y sirve como una especie de banco informal para el hampa. Pero las recientes expropiaciones no estaban acompa\u00f1adas de una orden de arresto oficial en su contra, y Matta Waldurraga nunca ha sido acusado de ning\u00fan delito en Honduras. En declaraciones a la prensa, Matta Waldurraga se refiri\u00f3 a la operaci\u00f3n de incautaci\u00f3n de 2014 como una \u201cpayasada\u201d, y dijo que esa propiedad hab\u00eda sido heredada de su abuela.<sup>103<\/sup> &nbsp;La familia tambi\u00e9n protest\u00f3 por la confiscaci\u00f3n por parte del gobierno, pero poco pudo hacer. El gobierno hondure\u00f1o dijo que las propiedades hab\u00edan sido compradas con ingresos ilegales y que por tanto pod\u00edan ser expropiadas seg\u00fan una nueva ley que el gobierno hab\u00eda aprobado s\u00f3lo dos a\u00f1os antes.<sup>104<\/sup>&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"293\" height=\"172\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_waldurraga.jpeg?resize=293%2C172&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244490\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_waldurraga.jpeg?w=293&amp;quality=100&amp;ssl=1 293w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_waldurraga.jpeg?w=370&amp;quality=100&amp;ssl=1 370w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/matta_waldurraga.jpeg?w=400&amp;quality=100&amp;ssl=1 400w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Las acciones agresivas del gobierno contra la familia hubieran sido sorpresivas si previamente no hubiera hecho clara su intenci\u00f3n de adoptar una l\u00ednea dura contra el crimen. Desde que asumi\u00f3 la presidencia en 2014, la administraci\u00f3n de Juan Orlando Hern\u00e1ndez, miembro incondicional del Partido Nacional, con una educaci\u00f3n castrense y ascendientes militares, ha mostrado su determinaci\u00f3n de ir contra el tr\u00e1fico de drogas. Adem\u00e1s de sus acciones contra el clan de Matta Ballesteros, la administraci\u00f3n Hern\u00e1ndez captur\u00f3 a un hondure\u00f1o acusado de narcotr\u00e1fico y lo extradit\u00f3 a Estados Unidos \u2014el primer hondure\u00f1o extraditado en m\u00e1s de cien a\u00f1os<sup>105<\/sup>\u2014,&nbsp; y captur\u00f3 a tres miembros importantes del clan Valle Valle<sup>106<\/sup>,&nbsp; una poderosa familia de narcotraficantes que viven en la provincia de Cop\u00e1n, al occidental del pa\u00eds, y que, seg\u00fan un funcionario estadounidense le dijo a InSight Crime, hab\u00edan estado traficando hasta 20 toneladas de coca\u00edna por mes en el pa\u00eds.<sup>107<\/sup> &nbsp;El gobierno adem\u00e1s declar\u00f3 al pa\u00eds zona de exclusi\u00f3n a\u00e9rea para los traficantes, al aprobar una ley que autoriza a la fuerza a\u00e9rea a derribar naves sospechosas de cargar drogas en su espacio a\u00e9reo.<sup>108<\/sup> &nbsp;Hacia finales de 2014, casi la mitad de los narcotraficantes hondure\u00f1os requeridos por Estados Unidos estaban en custodia,<sup>109<\/sup> &nbsp;y los vuelos cargados con drogas hab\u00edan disminuido considerablemente, seg\u00fan entrevistas con agentes de drogas hondure\u00f1os e internacionales.<sup>110<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hern\u00e1ndez estableci\u00f3 que su administraci\u00f3n est\u00e1 firmemente en contra del crimen organizado, y lo hizo con una coalici\u00f3n que, extra\u00f1amente, evoca a la de los a\u00f1os ochenta, que estuvo dominada por los militares. Si bien no ha servido en el ej\u00e9rcito, Hern\u00e1ndez \u2014quien por mucho tiempo ha sido un ac\u00e9rrimo seguidor del Partido Nacional, y que se desempe\u00f1\u00f3 como presidente del Congreso\u2014 se ha rodeado de numerosos militares retirados y en servicio. Entre ellos se encuentra su hermano Am\u00edlcar Hern\u00e1ndez, quien es uno de sus m\u00e1s importantes asesores de seguridad; el general retirado Juli\u00e1n Pacheco, quien ha ocupado varios puestos importantes, incluyendo el de ministro de Seguridad, y \u00d3scar \u00c1lvarez, un exoficial de las Fuerzas Especiales de Honduras que se form\u00f3 y entren\u00f3 en Estados Unidos y ha desempe\u00f1ado cargos ministeriales y en el Congreso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a Pacheco, es sin duda el miembro m\u00e1s poderoso de la \u00e9lite burocr\u00e1tica desde que Paz Garc\u00eda abandon\u00f3 el cargo en 1981. Despu\u00e9s de ganar la presidencia, Hern\u00e1ndez inmediatamente design\u00f3 al exjefe de inteligencia militar como director de la FUSINA, una fuerza especial interinstitucional creada para luchar contra el crimen organizado. Entre otras funciones, FUSINA tiene control sobre la Fuerza Nacional Antiextorsion (FNA). La FNA administra la \u00fanica unidad de interceptaci\u00f3n telef\u00f3nica del gobierno y al parecer mantiene estricto control sobre las operaciones de inteligencia. Los poderes de Pacheco aumentaron a principios de 2015, cuando se convirti\u00f3 en el primer general militar activo del pa\u00eds en ser nombrado ministro de Seguridad. \u00c9l debi\u00f3 retirarse oficialmente del servicio para asumir el cargo, pero en una entrevista con InSight Crime afirm\u00f3 que los rumores acerca de su alcance eran exagerados.<sup>111<\/sup> &nbsp;\u201cNo tengo tanto poder como la gente cree; eso no es cierto\u201d, dijo. \u201cAdem\u00e1s, el \u00fanico poder que puedo tener es la experiencia que he logrado acumular en una carrera de 35 a\u00f1os\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"866\" height=\"1024\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=866%2C1024&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244641\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=866%2C1024&amp;quality=100&amp;ssl=1 866w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=254%2C300&amp;quality=100&amp;ssl=1 254w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=768%2C908&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=1300%2C1536&amp;quality=100&amp;ssl=1 1300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=1733%2C2048&amp;quality=100&amp;ssl=1 1733w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=1200%2C1418&amp;quality=100&amp;ssl=1 1200w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=1568%2C1853&amp;quality=100&amp;ssl=1 1568w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=400%2C473&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?resize=706%2C834&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3.jpg?w=1980&amp;quality=100&amp;ssl=1 1980w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Current-formerMilitaryOfficEspanol-3-866x1024.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 866px) 100vw, 866px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Otro consejero cercano al presidente es \u00c1lvarez, quien tuvo entrenamiento con las Fuerzas Especiales del Ej\u00e9rcito de Estados Unidos antes de servir en las Fuerzas Especiales de Honduras. Fue ministro de Seguridad en 2002 y luego de nuevo en 2010. \u00c1lvarez es un descendiente de la \u00e9lite burocr\u00e1tica militar: su t\u00edo fue el general Gustavo \u00c1lvarez Mart\u00ednez, el fundador de APROH, la asociaci\u00f3n empresarial constituida por militares. Como un poderoso miembro del Partido Nacional, \u00c1lvarez ha sido asesor cercano de m\u00e1s de un presidente. Le ayud\u00f3 a Porfirio Lobo a ser elegido y luego sirvi\u00f3 como su ministro de Seguridad. M\u00e1s tarde hizo lo mismo para Hern\u00e1ndez, trabajando en su campa\u00f1a y ayud\u00e1ndole a dise\u00f1ar su estrategia de seguridad. \u00c1lvarez es actualmente congresista y se desempe\u00f1a como jefe de la bancada del Partido Nacional en el Congreso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los confidentes cercano a \u00c1lvarez durante a\u00f1os, y que pertenece al mismo partido, proviene tambi\u00e9n de una importante familia de militares. Armando Calidonio Alvarado sirvi\u00f3 como viceministro de Seguridad cuando \u00c1lvarez fue ministro entre 2002 y 2005, y luego de nuevo entre 2010 y 2011. Adem\u00e1s trabaj\u00f3 en las campa\u00f1as de Lobo y Hern\u00e1ndez y lleg\u00f3 a ser congresista. En 2013, fue elegido alcalde de San Pedro Sula. El padre de Calidonio, tambi\u00e9n llamado Armando Calidonio, fue uno de los acusados de tener v\u00ednculos con la red de Matta Ballesteros despu\u00e9s del asesinato de los Ferrari.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un hecho a los gobiernos militares de los a\u00f1os 1970, Hern\u00e1ndez ha llenado el gobierno de personal militar en cargos que han sido civiles tradicionalmente. Adem\u00e1s de Pacheco, nombr\u00f3 a militares como jefes de la aeron\u00e1utica civil, el sistema penitenciario, los puertos nacionales, las \u201czonas de desarrollo\u201d especiales, el instituto de desarrollo agropecuario, y la autoridad en materia de vivienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno de Hern\u00e1ndez es, en esencia, un h\u00edbrido de \u00e9lites terratenientes y burocr\u00e1ticas tradicionales. Los antecedentes del propio presidente ilustran esta mezcla. Nacido en una familia de 17 hijos, Hern\u00e1ndez estudi\u00f3 en una escuela militar. Su familia era de peque\u00f1os caficultores y al parecer \u00e9l progres\u00f3 gracias a sus conexiones pol\u00edticas y su matrimonio a Ana Garc\u00eda Car\u00edas, una descendente del General Tiburcio Car\u00edas Andino, el mismo que puso en marcha los cambios que resultaron ser claves en la transformaci\u00f3n a los militares a una \u00e9lite burocr\u00e1tica. Estas conexiones han resultado en negocios lucrativos. Se dice que es due\u00f1o de fincas cafeteras, entre otras explotaciones agr\u00edcolas, as\u00ed como de hoteles y estaciones de radio y televisi\u00f3n.<sup>112<\/sup> &nbsp;Hern\u00e1ndez es adem\u00e1s un hombre poderoso en el Partido Nacional. Ha obtenido apoyo para importantes personalidades del partido, como Porfirio Lobo y su hermano, Ram\u00f3n, de quienes tambi\u00e9n ha recibido apoyo, y supuestamente dirige el partido. Ha sido vinculado a un misterioso grupo de presi\u00f3n llamado Colibr\u00ed, que al parecer ha dise\u00f1ado lucrativos contratos y esquemas de comisiones para sus miembros y simpatizantes.<sup>113<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el poder de la administraci\u00f3n de Hern\u00e1ndez es m\u00e1s evidente en las fuerzas de seguridad. Adem\u00e1s de centralizar el control y el flujo de la inteligencia mediante el ministro de Seguridad, Juli\u00e1n Pacheco, como presidente del Congreso ide\u00f3 una ley que cre\u00f3 una polic\u00eda militar de 5.000 miembros.<sup>114<\/sup> &nbsp;Como presidente, ha consolidado ese organismo. Hern\u00e1ndez y Pacheco insisten en que la polic\u00eda militar es s\u00f3lo una medida temporal, pero en 2015 Hern\u00e1ndez intent\u00f3 consagrar dicha entidad en la Constituci\u00f3n del pa\u00eds. La medida fracas\u00f3, pero Hern\u00e1ndez dijo que volver\u00eda a intentarlo m\u00e1s adelante.<sup>115&nbsp;<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El alcance y el poder de la \u00e9lite burocr\u00e1tica militar impresionan a algunos observadores, especialmente porque la relaci\u00f3n de la instituci\u00f3n con el crimen organizado est\u00e1 a\u00fan en duda. El primer per\u00edodo de \u00c1lvarez como ministro de Seguridad, por ejemplo, coincidi\u00f3 con una ofensiva contra las pandillas de Honduras, llevada a cabo, en parte, por un escuadr\u00f3n de la muerte dirigido por la polic\u00eda, conocido como Los Magn\u00edficos.<sup>116<\/sup> &nbsp;Un presunto miembro de este grupo era un comandante de la polic\u00eda llamado Juan Carlos \u201cEl Tigre\u201d Bonilla. La inspectora de polic\u00eda en aquel momento dijo que hab\u00eda comenzado 13 investigaciones internas sobre las actividades de Bonilla, incluyendo el asesinato de varios hombres que hab\u00edan secuestrado y asesinado al exministro Reginald Panting, el mismo hombre que hab\u00eda considerado p\u00fablicamente la oferta de Matta Ballesteros de ayudar a pagar la deuda del pa\u00eds.<sup>117<\/sup> &nbsp;Los casos fueron cerrados, dijo la inspectora, por orden de \u00c1lvarez.<\/p>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"alignleft size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"661\" src=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Juan_Orlando_Hernandez.jpg?resize=900%2C661&#038;quality=100&#038;ssl=1\" alt=\"\" class=\"wp-image-244499\" srcset=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Juan_Orlando_Hernandez.jpg?w=900&amp;quality=100&amp;ssl=1 900w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Juan_Orlando_Hernandez.jpg?resize=300%2C220&amp;quality=100&amp;ssl=1 300w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Juan_Orlando_Hernandez.jpg?resize=768%2C564&amp;quality=100&amp;ssl=1 768w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Juan_Orlando_Hernandez.jpg?resize=400%2C294&amp;quality=100&amp;ssl=1 400w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Juan_Orlando_Hernandez.jpg?resize=706%2C519&amp;quality=100&amp;ssl=1 706w, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/10\/Juan_Orlando_Hernandez.jpg?w=370&amp;quality=100&amp;ssl=1 370w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Aunque el presidente Hern\u00e1ndez no se ha visto implicado en actividades delictivas, en su campa\u00f1a presidencial participaron algunos miembros cuestionables, como Hugo Ard\u00f3n, quien encabez\u00f3 la campa\u00f1a de Hern\u00e1ndez en la parte occidental del pa\u00eds. Ard\u00f3n dirigi\u00f3 el organismo encargado de las carreteras durante a\u00f1os hasta junio de 2015, tiempo durante el cual aprob\u00f3 millones de d\u00f3lares en contratos gubernamentales con empresas dirigidas por grupos criminales, como Los Cachiros, un poderoso clan que sol\u00eda tener su base en la provincia de Col\u00f3n (y que es tema de nuestro segundo estudio de caso). El hermano de Ard\u00f3n, Alexander, fue alcalde de El Para\u00edso, Cop\u00e1n, un importante corredor para el narcotr\u00e1fico. Como alcalde, Alexander se hizo tristemente c\u00e9lebre por haber reconstruido la alcald\u00eda a imagen de la Casa Blanca, incluso con un helipuerto. Las autoridades le dijeron a InSight Crime en 2015 que estaban investigando a Alexander por tr\u00e1fico de drogas.<sup>118<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Partido Nacional ha habido importantes figuras conectadas con actividades criminales. Ram\u00f3n Lobo, exdiputado y hermano del expresidente Porfirio \u201cPepe\u201d Lobo, ha estado bajo investigaciones por a\u00f1os. Un hijo de Ram\u00f3n, Jorge, fue detenido en 2002 cargando US$6 millones. Pag\u00f3 cinco a\u00f1os de prisi\u00f3n. En 2003, su hija, Margarita, fue herida en un ataque de la organizaci\u00f3n criminal Los Cachiros, debido a un traficante rival que supuestamente estaba saliendo con Margarita en ese momento. En 2012, Ram\u00f3n asisti\u00f3 a la inauguraci\u00f3n de una estaci\u00f3n de gasolina y un centro comercial en el estado de Col\u00f3n; el centro comercial fue construido por Javier Rivera Maradiaga, el l\u00edder de Los Cachiros.<sup>119<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pepe Lobo tambi\u00e9n ha estado conectado con elementos criminales. Durante su per\u00edodo en el cargo, el hijo de Lobo public\u00f3 en Facebook una foto del entonces presidente con Jos\u00e9 Natividad \u201cChepe\u201d Luna Pereira. Luna, ciudadano salvadore\u00f1o requerido en ese momento por Estados Unidos por narcotr\u00e1fico, aparentemente era el propietario y director de una flota de autobuses y camiones desde su sede en San Pedro Sula. Cuando fue detenido en Honduras en 2011, durante la administraci\u00f3n de Lobo, las autoridades salvadore\u00f1as y estadounidenses trataron de deportarlo a El Salvador, donde enfrentaba cargos por tr\u00e1fico de drogas, pero un juez misteriosamente lo liber\u00f3 antes de que pudieran sustentar los cargos.<sup>120<\/sup> Luna fue asesinado en San Pedro Sula en el a\u00f1o 2014.<sup>121<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia Lobo ha seguido siendo objeto de investigaciones desde que Lobo termin\u00f3 su periodo en el cargo.<sup>122<\/sup> Seg\u00fan informes, en mayo de 2015 el hijo de Lobo, Fabio Lobo Lobo, fue capturado en Hait\u00ed en una operaci\u00f3n conjunta entre Hait\u00ed y Estados Unidos, y enviado a Nueva York para enfrentar cargos por narcotr\u00e1fico.&nbsp; Lobo no defendi\u00f3 a su hijo y le dijo a la prensa que \u00e9l deber\u00eda afrontar las consecuencias de sus actos. En un tuit, el embajador de Estados Unidos en Honduras, James Nealon, declar\u00f3: \u201cNadie est\u00e1 por encima de la ley\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*&nbsp;<em>Este informe fue escrito por Steven Dudley. Dudley, Javier Mel\u00e9ndez \u2014&nbsp;que actu\u00f3 como coordinador de investigaci\u00f3n para este proyecto \u2014&nbsp;junto con investigadores del Centro de Investigaci\u00f3n y Promoci\u00f3n de los Derechos Humanos (<a href=\"https:\/\/www.ciprodeh.org.hn\/\" target=\"_blank\" rel=\"noopener\">CIPRODEH<\/a>) y la Asociaci\u00f3n para una Sociedad m\u00e1s Justa (<a href=\"https:\/\/www.ciprodeh.org.hn\/\" target=\"_blank\" rel=\"noopener\">ASJ<\/a>), asistieron en la investigaci\u00f3n y la producci\u00f3n de este informe. Mapa por Jorge Mej\u00eda. Gr\u00e1ficos por Andrew J Higgens.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-notas-al-pie\">\n<hr>\n<p>Notas al pie<\/p><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"A\">[1]<\/a> James LeMoyne, \u201cMilitary Officers in Honduras Are Linked to the Drug Trade\u201d, New York Times, 12 de febrero de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/02\/12\/world\/military-officers-in-honduras-are-linked-to-the-drug-trade.html\">https:\/\/www.nytimes.com\/1988\/02\/12\/world\/military-officers-in-honduras-are-linked-to-the-drug-trade.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vea tambi\u00e9n: Steven Dudley y Michael Lohmuller, \u201cDocumentos revelan v\u00ednculos entre la CIA y Guadalajara, no un complot\u201d 13 de noviembre de 2013. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/analisis\/documentos-revelan-vinculos-entre-la-cia-y-guadalajara-no-complot\/?highlight=WyJjb21wbG90Il0=\">\/noticias\/analisis\/documentos-revelan-vinculos-entre-la-cia-y-guadalajara-no-complot?highlight=WyJjb21wbG90Il0=<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"B\">[2]<\/a> Larry Rohter, \u201cSeized Honduran: Drug Baron or a Robin Hood?\u201d, The New York Times, 16 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html\">https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"C\">[3]<\/a> Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012), p. 276.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"D\">[4]<\/a> Senado de Estados Unidos, \u201cDrugs, Law Enforcement and Foreign Policy: A Report Prepared by the Subcommittee on Terrorism, Narcotics and International Operations of the Committee on Foreign Relations\u201d (a.k.a., the Kerry Committee Report), Diciembre de 1988, p. 77.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"E\">[5]<\/a> Declaraci\u00f3n juramentada referida en el Departamento de Estados de Estados Unidos, en cable a la embajada de Estados Unidos en Honduras, \u201cUpdate on USG Prosecutions of Matta\u201d, 15 de julio de 1988.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"F\">[6]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"G\">[7]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"H\">[8]<\/a> Noveno Circuito de Apelaciones de Estados Unidos, \u201cUSA v Matta Ballesteros\u201d, No. 91-50336, 1995.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"I\">[9]<\/a> Departamento de Estados de Estados Unidos, cable a la embajada de Estados Unidos en Colombia, \u201cInformation on the arrest of Matta Ballesteros\u201d, 25 de mayo de 1988.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"J\">[10]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"K\">[11]<\/a> Cable de la Embajada de Estados Unidos al Departamento de Estado, et al. \u201cHonduran public reaction to Matta\u2019s arrest\u201d, 8 de abril de 1988.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"L\">[12]<\/a> Los Angeles Times, \u201c1,000 Attack US Embassy in Honduras\u201d, 8 de abril de 1988. Disponible en: <a href=\"https:\/\/articles.latimes.com\/1988-04-08\/news\/mn-1123_1_u-s-embassy\">https:\/\/articles.latimes.com\/1988-04-08\/news\/mn-1123_1_u-s-embassy<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"M\">[13]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"N\">[14]<\/a> El Heraldo, \u201cLas protestas m\u00e1s violentas contra EUA en Latinoam\u00e9rica\u201d, 14 de abril de 1988.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"O\">[15]<\/a> Fuerzas Armadas de Honduras, \u201cHistoria de las Fuerzas Armadas de Honduras.\u201d Disponible en: <a href=\"https:\/\/www.ffaah.mil.hn\/\">https:\/\/www.ffaah.mil.hn\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"P\">[16]<\/a> El ej\u00e9rcito era usado para controlar a los trabajadores en huelga a nombre de las compa\u00f1\u00edas bananeras. Vea por ejemplo Thomas M. Leonard, \u201cThe History of Honduras\u201d (Santa Barbara, CA, 2011), p. 88; y Robert Jackson Alexander, Eldon M. Parke, \u201cA History of Organized Labor in Panama and Central America\u201d (Westport, CT, 2008), p. 122.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"Q\">[17]<\/a> Instituto de Prevision Militar, \u201cHistoria y Creacion.\u201d Disponible en: <a href=\"https:\/\/grupoipm.hn\/sobre-ipm\/historia-y-creacion\/\">https:\/\/grupoipm.hn\/sobre-ipm\/historia-y-creacion\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"R\">[18]<\/a> El Partido Nacional es el m\u00e1s conservador de los dos partidos dominantes; fue fundado por un general y se ali\u00f3 con los militares durante el per\u00edodo del r\u00e9gimen militar. Vea: \u201cTwo Traditionally Dominant Parties\u201d, en Tim Merrill (ed.), \u201cHonduras: A Country Study\u201d (Washington, DC 1995). Disponible en: <a href=\"https:\/\/countrystudies.us\/honduras\/\">https:\/\/countrystudies.us\/honduras\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/countrystudies.us\/honduras\/\"><\/a><a name=\"S\">[19]<\/a> US Agency for International Development (USAID), \u201cU.S. Overseas Loans and Grants: Obligations and Loan Authorizations, 1 de Julio de 1945-30 de septiembre de 2012.\u201d Disponible en: <a href=\"https:\/\/eads.usaid.gov\/gbk\/\">https:\/\/eads.usaid.gov\/gbk\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"T\">[20]<\/a> Senado de Estados Unidos, \u201cDrugs, Law Enforcement and Foreign Policy: A Report Prepared by the Subcommittee on Terrorism, Narcotics and International Operations of the Committee on Foreign Relations\u201d (a.k.a., the Kerry Committee Report), Diciembre de 1988, p.73.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"U\">[21]<\/a> Peter Meyer, \u201cHonduras-US Relations\u201d, Congressional Research Service, 24 de julio de 2013, p. 19. Disponible en: <a href=\"https:\/\/www.fas.org\/sgp\/crs\/row\/RL34027.pdf\">https:\/\/www.fas.org\/sgp\/crs\/row\/RL34027.pdf<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"V\">[22]<\/a> Leslie Bethel (ed.), \u201cThe Cambridge History of Latin America, Volume 7: 1930 to the Present\u201d (New York, 1990), p. 311.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"W\">[23]<\/a> Manuel Torres Calder\u00f3n, \u201cLa \u00e9lite, su orientaci\u00f3n y fundamentos geogr\u00e1ficos en Honduras\u201d; se publicar\u00e1 pr\u00f3ximamente en un libro de FLACSO-Costa Rica editado por Eric Hershberg, titulado \u201c\u00c9lites y la configuraci\u00f3n del poder en Centroam\u00e9rica: Din\u00e1micas de acumulaci\u00f3n y sus consecuencias, Vol. 2.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"X\">[24]<\/a> Tanya M. Kerssen, \u201cGrabbing Power: The New Struggles for Land, Food and Democracy in Northern Honduras\u201d (Oakland, CA, 2013), p. 8.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"Y\">[25]<\/a> Manuel Torres Calder\u00f3n, \u201cLa \u00e9lite, su orientaci\u00f3n y fundamentos geogr\u00e1ficos en Honduras\u201d; se publicar\u00e1 pr\u00f3ximamente en un libro de FLACSO-Costa Rica editado por Eric Hershberg, titulado \u201c\u00c9lites y la configuraci\u00f3n del poder en Centroam\u00e9rica: Din\u00e1micas de acumulaci\u00f3n y sus consecuencias, Vol. 2.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<a name=\"Z\">[26]<\/a> La familia Matta Ballesteros cre\u00f3 un sitio web dedicado al \u201cabuelo, padre, esposo, hermano y amigo\u201d. Disponible en: <a href=\"https:\/\/www.juanramonmata.com\/origenes\/\">https:\/\/www.juanramonmata.com\/origenes\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AA\">[27]<\/a> Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012),, p. 271.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AB\">[28]<\/a> El Pais, \u201cDel autob\u00fas a la avioneta\u201d, 4 de diciembre de 1990. Disponible en: <a href=\"https:\/\/elpais.com\/diario\/1990\/12\/04\/espana\/660265220_850215.html\">https:\/\/elpais.com\/diario\/1990\/12\/04\/espana\/660265220_850215.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AC\">[29]<\/a> TK \u2013 footnote needed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AD\">[30]<\/a> Larry Rohter, \u201cSeized Honduran: Drug Baron or a Robin Hood?\u201d, The New York Times, 16 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html\">https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AE\">[31]<\/a> Michael Kenney, \u201cFrom Pablo to Osama: Trafficking and Terrorist Networks, Government Bureaucracies, and Competitive Adaptation\u201d (University Park, PA, 2007), p. 240.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AF\">[32]<\/a> Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012), p. 271.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AG\">[33]<\/a> Larry Rohter, \u201cSeized Honduran: Drug Baron or a Robin Hood?\u201d, The New York Times, 16 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html\">https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AH\">[34]<\/a> Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012), p. 272.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AI\">[35]<\/a> El n\u00facleo de esta organizaci\u00f3n dar\u00e1 origen a algunos de los grupos criminales m\u00e1s famosos de M\u00e9xico: los carteles de Sinaloa, Ju\u00e1rez y Tijuana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AJ\">[36]<\/a> Noveno Circuito de Apelaciones de Estados Unidos, \u201cUSA v Matta Ballesteros\u201d, No. 91-50336, 1995.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AK\">[37]<\/a> Thelma Mej\u00eda, \u201cUnfinished Business: The Military and Drugs in Honduras\u201d, Transnational Institute, 1 de diciembre de 1997. Disponible en: <a href=\"https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras\">https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AL\">[38]<\/a> Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012), p. 277.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AM\">[39]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AN\">[40]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AO\">[41]<\/a> Thelma Mej\u00eda, \u201cUnfinished Business: The Military and Drugs in Honduras\u201d, Transnational Institute, 1 de diciembre de 1997. Disponible en: <a href=\"https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras\">https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AP\">[42]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AQ\">[43]<\/a> Vea, entre otras noticias de La Prensa: \u201cPag\u00f3 para hacer desaparecer fichas delictivas en la DNI\u201d, 2 de abril de 1986, p. 4; \u201cCrimen de los esposos Ferrari, deuda de Matta ante la justicia hondure\u00f1a\u201d, 1 de abril de 1986, p. 5; \u201cEn libertad hermanos Reyes, responsables de la muerte de los esposos Ferrari\u201d, 4 de septiembre de 1996, p. 6; \u201cEl caso Ferrari: Una historia de mafias, venganzas, terror y romance\u201d, 1 de abril de 1986, p. 2. Varios de estos informes tambi\u00e9n se mencionan en Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AR\">[44]<\/a> Senado de Estados Unidos, \u201cDrugs, Law Enforcement and Foreign Policy: A Report Prepared by the Subcommittee on Terrorism, Narcotics and International Operations of the Committee on Foreign Relations\u201d (a.k.a., the Kerry Committee Report), Diciembre de 1988, pp. 74-75.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AS\">[45]<\/a> James LeMoyne, \u201cMilitary Officers in Honduras Are Linked to the Drug Trade\u201d, New York Times, 12 de febrero de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/02\/12\/world\/military-officers-in-honduras-are-linked-to-the-drug-trade.html\">https:\/\/www.nytimes.com\/1988\/02\/12\/world\/military-officers-in-honduras-are-linked-to-the-drug-trade.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AT\">[46]<\/a> Thelma Mej\u00eda, \u201cUnfinished Business: The Military and Drugs in Honduras\u201d, Transnational Institute, 1 de diciembre de 1997. Disponible en: <a href=\"https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras\">https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AU\">[47]<\/a> John Saunders, \u201cDrug fighter is silenced\u201d, The Globe and Mail, 27 de julio de 1978.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AV\">[48]<\/a> Thelma Mej\u00eda, \u201cUnfinished Business: The Military and Drugs in Honduras\u201d, Transnational Institute, 1 de diciembre de 1997. Disponible en: https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AX\">[49]<\/a> La Prensa, \u201cAbsuelto Ram\u00f3n Matta\u201d, 23 de agosto de 1986, pp. 4-5. Citado en Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AY\">[50]<\/a> Thelma Mej\u00eda, \u201cUnfinished Business: The Military and Drugs in Honduras\u201d, Transnational Institute, 1 de diciembre de 1997. Disponible en: <a href=\"https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras\">https:\/\/www.tni.org\/article\/unfinished-business-military-and-drugs-honduras<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AZ\">[51]<\/a> Peter Dale Scott y Jonathan Marshall, \u201cCocaine Politics: Drugs, Armies, and the CIA in Central America\u201d (Berkeley, CA, 1998), p. 54.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AAA\">[52]<\/a> US Congress, House Committee on Foreign Affairs, \u201cNarcotics review in Central America: Hearing before the Committee on Foreign Affairs, House of Representatives, One Hundredth Congress, second session, March 10, 1988\u201d (Washington DC, 1988), p. 79.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AAB\">[53]<\/a> Senado de Estados Unidos, \u201cDrugs, Law Enforcement and Foreign Policy: A Report Prepared by the Subcommittee on Terrorism, Narcotics and International Operations of the Committee on Foreign Relations\u201d (a.k.a., the Kerry Committee Report), Diciembre de 1988, pp. 74-75.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"AAC\">[54]<\/a> Ib\u00edd, p. 75.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n55\">[55]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n56\">[56]<\/a> \u201cDrugs, Law Enforcement And Foreign Policy: Report By The Committee On Foreign Relations, US Senate\u201d (Washington, DC, 1989), p. 74.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n57\">[57]<\/a> Senado de Estados Unidos, \u201cDrugs, Law Enforcement and Foreign Policy: A Report Prepared by the Subcommittee on Terrorism, Narcotics and International Operations of the Committee on Foreign Relations\u201d (a.k.a., the Kerry Committee Report), Diciembre de 1988, p. 43.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n58\">[58]<\/a> Ib\u00edd, p. 45.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n59\">[59]<\/a> Al menos un informe contradice ligeramente esta afirmaci\u00f3n. Dice que Torres Arias fue enviado a Argentina en 1981, supuestamente para sacarlo del camino. Fue absuelto en 1982. Vea: Doyle McManus y Ronald J. Ostrow, \u201cU.S. Aides Link Honduran Military Chief, Drug Trade\u201d, 13 February 1988. Disponible en: <a href=\"https:\/\/articles.latimes.com\/1988-02-13\/news\/mn-10860_1_honduran-military\">https:\/\/articles.latimes.com\/1988-02-13\/news\/mn-10860_1_honduran-military<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n60\">[60]<\/a> Senado de Estados Unidos, \u201cDrugs, Law Enforcement and Foreign Policy: A Report Prepared by the Subcommittee on Terrorism, Narcotics and International Operations of the Committee on Foreign Relations\u201d (a.k.a., the Kerry Committee Report), Diciembre de 1988, p. 75.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n61\">[61]<\/a> Ib\u00edd, p. 78.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n62\">[62]<\/a> Ib\u00edd, p. 76.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n63\">[63]<\/a> Ib\u00edd, p. 79.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n64\">[64]<\/a> Entrevista de InSight Crime con el representante del Ministro de Asuntos Exteriores, Tegucigalpa, 11 de octubre 2013.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n65\">[65]<\/a> Ioan Grillo, \u201cEl Narco\u201d (New York, NY, 2011), pp. 66-67.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n66\">[66]<\/a> Philip Shenon, \u201cUS Said to have Tapes of a Drug Agent\u2019s Torture\u201d, The New York Times, 16 de febrero de 1986. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1986\/02\/16\/us\/us-said-to-have-tapes-of-a-drug-agent-s-torture.html\">https:\/\/www.nytimes.com\/1986\/02\/16\/us\/us-said-to-have-tapes-of-a-drug-agent-s-torture.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n67\">[67]<\/a> Associated Press, \u201cTapes of Agent Slain by Captors: \u2018Don\u2019t Hit Me,\u2019\u201d 6 de agosto de 1988. Obtenido mediante The New York Times. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/08\/06\/us\/tapes-of-agent-slain-by-captors-don-t-hit-me.html\">https:\/\/www.nytimes.com\/1988\/08\/06\/us\/tapes-of-agent-slain-by-captors-don-t-hit-me.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n68\">[68]<\/a> Christopher Lehmann-Haupt, \u201cBooks of The Times; Behind the Torture-Death of a US Drug Agent\u201d, The New York Times, 13 de octubre de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/10\/13\/books\/books-of-the-times-behind-the-torture-death-of-a-us-drug-agent.html\">https:\/\/www.nytimes.com\/1988\/10\/13\/books\/books-of-the-times-behind-the-torture-death-of-a-us-drug-agent.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n69\">[69]<\/a> Esta fuga implic\u00f3 un presunto soborno, que se cree que fue de 1 o 2 millones de d\u00f3lares. Vea: US Congress, House Committee on Foreign Affairs, op. cit., p. 77. Vea tambi\u00e9n: Senado de Estados Unidos, \u201cDrugs, Law Enforcement and Foreign Policy: A Report Prepared by the Subcommittee on Terrorism, Narcotics and International Operations of the Committee on Foreign Relations\u201d (a.k.a., the Kerry Committee Report), Diciembre de 1988, p. 77.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n70\">[70]<\/a> Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012), p. 276.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n71\">[71]<\/a> Collier, Robert. \u201cHonduras Drug Traffic Quietly Overlooked.\u201d Pacific News Service, 20 de mayo de 1988. Vea tambi\u00e9n: Larry Rohter, \u201cSeized Honduran: Drug Baron or a Robin Hood?\u201d, The New York Times, 16 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html\">https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n72\">[72]<\/a> Larry Rohter, \u201cSeized Honduran: Drug Baron or a Robin Hood?\u201d, The New York Times, 16 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html\">https:\/\/www.nytimes.com\/1988\/04\/16\/world\/danli-journal-seized-honduran-drug-baron-or-a-robin-hood.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n73\">[73]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n74\">[74]<\/a> Loren Jenkins, \u201cUS Reported to Blame Colonel for Honduran Delay During Riot\u201d, Washington Post, 12 de abril de 1988. Disponible en: <a href=\"https:\/\/www.washingtonpost.com\/archive\/politics\/1988\/04\/12\/us-reported-to-blame-colonel-for-honduran-delay-during-riot\/4b7a01e8-6992-411f-b4eb-68a6ed91d3fe\/\">https:\/\/www.washingtonpost.com\/archive\/politics\/1988\/04\/12\/us-reported-to-blame-colonel-for-honduran-delay-during-riot\/4b7a01e8-6992-411f-b4eb-68a6ed91d3fe\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n75\">[75]<\/a> Julie Marie Bunck y Michael Ross Fowler, \u201cBribes, Bullets, and Intimidation: Drug Trafficking and the Law in Central America\u201d (University Park, PA, 2012), p. 276.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n76\">[76]<\/a> US Congress, House Committee on Foreign Affairs, \u201cNarcotics review in Central America\u2026\u201d op. cit., p. 79.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n77\">[77]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n78\">[78]<\/a> Rohter, \u201cMilitary Infighting Seen Behind Honduran\u2019s Arrest\u201d, The New York Times, 15 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/15\/world\/military-infighting-seen-behind-honduran-s-arrest.html\">https:\/\/www.nytimes.com\/1988\/04\/15\/world\/military-infighting-seen-behind-honduran-s-arrest.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n79\">[79]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n80\">[80]<\/a> US Congress, House Committee on Foreign Affairs, \u201cNarcotics review in Central America\u2026\u201d op. cit., p. 79.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n81\">[81]<\/a> En mayo de 1988, las autoridades de Estados Unidos arrestaron al hermanastro del general Regalado, coronel Rigoberto Regalado, en Miami, cuando encontraron cerca de 26 kilos de coca\u00edna en su equipaje. El coronel Regalado era el embajador de Honduras en Panam\u00e1 en ese momento. (Vea: Stephen Kinzer, \u201cHondurans\u2019 Trust of Military Leaders Plummets With Drug Arrest\u201d, 25 de mayo de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/05\/25\/world\/hondurans-trust-of-military-leaders-plummets-with-drug-arrest.html\">https:\/\/www.nytimes.com\/1988\/05\/25\/world\/hondurans-trust-of-military-leaders-plummets-with-drug-arrest.html<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n82\">[82]<\/a> US Congress, House Committee on Foreign Affairs, \u201cNarcotics review in Central America\u2026\u201d op. cit., p. 3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n83\">[83]<\/a> Ib\u00edd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n84\">[84]<\/a> Ib\u00edd, p. 37.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n85\">[85]<\/a> Elaine Sciolino, \u201cDrugs and Honduras: US Concerned\u201d, The New York Times, 17 de febrero de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/02\/18\/world\/drugs-and-honduras-us-concerned.html\">https:\/\/www.nytimes.com\/1988\/02\/18\/world\/drugs-and-honduras-us-concerned.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n86\">[86] <\/a>Noveno Circuito de Apelaciones de Estados Unidos, \u201cUSA v Matta Ballesteros\u201d, No. 91-50336, 1995.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n87\">[87]<\/a> Rohter, \u201cMilitary Infighting Seen Behind Honduran\u2019s Arrest\u201d, The New York Times, 15 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/15\/world\/military-infighting-seen-behind-honduran-s-arrest.html\">https:\/\/www.nytimes.com\/1988\/04\/15\/world\/military-infighting-seen-behind-honduran-s-arrest.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n88\">[88]<\/a> Associated Press, \u201cHonduran leader acts to put down anti-U.S. protests\u201d, 9 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/09\/world\/honduran-leader-acts-to-put-down-anti-us-protests.html\">https:\/\/www.nytimes.com\/1988\/04\/09\/world\/honduran-leader-acts-to-put-down-anti-us-protests.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n89\">[89]<\/a> John H. Lee, \u201cCamarena Figure Gets 3 Life Terms\u201d, 9 de mayo de 1991. Disponible en: <a href=\"https:\/\/articles.latimes.com\/1991-05-09\/local\/me-1914_1_honduran-juan-matta-ballesteros\">https:\/\/articles.latimes.com\/1991-05-09\/local\/me-1914_1_honduran-juan-matta-ballesteros<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n90\">[90]<\/a> James LeMoyne, \u201cMilitary Officers in Honduras Are Linked to the Drug Trade\u201d, New York Times, 12 de febrero de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/02\/12\/world\/military-officers-in-honduras-are-linked-to-the-drug-trade.html\">https:\/\/www.nytimes.com\/1988\/02\/12\/world\/military-officers-in-honduras-are-linked-to-the-drug-trade.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n91\">[91]<\/a> Entrevista de InSight Crime con coronel del ej\u00e9rcito que prefiere mantenerse an\u00f3nimo. Tegucigalpa. Fecha:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n92\">[92]<\/a> Falta nota al pie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n93\">[93]<\/a> Entrevista de InSight Crime con analista pol\u00edtico que prefiere mantenerse an\u00f3nimo. Tegucigalpa, 25 de abril de 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n94\">[94]<\/a> Entrevista de InSight Crime, periodista (an\u00f3nimo?), Honduras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n95\">[95]<\/a> Rohter, \u201cMilitary Infighting Seen Behind Honduran\u2019s Arrest\u201d, The New York Times, 15 de abril de 1988. Disponible en: <a href=\"https:\/\/www.nytimes.com\/1988\/04\/15\/world\/military-infighting-seen-behind-honduran-s-arrest.html\">https:\/\/www.nytimes.com\/1988\/04\/15\/world\/military-infighting-seen-behind-honduran-s-arrest.html<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n96\">[96]<\/a> El Heraldo, \u201cPoder Ejecutivo es el responsable exclusivo de la extradici\u00f3n de Matta\u201d. 7 April, 1988.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n97\">[97]<\/a> El Heraldo, \u201cBueso Pe\u00f1alba: no se pod\u00eda deportar\u201d. 6 April, 1988.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n98\">[98]<\/a> Kyra Gurney, \u201cConfiscaci\u00f3n de inmuebles de narco vinculado a la CIA es el m\u00e1s reciente golpe contra la impunidad en Honduras\u201d, InSight Crime, 4 de agosto de 2014. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/confiscacion-inmuebles-narco-vinculado-cia-reciente-golpe-contra-impunidad-honduras\/?highlight=WyJreXJhIl0=\">\/noticias\/noticias-del-dia\/confiscacion-inmuebles-narco-vinculado-cia-reciente-golpe-contra-impunidad-honduras?highlight=WyJreXJhIl0=<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n99\">[99]<\/a> Hilda Caldera y Gustavo Alfredo Landaverde, \u201cComportamiento reciente del narcotr\u00e1fico, el crimen organizado y maras en Honduras\u201d, United Nations Development Programme (UNDP), p. 284.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vea tambi\u00e9n: El Tiempo, \u201cTras el rastro de Matta Ballesteros\u201d, 10 de septiembre de 1993. Disponible en: <a href=\"https:\/\/www.eltiempo.com\/archivo\/documento\/MAM-218609\">https:\/\/www.eltiempo.com\/archivo\/documento\/MAM-218609<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n100\">[100]<\/a> Ib\u00edd, p. 285. Vea tambi\u00e9n: El Tiempo, \u201cAs\u00ed vive la esposa de un capo de la mafia, fugitiva en Bogot\u00e1\u201d, 3 de abril de 2005. Disponible en: <a href=\"https:\/\/www.eltiempo.com\/archivo\/documento\/MAM-1626554\">https:\/\/www.eltiempo.com\/archivo\/documento\/MAM-1626554<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n101\">[101]<\/a> El Tiempo, \u201cAs\u00ed vive la esposa de un capo de la mafia, fugitiva en Bogot\u00e1\u201d, 3 de abril de 2005. Disponible en: <a href=\"https:\/\/www.eltiempo.com\/archivo\/documento\/MAM-1626554\">https:\/\/www.eltiempo.com\/archivo\/documento\/MAM-1626554<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n102\">[102]<\/a> Caldera y Landaverde, op. cit., p. 285.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n103\">[103]<\/a> La Prensa, \u201cComo \u2018payasada\u2019 califica el hijo de Matta Ballesteros la incautaci\u00f3n de bienes\u201d,, 1 de agosto de 2014. Disponible en: <a href=\"https:\/\/www.laprensa.hn\/honduras\/tegucigalpa\/734126-98\/como-payasada-califica-el-hijo-de-matta-ballesteros-la-incautaci%C3%B3n-de-bienes\">https:\/\/www.laprensa.hn\/honduras\/tegucigalpa\/734126-98\/como-payasada-califica-el-hijo-de-matta-ballesteros-la-incautaci%C3%B3n-de-bienes<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n104\">[104]<\/a> Gurney, \u201cConfiscaci\u00f3n de inmuebles de narco vinculado a la CIA\u2026\u201d, op. cit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n105\">[105]<\/a> El Heraldo, \u201cAs\u00ed fue la extradici\u00f3n del hondure\u00f1o Carlos el \u2018Negro\u2019 Lobo\u201d, 9 de mayo de 2014. Disponible en: <a href=\"https:\/\/www.elheraldo.hn\/pais\/707599-364\/as%C3%AD-fue-la-extradici%C3%B3n-del-hondure%C3%B1o-carlos-el-negro-lobo\">https:\/\/www.elheraldo.hn\/pais\/707599-364\/as%C3%AD-fue-la-extradici%C3%B3n-del-hondure%C3%B1o-carlos-el-negro-lobo<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n106\">[106]<\/a> Marguerite Cawley, \u201c\u00bfQu\u00e9 sigue en la repentina lucha antidrogas de Honduras?\u201d, InSight Crime, 8 de octubre de 2014. Disponible en:&nbsp; <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/que-sigue-lucha-antidrogas-honduras\/\">\/noticias\/noticias-del-dia\/que-sigue-lucha-antidrogas-honduras<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n107\">[107]<\/a> Entrevista de InSight Crime con funcionario de antinarc\u00f3ticos que prefiere mantenerse an\u00f3nimo. Estados Unidos, por tel\u00e9fono, 2 de agosto de 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n108\">[108]<\/a> Marguerite Cawley, \u201cHonduras aprueba ley para derribar avionetas con drogas, Bolivia est\u00e1 lista para seguirle los pasos\u201d, InSight Crime, 20 de enero de 2014. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/honduras-aprueba-ley-para-derribar-avionetas-con-drogas-bolivia-esta-lista-para-seguirle-los-pasos\/\">\/noticias\/noticias-del-dia\/honduras-aprueba-ley-para-derribar-avionetas-con-drogas-bolivia-esta-lista-para-seguirle-los-pasos<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n109\">[109]<\/a> Marguerite Cawley, \u201cCasi la mitad de los traficantes hondure\u00f1os buscados por Estados Unidos han sido capturados\u201d, InSight Crime, 7 de octubre de 2014. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/mitad-traficantes-hondurenos-buscados-ee-uu-capturados\/\">\/noticias\/noticias-del-dia\/mitad-traficantes-hondurenos-buscados-ee-uu-capturados<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n110\">[110]<\/a> Varias entrevistas de InSight Crime con agentes antinarc\u00f3ticos hondure\u00f1os y extranjeros en 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n111\">[111]<\/a> Steven Dudley, \u201cLas ense\u00f1anzas de un exgeneral para la polic\u00eda de Honduras: Entrevista\u201d. InSight Crime, 2 de marzo de 2015. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/analisis\/exgeneral-quiere-ensenarle-policia-honduras-entrevista\/\">\/noticias\/analisis\/exgeneral-quiere-ensenarle-policia-honduras-entrevista<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n112\">[112]<\/a> Hector Calix, \u201cJuan Orlando, empresario y pol\u00edtico que sue\u00f1a con gobernar Honduras\u201d, El Heraldo, 16 de noviembre de 2012. Disponible en: <a href=\"https:\/\/www.elheraldo.hn\/alfrente\/565512-209\/juan-orlando-empresario-y-politico-que-suena-con-gobernar-honduras\">https:\/\/www.elheraldo.hn\/alfrente\/565512-209\/juan-orlando-empresario-y-politico-que-suena-con-gobernar-honduras<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n113\">[113]<\/a> Vea, por ejemplo, El Heraldo, \u201cExministro H\u00e9ctor Guill\u00e9n firm\u00f3 un contrato \u201ca precio de gallo muerto\u201d, 2 de agosto de 2012. Disponible en: <a href=\"https:\/\/www.elheraldo.hn\/alfrente\/565303-214\/exministro-h%C3%A9ctor-guill%C3%A9n-firm%C3%B3-un-contrato-a-precio-de-gallo-muerto\">https:\/\/www.elheraldo.hn\/alfrente\/565303-214\/exministro-h%C3%A9ctor-guill%C3%A9n-firm%C3%B3-un-contrato-a-precio-de-gallo-muerto<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n114\">[114]<\/a> Charles Parkinson, \u201cCongreso de Honduras vota a favor de fuerza de polic\u00eda militar\u201d, InSight Crime, 19 de agosto de 2013. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/congreso-de-honduras-vota-a-favor-de-fuerza-de-policia-militar\/\">\/noticias\/noticias-del-dia\/congreso-de-honduras-vota-a-favor-de-fuerza-de-policia-militar==<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n115\">[115]<\/a> Arron Daugherty, \u201cPresidente de Honduras ignora al Congreso en cuanto a la polic\u00eda militar\u201d, InSight Crime, 27 de enero de 2015. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/presidente-de-honduras-ignora-al-congreso-en-cuanto-a-la-policia-militar\/\">\/noticias\/noticias-del-dia\/presidente-de-honduras-ignora-al-congreso-en-cuanto-a-la-policia-militar<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n116\">[116]<\/a> Daniel Valencia Caravantes, \u201cUn western llamado Honduras\u201d, El Faro, 20 de mayo de 2013. Disponible en: <a href=\"https:\/\/www.salanegra.elfaro.net\/es\/201305\/cronicas\/12118\/Un-western-llamado-Honduras.htm\">https:\/\/www.salanegra.elfaro.net\/es\/201305\/cronicas\/12118\/Un-western-llamado-Honduras.htm<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n117\">[117]<\/a> El Heraldo, \u201cBorjas: Juan Carlos Bonilla implic\u00f3 a \u00d3scar \u00c1lvarez\u201d, 6 de abril de 2013. Disponible en: <a href=\"https:\/\/www.elheraldo.hn\/pais\/332175-364\/borjas-juan-carlos-bonilla-implic%C3%B3-a-%C3%B3scar-%C3%A1lvarez\">https:\/\/www.elheraldo.hn\/pais\/332175-364\/borjas-juan-carlos-bonilla-implic%C3%B3-a-%C3%B3scar-%C3%A1lvarez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n118\">[118]<\/a> Para m\u00e1s informaci\u00f3n sobre Alexander Ard\u00f3n, vea: Douglas Farah y Carl Meacham, \u201cAlternative Governance in the Northern Triangle: Finding Logic within Chaos,\u201d Center for Strategic and International Studies, September 2015. Disponible en: <a href=\"https:\/\/csis.org\/files\/publication\/150911_Farah_AlternativeGovernance_Web.pdf\">https:\/\/csis.org\/files\/publication\/150911_Farah_AlternativeGovernance_Web.pdf<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n119\">[119]<\/a> La Tribuna, \u201cInauguran en Tocoa una moderna estaci\u00f3n de servicio\u201d, 3 de enero de 2012.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n120\">[120]<\/a> Mimi Yagoub, \u201c\u00bfFue el asesinato de \u2018Chepe Luna\u2019 de El Salvador un golpe criminal o s\u00f3lo negocios?\u201d, InSight Crime, 27 de junio de 2014. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/fue-asesinato-chepe-luna-el-salvador-golpe-criminal-o-solo-negocios\/\">\/noticias\/noticias-del-dia\/fue-asesinato-chepe-luna-el-salvador-golpe-criminal-o-solo-negocios<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a name=\"n121\">[121]<\/a> Loren Riesenfeld, \u201cHijo del expresidente de Honduras capturado por narcotr\u00e1fico\u201d, InSight Crime, 22 de mayo de 2015. Disponible en: <a href=\"https:\/\/es.insightcrime.org\/noticias\/noticias-del-dia\/hijo-expresidente-honduras-capturado-narcotrafico\/\">\/noticias\/noticias-del-dia\/hijo-expresidente-honduras-capturado-narcotrafico=<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana del 5 de abril de 1988, Juan Ram\u00f3n Matta Ballesteros sali\u00f3 de su mansi\u00f3n en Tegucigalpa para irse a trotar. Matta Ballesteros era buscado por asesinato, narcotr\u00e1fico y otros cr\u00edmenes en varios pa\u00edses, pero en Honduras se sent\u00eda seguro. Sol\u00eda organizar fiestas con altos funcionarios en su casa, y ten\u00eda conexiones con oficiales militares.<sup>1<\/sup> &nbsp;En sus negocios legales empleaba miles de lugare\u00f1os, quienes lo honraban porque prove\u00eda medicinas, constru\u00eda escuelas y hac\u00eda donaciones a causas ben\u00e9ficas.<sup>2<\/sup> &nbsp;Se dice que una vez le ofreci\u00f3 al gobierno pagar la creciente deuda externa, ofrecimiento que al parecer por lo menos un pol\u00edtico lo tom\u00f3 en serio.<sup>3<\/sup><\/p>\n","protected":false},"author":3,"featured_media":43459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"single-feature.php","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"above","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[342],"tags":[447,398,455],"newspack_spnsrs_tax":[],"coauthors":[3658],"class_list":["post-8682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investigaciones","tag-elites-y-crimen-organizado","tag-honduras-pais","tag-infografias","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/investigaciones\/elites-crimen-organizado-honduras-juan-ramon-matta-ballesteros\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00c9lites y crimen organizado en Honduras: Juan Ram\u00f3n Matta Ballesteros","url":"http:\/\/insightcrime.org\/es\/investigaciones\/elites-crimen-organizado-honduras-juan-ramon-matta-ballesteros\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/investigaciones\/elites-crimen-organizado-honduras-juan-ramon-matta-ballesteros\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/04\/es-matta_ballesteros_family.jpg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/04\/es-matta_ballesteros_family.jpg?fit=250%2C185&quality=100&ssl=1"},"articleSection":"Investigaciones","author":[{"@type":"Person","name":"Steven Dudley"}],"creator":["Steven Dudley"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["\u00e9lites y crimen","honduras","infograf\u00edas"],"dateCreated":"2016-04-09T16:36:21Z","datePublished":"2016-04-09T16:36:21Z","dateModified":"2023-10-25T16:09:27Z"},"rendered":"<meta name=\"parsely-title\" content=\"\u00c9lites y crimen organizado en Honduras: Juan Ram\u00f3n Matta Ballesteros\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/investigaciones\/elites-crimen-organizado-honduras-juan-ramon-matta-ballesteros\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/04\/es-matta_ballesteros_family.jpg?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2016-04-09T16:36:21Z\" \/>\n<meta name=\"parsely-section\" content=\"Investigaciones\" \/>\n<meta name=\"parsely-tags\" content=\"\u00e9lites y crimen,honduras,infograf\u00edas\" \/>\n<meta name=\"parsely-author\" content=\"Steven Dudley\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":323136,"url":"https:\/\/insightcrime.org\/es\/noticias\/juan-ramon-matta-ballesteros-moldeo-narcotrafico-honduras\/","url_meta":{"origin":8682,"position":0},"title":"Video: C\u00f3mo Juan Ram\u00f3n Matta Ballesteros transform\u00f3 el narcotr\u00e1fico en Honduras","author":"InSight Crime","date":"31 de octubre de 2025","format":false,"excerpt":"El narcotraficante hondure\u00f1o Juan Ram\u00f3n Matta Ballesteros muri\u00f3 en una prisi\u00f3n de Estados Unidos a los 80 a\u00f1os, aunque su legado en el tr\u00e1fico de drogas sigue vigente. El subdirector Mike LaSusa y el investigador Sam Woolston analizan su trayectoria y la influencia duradera que dej\u00f3 en el mundo criminal.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/11\/ESP.png?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":313538,"url":"https:\/\/insightcrime.org\/es\/noticias-crimen-organizado-honduras\/juan-matta-ballesteros\/","url_meta":{"origin":8682,"position":1},"title":"Juan Matta Ballesteros","author":"InSight Crime","date":"3 de julio de 2025","format":false,"excerpt":"Juan Matta Ballesteros fue un narcotraficante hondure\u00f1o que fue pionero en el env\u00edo de grandes cargamentos de coca\u00edna a trav\u00e9s de Centroam\u00e9rica y uno de los primeros traficantes en conectar a los proveedores de coca\u00edna en Colombia con poderosos grupos de tr\u00e1fico en M\u00e9xico, como el Cartel de Guadalajara.","rel":"","context":"En \u00abHonduras\u00bb","block_context":{"text":"Honduras","link":"https:\/\/insightcrime.org\/es\/category\/noticias-crimen-organizado-honduras\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":167182,"url":"https:\/\/insightcrime.org\/es\/noticias\/dudas-en-torno-premeditado-asesinato-empresario-hondureno-hospital\/","url_meta":{"origin":8682,"position":2},"title":"Dudas en torno al premeditado asesinato de empresario hondure\u00f1o en un hospital","author":"Seth Robbins","date":"6 de septiembre de 2021","format":false,"excerpt":"El nombre del empresario hondure\u00f1o Wilkin Montalv\u00e1n se dio a conocer en noviembre de 2018, cuando Tony Hern\u00e1ndez, hermano del presidente, fue interrogado por agentes estadounidenses en torno a varios narcotraficantes. Tres a\u00f1os despu\u00e9s, es claro que alguien quer\u00eda la muerte de Montalv\u00e1n.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Slain Honduran businessman Wilkin Montalv\u00e1n ","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2021\/09\/Slain_Wilkin_Montalvan_Hoduras.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6357,"url":"https:\/\/insightcrime.org\/es\/noticias-crimen-organizado-honduras\/honduras\/","url_meta":{"origin":8682,"position":3},"title":"Perfil de Honduras","author":"InSight Crime","date":"6 de septiembre de 2024","format":false,"excerpt":"Honduras es uno de los centros de operaciones del narcotr\u00e1fico m\u00e1s importantes entre Suram\u00e9rica y M\u00e9xico.","rel":"","context":"En \u00abHonduras\u00bb","block_context":{"text":"Honduras","link":"https:\/\/insightcrime.org\/es\/category\/noticias-crimen-organizado-honduras\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/08\/Honduras-country-profile-ok.jpg?fit=1200%2C677&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/08\/Honduras-country-profile-ok.jpg?fit=1200%2C677&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/08\/Honduras-country-profile-ok.jpg?fit=1200%2C677&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/08\/Honduras-country-profile-ok.jpg?fit=1200%2C677&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2017\/08\/Honduras-country-profile-ok.jpg?fit=1200%2C677&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":313485,"url":"https:\/\/insightcrime.org\/honduras-organized-crime-news\/juan-matta-ballesteros\/","url_meta":{"origin":8682,"position":4},"title":"Juan Matta Ballesteros","author":"InSight Crime","date":"3 de julio de 2025","format":false,"excerpt":"Juan Matta Ballesteros was a Honduran drug trafficker who pioneered the bulk shipping of cocaine through Central America. He was one of the first traffickers to connect cocaine suppliers in Colombia to powerful trafficking groups in Mexico, such as the Guadalajara Cartel.\u00a0","rel":"","context":"En \u00abHonduras\u00bb","block_context":{"text":"Honduras","link":"https:\/\/insightcrime.org\/category\/honduras-organized-crime-news\/"},"img":{"alt_text":"Juan Matta Ballesteros","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2026\/06\/Perfil-Criminal-Juan-Matta-Ballesteros.jpg?fit=1200%2C900&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":323140,"url":"https:\/\/insightcrime.org\/news\/video-how-juan-ramon-matta-ballesteros-shaped-honduras-drug-trade\/","url_meta":{"origin":8682,"position":5},"title":"The InSight Take: How Juan Ram\u00f3n Matta Ballesteros Shaped Honduras&#8217; Drug Trade","author":"InSight Crime","date":"31 de octubre de 2025","format":false,"excerpt":"Honduran drug trafficker Juan Ram\u00f3n Matta Ballesteros has died in a US prison at age 80, though his drug trafficking legacy lives on. Deputy director Mike LaSusa and investigator Sam Woolston\u00a0discuss his career and lasting influence in the underworld.","rel":"","context":"En \u00abNews\u00bb","block_context":{"text":"News","link":"https:\/\/insightcrime.org\/category\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/11\/ESP.png?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/04\/es-matta_ballesteros_family.jpg?fit=250%2C185&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/8682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=8682"}],"version-history":[{"count":6,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/8682\/revisions"}],"predecessor-version":[{"id":244643,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/8682\/revisions\/244643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/43459"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=8682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=8682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=8682"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=8682"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=8682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}