{"id":9464,"date":"2016-12-08T16:59:31","date_gmt":"2017-03-28T00:21:38","guid":{"rendered":"http:\/\/newwp.insightcrime.org?p=9464"},"modified":"2023-04-24T15:56:00","modified_gmt":"2023-04-24T20:56:00","slug":"mexico-lucha-contra-robo-informatico-generalizado-de-informacion-personal-tristan-clavel","status":"publish","type":"post","link":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/mexico-lucha-contra-robo-informatico-generalizado-de-informacion-personal-tristan-clavel\/","title":{"rendered":"M\u00e9xico lucha contra robo inform\u00e1tico generalizado de informaci\u00f3n personal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El hurto inform\u00e1tico de informaci\u00f3n personal y comercial en M\u00e9xico va en aumento, seg\u00fan informes, una muestra del limitado poder de los entes de gobierno para contrarrestar la considerable industria en r\u00e1pida evoluci\u00f3n de los delitos inform\u00e1ticos en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico se ha convertido en un para\u00edso para el mercado negro de todo tipo de informaci\u00f3n personal robada, seg\u00fan una nota de <a href=\"https:\/\/www.cronica.com.mx\/notas\/2016\/999505.html\" target=\"_blank\">Cr\u00f3nica<\/a>. Y el potencial de ganancias es considerable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La excomisionada del organismo aut\u00f3nomo constitucional de M\u00e9xico a cargo de la protecci\u00f3n de informaci\u00f3n personal (<a href=\"https:\/\/inicio.ifai.org.mx\/SitePages\/ifai.aspx\" target=\"_blank\">Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales<\/a>), Sigrid Arzt, se\u00f1al\u00f3 que \u201cun expediente m\u00e9dico puede llegar a valer hasta US$10.000, porque con esa informaci\u00f3n puedes hacer transacciones para cobrar seguros, pensiones, suplantar la identidad y tener servicios m\u00e9dicos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arzt tambi\u00e9n se\u00f1al\u00f3 la impunidad generalizada &nbsp;con respecto a los cr\u00edmenes inform\u00e1ticos y culp\u00f3 de ello a la falta de instrumentos legales adecuados y a la no implementaci\u00f3n de las leyes existentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00f3nica tambi\u00e9n inform\u00f3 que el robo inform\u00e1tico no es obra de piratas aislados. Seg\u00fan Sebastian Brenner, estratega de seguridad para <a href=\"https:\/\/www.symantec.com\/es\/mx\/\" target=\"_blank\">Symantec Latinoam\u00e9rica<\/a>, estos son \u201cgrupos muy bien estructurados, con expertos para cada etapa del proceso: infiltraci\u00f3n, captura, comercializaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brenner coment\u00f3 que los datos de una cuenta de correo pod\u00edan valer US$30 mientras que los de una cuenta de juegos en internet pod\u00edan llegar a US$3.000 \u2014una muestra de la variedad de objetivos y precios posibles\u2014 y que estos ataques, junto con los dirigidos a las redes empresariales, van en aumento en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s a\u00fan, el robo inform\u00e1tico no solo ata\u00f1e a una variedad de posibles blancos, sino tambi\u00e9n a una variada gama de compradores potenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn los niveles m\u00e1s bajos, las empresas de mercadotecnia\u2026 compa\u00f1\u00edas competidoras y otras especializadas en crear nuevos productos en sistemas electr\u00f3nicos para venderlos a nivel internacional; y en el peor de los casos el crimen organizado, que utiliza la informaci\u00f3n para robos, sobornos, <a href=\"\/component\/tags\/tag\/248-extorsion\" target=\"_blank\">extorsiones<\/a> y <a href=\"\/component\/tags\/tag\/208-secuestro\" target=\"_blank\">secuestros<\/a>\u201c, explic\u00f3 Issa Luna Pla, investigadora del <a href=\"https:\/\/www.juridicas.unam.mx\/\" target=\"_blank\">Instituto de Investigaciones Jur\u00eddicas<\/a> de la Universidad Nacional Aut\u00f3noma de M\u00e9xico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lisis de InSight Crime<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La tendencia es preocupante. M\u00e1s a\u00fan, los cr\u00edmenes inform\u00e1ticos costaron a M\u00e9xico un total estimado de <a href=\"https:\/\/es.scribd.com\/doc\/174849738\/Norton-Cibercrime-Report-2013\" target=\"_blank\">US$3 mil millones en 2012<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico sin duda necesita remediar las deficiencias institucionales planteadas por Luna Pla: mejores marcos legales y mecanismos de gobierno m\u00e1s eficientes obviamente ayudar\u00edan. Pero las garant\u00edas institucionales no evolucionar\u00e1n a la misma velocidad que la tecnolog\u00eda que los criminales explotan. Por esta raz\u00f3n, la mayor\u00eda de informes aboga por que las firmas privadas <a href=\"https:\/\/www.as-coa.org\/articles\/explainer-fighting-cybercrime-latin-america\" target=\"_blank\">inviertan en m\u00e1s seguridad tecnol\u00f3gica<\/a>, y que el gobierno y otros inviertan en <a href=\"https:\/\/publications.iadb.org\/handle\/11319\/7449?locale-attribute=es\" target=\"_blank\">campa\u00f1as de concientizaci\u00f3n p\u00fablica<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"color: #800000\"><strong>VEA TAMBI\u00c9N:<\/strong><\/span> <a href=\"\/component\/tags\/tag\/315-crimen-cibernetico\" target=\"_blank\">Cobertura sobre crimen cibern\u00e9tico<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El otro aspecto es que las barreras de ingreso a este negocio son tan pocas en la actual fase que la lucha parece interminable. No hay certeza, por ejemplo, de qu\u00e9 proporci\u00f3n de los cr\u00edmenes inform\u00e1ticos fue cometida por organizaciones criminales de M\u00e9xico, ni detalles importantes sobre hasta qu\u00e9 punto estos grupos se organizan bajo una jerarqu\u00eda definida. Las leyes deben cambiar a la misma velocidad de las t\u00e9cnicas para perseguir a estos criminales inform\u00e1ticos, sin importar qu\u00e9 tan organizados est\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hurto inform\u00e1tico de informaci\u00f3n personal y comercial en M\u00e9xico va en aumento, seg\u00fan informes, una muestra del limitado poder de los entes de gobierno para contrarrestar la considerable industria en r\u00e1pida evoluci\u00f3n de los delitos inform\u00e1ticos en el pa\u00eds.<\/p>\n","protected":false},"author":79,"featured_media":45674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"newspack_ads_suppress_ads":false,"newspack_popups_has_disabled_popups":false,"newspack_sponsor_sponsorship_scope":"","newspack_sponsor_native_byline_display":"inherit","newspack_sponsor_native_category_display":"inherit","newspack_sponsor_underwriter_style":"inherit","newspack_sponsor_underwriter_placement":"inherit","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_newspack_byline_active":false,"_newspack_byline":"","newspack_hide_updated_date":false,"newspack_show_updated_date":false,"newspack_featured_image_position":"","newspack_post_subtitle":"","newspack_article_summary_title":"Overview:","newspack_article_summary":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[334],"tags":[444,406],"newspack_spnsrs_tax":[],"coauthors":[4036],"class_list":["post-9464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-dia","tag-crimen-cibernetico","tag-mexico-pais","entry"],"parsely":{"version":"1.1.0","canonical_url":"https:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/mexico-lucha-contra-robo-informatico-generalizado-de-informacion-personal-tristan-clavel\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9xico lucha contra robo inform\u00e1tico generalizado de informaci\u00f3n personal","url":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/mexico-lucha-contra-robo-informatico-generalizado-de-informacion-personal-tristan-clavel\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/mexico-lucha-contra-robo-informatico-generalizado-de-informacion-personal-tristan-clavel\/"},"thumbnailUrl":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/12\/es-16-12-07-Mexico-Cyber-theft.jpg?resize=150%2C150&quality=100&ssl=1","image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/12\/es-16-12-07-Mexico-Cyber-theft.jpg?fit=309%2C210&quality=100&ssl=1"},"articleSection":"Noticias del d\u00eda","author":[{"@type":"Person","name":"Tristan Clavel"}],"creator":["Tristan Clavel"],"publisher":{"@type":"Organization","name":"InSight Crime","logo":"https:\/\/insightcrime.org\/wp-content\/uploads\/2023\/08\/logo.png"},"keywords":["crimen cibern\u00e9tico","m\u00e9xico"],"dateCreated":"2017-03-28T00:21:38Z","datePublished":"2017-03-28T00:21:38Z","dateModified":"2023-04-24T20:56:00Z"},"rendered":"<meta name=\"parsely-title\" content=\"M\u00e9xico lucha contra robo inform\u00e1tico generalizado de informaci\u00f3n personal\" \/>\n<meta name=\"parsely-link\" content=\"http:\/\/insightcrime.org\/es\/noticias\/noticias-del-dia\/mexico-lucha-contra-robo-informatico-generalizado-de-informacion-personal-tristan-clavel\/\" \/>\n<meta name=\"parsely-type\" content=\"post\" \/>\n<meta name=\"parsely-image-url\" content=\"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/12\/es-16-12-07-Mexico-Cyber-theft.jpg?resize=150%2C150&amp;quality=100&amp;ssl=1\" \/>\n<meta name=\"parsely-pub-date\" content=\"2017-03-28T00:21:38Z\" \/>\n<meta name=\"parsely-section\" content=\"Noticias del d\u00eda\" \/>\n<meta name=\"parsely-tags\" content=\"crimen cibern\u00e9tico,m\u00e9xico\" \/>\n<meta name=\"parsely-author\" content=\"Tristan Clavel\" \/>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/insightcrime.org\/p.js"},"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":201177,"url":"https:\/\/insightcrime.org\/es\/news\/tres-revelaciones-criminales-de-las-sedena-leaks-en-mexico\/","url_meta":{"origin":9464,"position":0},"title":"Tres revelaciones criminales de las \u2018Sedena Leaks\u2019 en M\u00e9xico","author":"Chris Dalby","date":"10 de octubre de 2022","format":false,"excerpt":"Seis terabytes de informaci\u00f3n filtrada de la Secretar\u00eda de la Defensa Nacional (Sedena) por el colectivo de piratas inform\u00e1ticos Guacamaya han volcado una tonelada de secretos celosamente guardados sobre la lucha de M\u00e9xico contra el crimen organizado.","rel":"","context":"En \u00abNews\u00bb","block_context":{"text":"News","link":"https:\/\/insightcrime.org\/category\/news\/"},"img":{"alt_text":"Sedena Leaks. Soldado vigila una poblaci\u00f3n en M\u00e9xico","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/10\/revelaciones-sedena-leaks-ejercito-guacamaya-1-1.jpeg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":174634,"url":"https:\/\/insightcrime.org\/es\/noticias\/gobiernos-latinoamericanos-presa-facil-cibersecuestro-datos\/","url_meta":{"origin":9464,"position":1},"title":"Gobiernos latinoamericanos son presa f\u00e1cil del cibersecuestro de datos durante COVID-19","author":"Anastasia Austin","date":"5 de enero de 2022","format":false,"excerpt":"Un reciente ciberataque que golpe\u00f3 a sitios de internet gubernamentales en Brasil, incluidas las plataformas que hacen seguimiento a datos epidemiol\u00f3gicos y de vacunaci\u00f3n para COVID-19, aviva los temores de una oleada de ciberataques a infraestructura cr\u00edtica en los pa\u00edses latinoamericanos.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Ministerio da Saude Brasil","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/01\/mca_abr_numero_de_serie_de_4_digitos_090620_1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":191092,"url":"https:\/\/insightcrime.org\/es\/news\/extorsion-expres-aplicaciones-credito-facil-tienen-alto-costo-mexico\/","url_meta":{"origin":9464,"position":2},"title":"Extorsi\u00f3n expr\u00e9s: aplicaciones de cr\u00e9dito f\u00e1cil tienen un alto costo en M\u00e9xico","author":"Gabrielle Gorder","date":"13 de julio de 2022","format":false,"excerpt":"Los estafadores de M\u00e9xico han perfeccionado su modus operandi de nuevo, esta vez mediante el uso de aplicaciones de cr\u00e9dito expr\u00e9s para extorsionar a los usuarios y drenar sus cuentas bancarias.","rel":"","context":"En \u00abNews\u00bb","block_context":{"text":"News","link":"https:\/\/insightcrime.org\/category\/news\/"},"img":{"alt_text":"Aplicaci\u00f3n de montadeudas","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/07\/Montadeudas_ImpactoMichoacan_672022.webp?fit=586%2C330&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/07\/Montadeudas_ImpactoMichoacan_672022.webp?fit=586%2C330&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/07\/Montadeudas_ImpactoMichoacan_672022.webp?fit=586%2C330&quality=100&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":313422,"url":"https:\/\/insightcrime.org\/es\/noticias\/hackeo-del-cartel-de-sinaloa-al-fbi-revela-grietas-en-la-seguridad\/","url_meta":{"origin":9464,"position":3},"title":"Hackeo del Cartel de Sinaloa al FBI revela grietas en la seguridad","author":"Parker Asmann","date":"2 de julio de 2025","format":false,"excerpt":"El Cartel de Sinaloa hacke\u00f3 a una de las principales agencias de seguridad de Estados Unidos y obtuvo informaci\u00f3n clasificada que luego fue utilizada para intimidar y asesinar a posibles fuentes del gobierno, seg\u00fan un informe de un \u00f3rgano de control interno que evidencia fallas m\u00e1s amplias en la protecci\u00f3n\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/07\/Feature-Hakers-Name-file.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/07\/Feature-Hakers-Name-file.jpg?fit=1200%2C690&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/07\/Feature-Hakers-Name-file.jpg?fit=1200%2C690&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/07\/Feature-Hakers-Name-file.jpg?fit=1200%2C690&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2025\/07\/Feature-Hakers-Name-file.jpg?fit=1200%2C690&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":196145,"url":"https:\/\/insightcrime.org\/es\/noticias\/policias-corruptos-juegan-dos-bandas-guanajuato-mexico\/","url_meta":{"origin":9464,"position":4},"title":"Polic\u00edas corruptos juegan a dos bandas en Guanajuato, M\u00e9xico","author":"Scott Mistler-Ferguson","date":"29 de agosto de 2022","format":false,"excerpt":"Una investigaci\u00f3n realizada en Guanajuato, M\u00e9xico, dio de baja a unos 150 agentes de polic\u00eda sospechosos de nexos con carteles.","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/insightcrime.org\/es\/category\/noticias\/"},"img":{"alt_text":"Agente de polic\u00eda de guardia en Celaya, Guanajuato, M\u00e9xico.","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2022\/08\/Celaya-Police-1.jpg?fit=350%2C250&quality=100&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":232699,"url":"https:\/\/insightcrime.org\/es\/investigaciones\/mexico-buenas-leyes-pocas-sanciones-trafico-precursores\/","url_meta":{"origin":9464,"position":5},"title":"En M\u00e9xico hay buenas leyes, pero pocas sanciones para el tr\u00e1fico de precursores","author":"Victoria Dittmar","date":"10 de mayo de 2023","format":false,"excerpt":"Las regulaciones de M\u00e9xico con respecto a los precursores qu\u00edmicos son estrictas en el papel","rel":"","context":"En \u00abInvestigaciones\u00bb","block_context":{"text":"Investigaciones","link":"https:\/\/insightcrime.org\/es\/category\/investigaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Precursor-Chemical-Cover-C8-1-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Precursor-Chemical-Cover-C8-1-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Precursor-Chemical-Cover-C8-1-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Precursor-Chemical-Cover-C8-1-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2023\/09\/Precursor-Chemical-Cover-C8-1-1.jpg?fit=1200%2C576&quality=100&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/insightcrime.org\/wp-content\/uploads\/2016\/12\/es-16-12-07-Mexico-Cyber-theft.jpg?fit=309%2C210&quality=100&ssl=1","_links":{"self":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/9464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/comments?post=9464"}],"version-history":[{"count":1,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/9464\/revisions"}],"predecessor-version":[{"id":27832,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/posts\/9464\/revisions\/27832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media\/45674"}],"wp:attachment":[{"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/media?parent=9464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/categories?post=9464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/tags?post=9464"},{"taxonomy":"newspack_spnsrs_tax","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/newspack_spnsrs_tax?post=9464"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/insightcrime.org\/es\/wp-json\/wp\/v2\/coauthors?post=9464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}